{"id":110030,"date":"2019-05-20T08:15:01","date_gmt":"2019-05-20T06:15:01","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/arriva-a-cosenza-la-protesta-dei-dipendenti-italbacolor-di-fuscaldo\/"},"modified":"2023-01-16T18:27:40","modified_gmt":"2023-01-16T17:27:40","slug":"293537-arriva-a-cosenza-la-protesta-dei-dipendenti-italbacolor-di-fuscaldo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/293537-arriva-a-cosenza-la-protesta-dei-dipendenti-italbacolor-di-fuscaldo\/","title":{"rendered":"Arriva a Cosenza la protesta dei dipendenti Italbacolor di Fuscaldo"},"content":{"rendered":"<h4>Sono scesi in piazza a Cosenza questa mattina i dipendenti della Italbacolor, azienda con sede a Fuscaldo, nel Cosentino, che realizza prodotti in alluminio.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; La propriet\u00e0, nei giorni scorsi, ha annunciato <span style=\"color: #0000ff;\"><strong><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/7002\" target=\"_blank\" rel=\"noopener\">80 licenziamenti<\/a> <\/strong><\/span>dopo che la magistratura ha disposto il fermo dell&#8217;impianto per presunte irregolarit\u00e0 in materia di smaltimento delle acque reflue emerse da un sopralluogo delle forze dell&#8217;ordine. L&#8217;azienda sostiene di aver ottemperato alle prescrizioni, ma la magistratura non ha ancora autorizzato la ripresa dell&#8217;attivit\u00e0 produttiva ed il blocco permane. I sindacati hanno chiesto di essere ricevuti dal prefetto: &#8220;L&#8217;azienda e le istituzioni &#8211; ha detto il segretario della Fiom-Cgil Calabria, Massimo Covello &#8211; facciano celermente la loro parte&#8221;.<\/p>\n<p>La manifestazione \u00e8 stata promossa da Fiom, Fim-Cisl e Uilm ed una delegazione \u00e8 stata poi ricevuta in Prefettura. Ai funzionari presenti \u00e8 stato rappresentato dettagliatamente lo stato della vertenza e richiesta la massima attenzione nonch\u00e9 ogni azione utile al superamento dello stallo che sta impedendo la ripresa delle attivit\u00e0 e il ritiro delle procedure di licenziamento collettivo.<\/p>\n<p>I funzionari prefettizi &#8211; prosegue il comunicato &#8211; hanno assicurato la massima attenzione e si sono impegnati a riportare al Prefetto le richieste pressanti ricevute&#8221;. Alla fine dell\u2019incontro, nel corso di un\u2019assemblea, si \u00e8 deciso di continuare la mobilitazione con l\u2019indizione per <strong>domani mattina di un sit-in davanti<\/strong> al palazzo comunale di <strong>Fuscaldo<\/strong>, &#8220;per sensibilizzare tutta la cittadinanza e l\u2019Istituzione locale sulla vertenza&#8221;.<\/p>\n<p>Sindacati e lavoratori &#8220;fanno appello a tutte le istituzioni interessate a compiere immediatamente ogni azione utile a consentire la ripresa delle attivit\u00e0, a preservare l\u2019occupazione ed ad evitare un dramma sociale non soltanto ai lavoratori diretti ma all\u2019economia dell\u2019intero territorio gi\u00e0 interessata da processi di depauperamento industriale ed impoverimento.La forte e civile determinazione dei lavoratori e lavoratrici manifestata stamattina &#8211; si legge infine &#8211; non cesser\u00e0 fino al raggiungimento dell\u2019obiettivo: <strong>lavoro e dignit\u00e0&#8221;<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sono scesi in piazza a Cosenza questa mattina i dipendenti della Italbacolor, azienda con sede a Fuscaldo, nel Cosentino, che realizza prodotti in alluminio.<\/p>\n","protected":false},"author":42,"featured_media":110031,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42,28,576],"tags":[],"class_list":["post-110030","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza","category-provincia","category-tirreno"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/110030","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=110030"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/110030\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/110031"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=110030"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=110030"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=110030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}