{"id":110289,"date":"2019-05-24T09:48:43","date_gmt":"2019-05-24T07:48:43","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/buone-pratiche-ed-ecocalendari-continuano-le-giornate-in-piazza-di-ecologia-oggi\/"},"modified":"2023-01-16T18:27:56","modified_gmt":"2023-01-16T17:27:56","slug":"294528-buone-pratiche-ed-ecocalendari-continuano-le-giornate-in-piazza-di-ecologia-oggi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/294528-buone-pratiche-ed-ecocalendari-continuano-le-giornate-in-piazza-di-ecologia-oggi\/","title":{"rendered":"Buone pratiche ed ecocalendari, continuano le giornate in piazza di Ecologia Oggi"},"content":{"rendered":"<h4>Continuano le giornate in piazza dedicate all&#8217;informazione sulle buone pratiche ambientali e sui nuovi ecocalendari. Domani anche la raccolta straordinaria dell&#8217;olio esausto<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Il prossimo appuntamento \u00e8 per domani, <strong>sabato 25 maggio<\/strong> dalle 10:00 alle 12:00, su Piazza Europa. Ecologia Oggi sar\u00e0 sul posto per illustrare il <strong>nuovo Regolamento Comunale per la gestione dei rifiuti<\/strong>, per promuovere la <strong>salvaguardia<\/strong> dell\u2019ambiente e <strong>contrastare il fenomeno dell\u2019abbandono dei rifiuti<\/strong>\u00a0che mortifica i luoghi della convivenza e offende la maggioranza dei cittadini che rispetta la natura e le buone pratiche ambientali.\u00a0Nella stessa giornata verr\u00e0 effettuata una raccolta straordinaria dell&#8217;olio vegetale esausto.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-294547 alignright\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/05\/piazza-europa.jpg\" alt=\"\" width=\"689\" height=\"379\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Continuano le giornate in piazza dedicate all&#8217;informazione sulle buone pratiche ambientali e sui nuovi ecocalendari. Domani anche la raccolta straordinaria dell&#8217;olio esausto<\/p>\n","protected":false},"author":42,"featured_media":110290,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42,70],"tags":[],"class_list":["post-110289","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza","category-quiecologia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/110289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=110289"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/110289\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/110290"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=110289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=110289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=110289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}