{"id":110293,"date":"2019-05-24T09:55:22","date_gmt":"2019-05-24T07:55:22","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cittadella-accoltellato-dopo-una-lite-individuato-e-denunciato-il-responsabile\/"},"modified":"2023-01-16T18:27:58","modified_gmt":"2023-01-16T17:27:58","slug":"294542-cittadella-accoltellato-dopo-una-lite-individuato-e-denunciato-il-responsabile","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/294542-cittadella-accoltellato-dopo-una-lite-individuato-e-denunciato-il-responsabile\/","title":{"rendered":"Cittadella, accoltellato dopo una lite. Individuato e denunciato il responsabile"},"content":{"rendered":"<h4>Si tratta di un 31enne di Cetraro, denunciato dai carabinieri di Scalea, per lesioni personali aggravate. La lite, che ha portato al ferimento di un 30enne, sorta per futili motivi<!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>CITTADELLA DEL CAPO (CS) &#8211; I carabinieri della compagnia di Scalea, diretta dal capitano Andrea Massari, hanno <strong>denunciato in stato di libert\u00e0 per lesioni personali e aggravate<\/strong>\u00a0<strong>un 31enne di Cetraro,<\/strong> ritenuto\u00a0 responsabile dell<span style=\"color: #0000ff;\">\u2019<a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/7078\"><strong>accoltellamento avvenuto ieri pomeriggio<\/strong><\/a><\/span> nei pressi di un bar, davanti la stazione di Cittadella del Capo sul tirreno cosentino, di un 30enne finito poi al&#8217;ospedale di Cosenza e dimesso questa mattina con una prognosi di 10 giorni.<\/p>\n<p>Tutto sarebbe scaturito da <strong>una lite, nata da futili motivi,<\/strong> all&#8217;interno del bar (e legata probabilmente apprezzamento verso una ragazza) che ha portato al successivo litigio e poi al ferimento del giovane. La tempestiva attivit\u00e0 investigativa dei carabinieri, le testimonianze sia della vittima che dei presenti, oltre all&#8217;<strong>utilizzo delle immagini di videosorveglianza<\/strong>, hanno portato questa mattina all&#8217;i<strong>ndividuazione e alla denuncia del 31enne<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si tratta di un 31enne di Cetraro, denunciato dai carabinieri di Scalea, per lesioni personali aggravate. La lite, che ha portato al ferimento di un 30enne, sorta per futili motivi<\/p>\n","protected":false},"author":46,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-110293","post","type-post","status-publish","format-standard","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/110293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=110293"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/110293\/revisions"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=110293"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=110293"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=110293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}