{"id":110417,"date":"2019-05-27T11:00:45","date_gmt":"2019-05-27T09:00:45","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/randagismo-a-san-giovanni-in-fiore-lettera-appello-alla-civilta\/"},"modified":"2023-01-16T18:28:06","modified_gmt":"2023-01-16T17:28:06","slug":"295036-randagismo-a-san-giovanni-in-fiore-lettera-appello-alla-civilta","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/295036-randagismo-a-san-giovanni-in-fiore-lettera-appello-alla-civilta\/","title":{"rendered":"Randagismo a San Giovanni in Fiore, lettera-appello alla &#8220;civilt\u00e0&#8221;"},"content":{"rendered":"<h4>La lettera ricevuta in redazione \u00e8 rivolta al sindaco di San Giovanni in Fiore, Belcastro confidando nel suo &#8220;spirito di civilt\u00e0 e umanit\u00e0&#8221;.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>SAN GIOVANNI IN FIORE (CS) &#8211; A scrivere sono Daniela M. e Patrizia N. che si rivolgono al primo cittadino a seguito dell&#8217;articolo riportato sulla nostra testata e intitolato <span style=\"color: #0000ff;\"><strong><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/7107\" target=\"_blank\" rel=\"noopener noreferrer\">&#8220;Cani randagi invadono la Sila aggredendo i cittadini: servizi veterinari Asp assenti&#8221;.<\/a><\/strong><\/span><\/p>\n<p>&#8220;Gentile Primo Cittadino, ci appelliamo a lei confidando nel suo spirito di civilt\u00e0 e umanit\u00e0. Perch\u00e9 di questo si tratta. Nel Comune di San Giovanni in Fiore la <strong>popolazione convive con una popolazione&#8230; canina<\/strong>, come giusto sarebbe se fosse una sana e regolare convivenza, come succede infatti in diverse citt\u00e0 di Italia. Ma l&#8217;ostentato disinteresse e la comodit\u00e0 di non intervenire di molti, se non allontando e scaricando il &#8216;problema&#8217; ad altri, ha creato un numero esagerato di cani bisognosi.<strong> Perch\u00e9 quel &#8216;problema&#8217; si chiama vita<\/strong> e ha come causa, il voltarsi dall&#8217;altra parte della cosiddetta &#8220;gente bene&#8221;.<\/p>\n<p>&#8220;<strong>Nessuna prevenzione al randagismo, nessun pronto soccorso veterinario e la burocrazia che blocca qualsiasi intervento. <\/strong>E, ironia della sorte &#8211; prosegue la lettera &#8211; le persone che si espongono per aiutare questa popolazione canina, e aiutare cos\u00ec anche la propria citt\u00e0 e coscienza, ecco loro <strong>vengono multati<\/strong>. Invece di andare a sequestrare i cani a chi li salva dalla strada e da tutte le tremende conseguenze, perch\u00e9 per motivi economici non \u00e8 riuscito a vaccinarli e microchipparli, bisognerebbe aiutarli a fare ci\u00f2. Tanto vaccinare e chippare un cane in canile o presso queste persone, da parte delle ASP non avrebbe differenza di costi. Adesso invece questi poveri cani, che venivano accuditi amorevolmente, persino toelettati, si trovano rinchiusi in un sovraffollato canile del Sud&#8221;.<\/p>\n<p>&#8220;Ecco dottor Belcastro, ci appelliamo a lei. Noi abbiamo bisogno che adesso lei intervenga. In un Paese che sa solo cambiare canale davanti ai drammi che ci assediano. Noi abbiamo bisogno che lei dia un esempio&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La lettera ricevuta in redazione \u00e8 rivolta al sindaco di San Giovanni in Fiore, Belcastro confidando nel suo &#8220;spirito di civilt\u00e0 e umanit\u00e0&#8221;.<\/p>\n","protected":false},"author":21,"featured_media":110418,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-110417","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/110417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=110417"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/110417\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/110418"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=110417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=110417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=110417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}