{"id":110444,"date":"2019-05-28T06:56:54","date_gmt":"2019-05-28T04:56:54","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/ndrangheta-cinque-arresti-per-omicidio-aggravato-dalle-finalita-mafiose\/"},"modified":"2023-01-16T18:28:07","modified_gmt":"2023-01-16T17:28:07","slug":"295259-ndrangheta-cinque-arresti-per-omicidio-aggravato-dalle-finalita-mafiose","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/295259-ndrangheta-cinque-arresti-per-omicidio-aggravato-dalle-finalita-mafiose\/","title":{"rendered":"&#8216;Ndrangheta, cinque arresti per omicidio aggravato dalle finalit\u00e0 mafiose"},"content":{"rendered":"<h4>Cinque persone sono state colpite da provvedimenti cautelari, emessi dai gip dei Tribunali di Milano e Catanzaro, accusate di omicidio aggravato dalle finalita\u2019 mafiose. <!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CROTONE &#8211; L&#8217;indagine, svolta in stretta sinergia e costante coordinamento dalla procure <strong>distrettuali di Milano e Catanzaro<\/strong> \u2013 segue l\u2019operazione <strong>Stige<\/strong> condotta dai carabinieri del Ros nel gennaio del 2018\u00a0 e che ha disarticolato<strong> la \u201clocale\u201d di \u2018ndrangheta di Ciro\u2019<\/strong>. Blitz che ha consentito di dare nuovo impulso alle indagini in ordine agli omicidi di Vincenzo Pirillo e Cataldo Aloisio, verificatisi rispettivamente il agosto 2007 a Ciro\u2019 Marina (Kr) e il 27 settembre 2008 a Legnano (Mi). Gli investigatori hanno accertato come i due delitti, maturati in seno al sodalizio cirotano e decisi dai vertici della locale di Ciro\u2019 Marina, fossero tra loro strettamente collegati e finalizzati al mantenimento degli equilibri interni all&#8217;organizzazione.<\/p>\n<p>L\u2019omicidio in territorio lombardo, affidata al capo della locale di Legnano, ha confermato che le due locali di \u2018ndrangheta (operanti, rispettivamente, sul territorio di Ciro\u2019 Marina e Legnano) erano strettamente collegate ed operino in stretta sinergia, come gia\u2019 accertato da sentenze definitive. Dalle ordinanze dei gip di Milano e Catanzaro emerge, in particolare, che l\u2019eliminazione di Pirillo \u2013 per un periodo reggente della cosca \u2013 veniva stabilita (da Cataldo Marincola e Giuseppe Spagnolo) ed eseguita da Spagnolo per punirne l\u2019impropria gestione delle casse del clan, avendo lo stesso pirillo anteposto i propri interessi al mantenimento delle famiglie dei detenuti. L\u2019omicidio di Aloisio \u2013 nipote di Pirillo \u2013 venne conseguentemente deliberato (da Farao e Marincola) ed eseguito (da Rispoli e Farao) per il timore di una sua vendetta, che avrebbe inevitabilmente destabilizzato gli equilibri dell\u2019associazione mafiosa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cinque persone sono state colpite da provvedimenti cautelari, emessi dai gip dei Tribunali di Milano e Catanzaro, accusate di omicidio aggravato dalle finalita\u2019 mafiose.<\/p>\n","protected":false},"author":42,"featured_media":110445,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-110444","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/110444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=110444"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/110444\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/110445"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=110444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=110444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=110444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}