{"id":110558,"date":"2019-05-30T11:13:22","date_gmt":"2019-05-30T09:13:22","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/la-protesta-del-sindaco-di-san-giovanni-in-fiore-allasp-riaprite-lufficio-ticket\/"},"modified":"2023-01-16T18:28:15","modified_gmt":"2023-01-16T17:28:15","slug":"295705-la-protesta-del-sindaco-di-san-giovanni-in-fiore-allasp-riaprite-lufficio-ticket","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/295705-la-protesta-del-sindaco-di-san-giovanni-in-fiore-allasp-riaprite-lufficio-ticket\/","title":{"rendered":"La protesta del sindaco di San Giovanni in Fiore all&#8217;Asp di Cosenza: &#8220;riaprite l&#8217;ufficio ticket&#8221;"},"content":{"rendered":"<h4>Giuseppe Belcastro aveva gi\u00e0 manifestato al Prefetto l&#8217;enorme disagio provocato dalla chiusura dell\u2019ufficio, con gli utenti riversati presso l\u2019unico sportello funzionante e che provoca file lunghissime. Questa mattina la nuova protesta all&#8217;Asp di Cosenza per quello che ritiene un atto &#8220;incomprensibile ed inaccettabile&#8221;<!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>COSENZA &#8211;\u00a0Non demorde il sindaco Belcastro rispetto alle <strong>gravissime<a href=\"https:\/\/quicosenza.it\/news\/7124\"> problematiche di accesso al servizio di prenotazione e pagamento ticket<\/a><\/strong> venutesi a creare \u00a0a San Giovanni in Fiore dopo la decisione di c<strong>hiudere l&#8217;ufficio preposto presso l&#8217;ospedale cittadino<\/strong>. Una situazione paradossale che, come denunciato ieri dallo stesso sindaco, <strong>sta provocando enormi disagi tra i cittadini\/utenti, costretti a sopportare file lunghissime<\/strong> alla fine delle quali, a volte, non si riesce neppure ad avere soddisfatte le prestazioni richieste.<\/p>\n<div><\/div>\n<div>&#8220;Anche questa mattina mi sono recato presso gli uffici dell&#8217;Asp di Cosenza per \u00a0<strong>manifestare, a nome dell&#8217;intera collettivit\u00e0 sangiovannese, le sacrosante proteste verso un atto che rimane ancora incomprensibile ed inaccettabile<\/strong> e per chiedere, quindi, \u00a0la <strong>riapertura dell&#8217;ufficio ticket<\/strong> \u2013 afferma Pino Belcastro &#8211; \u00a0I<strong> disagi che si stanno registrando presso l&#8217;unico sportello funzionante ubicato nel distretto sanitario sono inaccettabili<\/strong> per i pazienti e per le loro famiglie, che hanno il sacrosanto diritto di poter accedere il pi\u00f9 \u00a0agevolmente possibile \u00a0a questo servizio. \u00a0Ho, pertanto, se<strong>ntito il dirigente amministrativo dell&#8217;Asp di Cosenza, Elio Bozzo, al quale ho riportato il malessere che vive la comunit\u00e0 e tutta la mia amarezza<\/strong> e prostrazione per l&#8217;ennesima criticit\u00e0 \u00a0che siamo costretti a vivere in campo sanitario. Il dott. Bozzo mi h<strong>a assicurato massima attenzione e disponibilit\u00e0 per la soluzione della problematica<\/strong>. Intanto invito i miei concittadini ad <strong>utilizzare anche il servizio prenotazione e pagamento ticket attivo nelle farmacie cittadine convenzionate ed abilitate<\/strong>. Ci\u00f2 pu\u00f2 momentaneamente limitare \u00a0il disservizio, nell&#8217;attesa che tale problematica sia affrontata e risolta definitivamente. Nelle more, per quanto \u00e8 nelle possibilit\u00e0 e nelle competenze del Comune, mi sono dichiarato disponibile sin da subito \u00a0ad attuare ogni atto ed iniziativa utile alla soluzione del problema&#8221;.<\/div>\n<div><\/div>\n<div>&#8220;Che sia chiaro a tutti per\u00f2 \u2013 conclude il sindaco Belcastro \u2013 <strong>sui temi della \u00a0sanit\u00e0, sulla garanzia del diritto alla cura dei sangiovannesi \u00a0non faremo mai passi indietro<\/strong> e c<strong>ontinueremo a batterci per avere un sistema sanitario efficace ed efficiente<\/strong>, rispondente ai bisogni ed alla salvaguardia della salute dei nostri concittadini&#8221;.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Giuseppe Belcastro aveva gi\u00e0 manifestato al Prefetto l&#8217;enorme disagio provocato dalla chiusura dell\u2019ufficio, con gli utenti riversati presso l\u2019unico sportello funzionante e che provoca file lunghissime. Questa mattina la nuova protesta all&#8217;Asp di Cosenza per quello che ritiene un atto &#8220;incomprensibile ed inaccettabile&#8221;<\/p>\n","protected":false},"author":46,"featured_media":110559,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-110558","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/110558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=110558"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/110558\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/110559"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=110558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=110558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=110558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}