{"id":110641,"date":"2019-05-31T15:43:38","date_gmt":"2019-05-31T13:43:38","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/omicidio-ruffolo-porcaro-scarcerato\/"},"modified":"2023-01-16T18:28:20","modified_gmt":"2023-01-16T17:28:20","slug":"295974-omicidio-ruffolo-porcaro-scarcerato","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/295974-omicidio-ruffolo-porcaro-scarcerato\/","title":{"rendered":"Omicidio Ruffolo, Porcaro scarcerato"},"content":{"rendered":"<h4>Libero, Roberto Porcaro lascia il carcere per assenza di gravit\u00e0\u00a0degli\u00a0indizi di\u00a0colpevolezza<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Il Tribunale del riesame ha scarcerato Roberto Porcaro accusato di essere il mandante nell&#8217;omicidio Ruffolo, ucciso il 22 settembre 2011 mentre percorreva via degli stadi in Cosenza a bordo della propria autovettura Alfa romeo Giulietta. La difesa rappresentata dagli avvocati Gianluca Acciardi e Sergio Rotundo, lo scorso 28 maggio hanno discusso il ricorso presentato per chiedere l&#8217;annullamento della misura cautelare della custodia in carcere. Ricordiamo che Porcaro era stato tratto in arresto il 17 maggio scorso insieme a Massimiliano D&#8217;Elia accusato di essere l&#8217;esecutore materiale dell&#8217;omicidio.<\/p>\n<p>Gli avvocati dell&#8217;indagato hanno prodotto indagini difensive, documentando ogni singola dichiarazione accusatoria mossa dai collaboratori di giustizia. Tra l&#8217;altro hanno dimostrato come Porcaro fino a marzo del 2019 non era neanche iscritto nel registro delle notizie di reato, evento avvenuto solo dopo le dichiarazioni dei due pentiti Giuseppe Montemurro e Zaffonte Giuseppe, evidenziando come queste fossero contraddittorie le une con le altre. Per Massimiliano D&#8217;Elia, difeso dall&#8217;avvocato Fiorella Bozzarello ancora c&#8217;\u00e8 da attendere. L&#8217;udienza del riesame sar\u00e0 fissata nella prossima settimana.<\/p>\n<p>Le accuse mosse ai due indagati sono di omicidio, aggravato dal metodo e dall\u2019aver agevolato un\u2019associazione mafiosa, e porto illegale di armi. All\u2019indagine portata avanti dal sostituto procuratore della Dda Camillo Falvo avrebbero contribuito anche le dichiarazioni dei due collaboratori di giustizia, ricostruendo le dinamiche del clan mafioso Lanzino-Patitucci che portarono all\u2019omicidio di Giuseppe Ruffolo, attinto da diversi colpi d\u2019arma da fuoco.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-293184\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/05\/omicidio-ruffolo-cosenza-2011-07.jpg\" alt=\"\" width=\"900\" height=\"474\" title=\"\"><\/p>\n<p>In particolare D\u2019Elia anche quale esecutore materiale, lo avrebbe attinto con numerosi colpi d\u2019arma da fuoco (almeno 6), con una pistola calibro 7,65. Quest\u2019ultimo a bordo uno scooter \u201cApulia Scarabeo 500\u201d avrebbe affiancato la vittima che viaggiava sulla sua autovettura near \u201cAlfa Romeo Giulietta\u201d su via degli Stadi, a Cosenza<\/p>\n<p>Sempre secondo gli inquirenti dalle testimonianze rese dai collaboratori di giustizia, D\u2019Elia avrebbe agito a causa dei contrasti insorti all\u2019interno del clan mafioso confederato Lanzino-Patitucci per il quale era impegnato in attivit\u00e0 estorsive e spaccio. Ruffolo agiva senza il consenso del clan sull\u2019attivit\u00e0 usuraria che esercitava in citt\u00e0 e, ancor di pi\u00f9 senza far confluire parte dei proventi illeciti nella bacinella dell\u2019organizzazione criminale; D\u2019Elia all\u2019interno del clan si relazionava direttamente con Roberto Porcaro considerato uno dei vertici. Ma ci sarebbe anche un\u2019altra motivazione alla base dell\u2019omicidio di Ruffolo. D\u2019Elia avrebbe avuto contrasti con Ruffolo per via di una condanna di un amico di quest\u2019ultimo che lo stesso D\u2019Elia avrebbe indicato quale esecutore materiale di un attentato alla sua persona la sera del 28 ottobre 2006 presso la discoteca B-Side<\/p>\n<p>In buona sostanza D\u2019Elia il 22 settembre del 2011, avrebbe sparato e ucciso Ruffolo per fatti futili, con la premeditazione e compiendo il fatto con metodo Mafioso al fine di agevolare l\u2019associazione mafiosa Lanzino \u2013 Patitucci.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Libero, Roberto Porcaro lascia il carcere per assenza di gravit\u00e0\u00a0degli\u00a0indizi di\u00a0colpevolezza<\/p>\n","protected":false},"author":37,"featured_media":110642,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-110641","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/110641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=110641"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/110641\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/110642"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=110641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=110641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=110641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}