{"id":110739,"date":"2019-06-03T12:54:06","date_gmt":"2019-06-03T10:54:06","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/sub-e-giovani-uniti-per-raccogliere-la-plastica-dal-tirreno-cosentino-video\/"},"modified":"2023-01-16T18:28:27","modified_gmt":"2023-01-16T17:28:27","slug":"296245-sub-e-giovani-uniti-per-raccogliere-la-plastica-dal-tirreno-cosentino-video","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/296245-sub-e-giovani-uniti-per-raccogliere-la-plastica-dal-tirreno-cosentino-video\/","title":{"rendered":"Sub e giovani uniti per raccogliere la plastica dal Tirreno cosentino (VIDEO)"},"content":{"rendered":"<h4>Ripuliti spiagge e fondali dai numerosi rifiuti abbandonati<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>PRAIA A MARE (CS) &#8211; Il Tour Spiagge #Plasticfree 2019 organizzato dall\u2019organizzazione Aggregata WWF Cosenza Sila Pollino si \u00e8 svolto sabato 1 giugno a Fiuzzi di Praia a Mare in una giornata gioiosa, di sole, emozionante. I bambini, quasi adolescenti, delle classi secondarie di primo grado (prime sezione A e B) dell\u2019Istituto Comprensivo di Praia a Mare, si sono adoperati per la raccolta di plastica (e non solo) sulla spiaggia e con il generoso aiuto degli amici \u201cDinoSub\u201d dell\u2019isola di Dino guidati dal responsabile Giorgio Chiappetta, anche il fondale \u00e8 stato ripulito. Le autorit\u00e0 rappresentate dagli assessori comunali Ferdinando Marsiglia, dall\u2019assessore (e docente degli alunni presenti) Anna Maiorano, dal delegato di spiaggia comandante Domenico Galasso dell\u2019Ufficio Locale Marittimo di Praia a Mare, dalla Capitaneria di Porto di Maratea comandata da Antonio Bisanti, da Massimo Lo Monaco e Valentina Paduano del Nucleo Operativo WWF di Maratea, si sono amalgamate nella freschezza e nei colori dei ragazzini e di quel luogo magico. Il Presidente Nicoletta Boldrini e il referente Campagna Mare Gianni Argir\u00f2 dell\u2019O.A. WWF Cosenza Sila Pollino si ritengono <strong>soddisfatti dell\u2019ottima riuscita dell\u2019evento e sono sicuri che proprio le nuove generazioni animeranno e guideranno gli adulti scuotendo le coscienze del mondo, proprio come ha fatto Greta Thunberg. <\/strong>\u201cSolo i bambini mettendosi un dito nel naso potranno guidare\u201d canta Ron in \u201cil mondo avr\u00e0 una grande anima\u201d frasi che rappresentano l&#8217;entusiasmante esperienza vissuta in questo weekend e documentata ne video racconto di Benedetta, socio junior WWF.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"Tour Spiagge #Plasticfree 2019 - Praia a Mare (CS)\" width=\"740\" height=\"416\" src=\"https:\/\/www.youtube.com\/embed\/ZlN-Q8a7nuk?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ripuliti spiagge e fondali dai numerosi rifiuti abbandonati<\/p>\n","protected":false},"author":43,"featured_media":110740,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,34,13],"tags":[],"class_list":["post-110739","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-magazine","category-qui-green"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/110739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=110739"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/110739\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/110740"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=110739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=110739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=110739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}