{"id":110761,"date":"2019-06-03T18:03:00","date_gmt":"2019-06-03T16:03:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/appalti-calabria-adamo-presenta-un-esposto-al-csm-contro-gratteri\/"},"modified":"2023-01-16T18:28:28","modified_gmt":"2023-01-16T17:28:28","slug":"296304-appalti-calabria-adamo-presenta-un-esposto-al-csm-contro-gratteri","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/296304-appalti-calabria-adamo-presenta-un-esposto-al-csm-contro-gratteri\/","title":{"rendered":"Appalti Calabria: Adamo presenta un esposto al Csm contro Gratteri"},"content":{"rendered":"<h4>L&#8217;ex vicepresidente Regione ha reso noto, in un comunicato, di avere presentato un esposto &#8220;nei confronti del Procuratore della Repubblica di Catanzaro Nicola Gratteri<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; L\u2019ex vicepresidente della Giunta regionale della Calabria, Nicola Adamo, indagato dalla Procura di Catanzaro in due inchieste su presunte irregolarit\u00e0 nella gestione di alcuni appalti, ha presentato un esposto nei confronti del procuratore Nicola Gratteri, esposto indirizzato al presidente del Csm e ai procuratori generali presso la Corte di Cassazione e la Corte d\u2019appello del capoluogo calabrese. Lo ha reso noto, con un comunicato, lo stesso Adamo. \u201cL\u2019informazione pubblica che i magistrati inquirenti svolgono sulle attivit\u00e0 di indagine \u2013 scrive Adamo &#8211; deve sempre rispettare il principio di presunzione di non colpevolezza e la dignit\u00e0 dei soggetti coinvolti, ormai patrimonio condiviso, anche in ambito europeo.<\/p>\n<p>Le recenti modalit\u00e0 di comunicazione che hanno caratterizzato la \u2018presentazione\u2019 dei procedimenti denominati \u2018Lande desolate\u2019 e \u2018Passepartout\u2019 mi hanno indotto a formalizzare un esposto nei confronti del procuratore della Repubblica di Catanzaro, Nicola Gratteri, indirizzato al presidente del Consiglio superiore della magistratura, al procuratore generale presso la Corte di Cassazione e al procuratore generale presso la competente Corte di Appello. Questa mia doverosa iniziativa \u2013 prosegue l\u2019ex vicepresidente della Regione &#8211; non ha nulla a che vedere con il merito della vicenda rispetto al quale, come sempre, non mi sottrarr\u00f2 all\u2019accertamento dei fatti per difendere la mia totale innocenza.<\/p>\n<p>Con i miei legali, Ugo Celestino e Fabio Viglione, mi difender\u00f2 nel processo e non dal processo, nel pieno rispetto delle regole e con la fiducia che ciascun cittadino deve nutrire nel lavoro dell\u2019autorit\u00e0 giudiziaria\u201d. Adamo quindi conclude: \u201cL&#8217;esposto ho inteso inoltrarlo, dunque, al solo fine di tutelare i diritti e la dignit\u00e0 dell&#8217;indagato nel tentativo di contrastare gogne mediatiche conseguenti a suggestioni colpevoliste magari fondate su pregiudizi accusatori&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;ex vicepresidente Regione ha reso noto, in un comunicato, di avere presentato un esposto &#8220;nei confronti del Procuratore della Repubblica di Catanzaro Nicola Gratteri<\/p>\n","protected":false},"author":44,"featured_media":110762,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,42],"tags":[],"class_list":["post-110761","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/110761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=110761"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/110761\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/110762"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=110761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=110761"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=110761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}