{"id":110777,"date":"2019-06-04T09:06:50","date_gmt":"2019-06-04T07:06:50","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/giunta-manna-le-dichiarazioni-alla-vigilia-del-ballottaggio\/"},"modified":"2023-01-16T18:28:30","modified_gmt":"2023-01-16T17:28:30","slug":"296388-giunta-manna-le-dichiarazioni-alla-vigilia-del-ballottaggio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/296388-giunta-manna-le-dichiarazioni-alla-vigilia-del-ballottaggio\/","title":{"rendered":"Giunta Manna: le dichiarazioni alla vigilia del ballottaggio"},"content":{"rendered":"<h4>Riceviamo e pubblichiamo una nota congiunta diffusa dalla giunta Manna alla vigilia del turno di ballottaggio previsto domenica 9 giugno<!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>RENDE (CS) &#8211; \u201cSono stati anni di lavoro serrato e appassionante. Si \u00e8 agito seguendo un modello di governance territoriale capace di valorizzare esperienze condivise di educazione di genere e cittadinanza paritaria realizzando un modello esportabile di societ\u00e0 civile all\u2019interno delle istituzioni\u201d. Inizia cos\u00ec la nota congiunta diffusa dalla giunta Manna alla vigilia del ballottaggio di domenica nove giugno.<\/p>\n<p>\u201cAbbiamo lavorato &#8211; proseguono gli assessori &#8211; in un\u2019ottica democratica partecipata, proponendo azioni dal basso tese a tutelare dignit\u00e0 e diritti delle donne e degli uomini, delle fasce pi\u00f9 deboli oltre che a individuarne bisogni e necessit\u00e0. Ponendo i cittadini come attori principali di una programmazione partecipata, si \u00e8 tracciato un percorso che, nel riconoscimento della autonomia del lavoro dei singoli assessorati, ha visto la giunta lavorare in maniera collegiale condividendo spesso percorsi d\u2019azione. Dal lavoro comune condotto dalla nostra giunta, dove gli ambiti d\u2019intervento si sono pi\u00f9 volte incrociati contaminandosi in un\u2019ottica comunitaria, abbiamo posto in essere un&#8217;organica opera di rivitalizzazione riuscendo a riconsiderare la &#8220;polis&#8221;, cuore ed insieme centro del nostro agire politico\u201d.<\/p>\n<p>\u201cL&#8217;accessibilit\u00e0 &#8211; continua la nota &#8211; \u00e8 stato presupposto necessario da cui partire, cos\u00ec come il ri-lancio di una nuova economia urbana che si basa su terziario avanzato, rete di innovazioni, una classe dirigente giovane in grado di fare della citt\u00e0 un polo multisettoriale e all&#8217;avanguardia. In questi anni siamo riusciti a risanare conti e ad azzerare i debiti. Abbiamo colto le istanze del nostro personale e siamo riusciti ad assumere a tempo indeterminato e a tempo pieno i lavoratori che per anni hanno vissuto sulle loro spalle il precariato. Rende, dunque, &#8211; conclude la giunta &#8211; come citt\u00e0 dei diritti un tempo negati, consapevoli che il sociale cos\u00ec come le pari opportunit\u00e0 siano strumenti necessari al processo di rigenerazione urbana. Chiave di volta di tale processo \u00e8 stato il civismo, la cittadinanza attiva, la cultura: monumenti e chiese sono divenuti beni non meramente conservati, ma rivitalizzati; si \u00e8 lavorato nelle scuole e in ateneo alla costruzione di percorsi di autodeterminazione e consapevolezza di s\u00e9; le maestranze sono state valorizzate affinch\u00e9 il sapere artigiano divenga al tempo stesso conoscenza degli antichi mestieri e prospettiva lavorativa futura per incentivare l\u2019appartenenza al proprio territorio.<\/p>\n<p>Un territorio che abbiamo voluto tutelare anche da un punto di vista ambientale: siamo comune virtuoso per quanto riguarda la cultura della raccolta differenziata diffusa ormai a tutti i livelli, ma siamo anche comune modello in tema di protezione civile e di salvaguardia del territorio. Ri-costruire ed insieme capitalizzare il nostro patrimonio umano, storico, artistico: cos\u00ec abbiamo attivato un dialogo virtuoso tra economia, cultura, turismo, imprenditoria mettendo in campo una progettazione condivisa. Si \u00e8 alimentato un nuovo modo di guardare alla cosa pubblica non solo come fonte di identit\u00e0 culturale e coesione sociale, ma anche fattore competitivo e di crescita economica nel segno dell&#8217;innovazione dove la comunit\u00e0 avr\u00e0 modo di formarsi e confrontarsi su una pluralit\u00e0 di linguaggi, saperi e tradizioni mettendo insieme culture provenienti da tutto il mondo. Riteniamo, dunque, che attraverso tali buone pratiche, realizzando percorsi virtuosi sia stato possibile costruire una nuova idea di citt\u00e0: aperta, plurale, multiculturale, identitaria, comunitaria. Una citt\u00e0 a misura d&#8217;uomo dove convergono e si mescolano culture e patrimoni umani, sociali, artistici e culturali\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Riceviamo e pubblichiamo una nota congiunta diffusa dalla giunta Manna alla vigilia del turno di ballottaggio previsto domenica 9 giugno<\/p>\n","protected":false},"author":46,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[44],"tags":[],"class_list":["post-110777","post","type-post","status-publish","format-standard","hentry","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/110777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=110777"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/110777\/revisions"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=110777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=110777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=110777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}