{"id":110793,"date":"2019-06-04T12:57:14","date_gmt":"2019-06-04T10:57:14","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/brutale-aggressione-per-rapina-gli-portano-via-un-pacchetto-di-sigarette-arrestati\/"},"modified":"2023-01-16T18:28:31","modified_gmt":"2023-01-16T17:28:31","slug":"296447-brutale-aggressione-per-rapina-gli-portano-via-un-pacchetto-di-sigarette-arrestati","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/296447-brutale-aggressione-per-rapina-gli-portano-via-un-pacchetto-di-sigarette-arrestati\/","title":{"rendered":"Brutale aggressione per rapina. Gli portano via un pacchetto di sigarette, arrestati"},"content":{"rendered":"<h4>Notte da incubo per un giovane 27enne aggredito da tre persone a Catanzaro. I malviventi, alla fine, gli hanno portato via solo un pacchetto di sigarette prima di fuggire in auto. La Squadra Volante li ha individuati, inseguiti e infine arrestati<!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>CATANZARO &#8211; <strong>Aggredito e picchiato in modo violento da 3 malviventi<\/strong> che volevano rapinarlo ma che alla fine se erano dileguarsi in auto <strong>portandogli via solo un pacchetto di sigarette<\/strong>. Si \u00e8 conclusa con <b>3 arresti da parte della polizia e 25 giorni di prognosi<\/b> al malcapitato, l&#8217;<strong>aggressione per rapina avvenuta nei pressi di una pizzeria in Via Campanella<\/strong> a Catanzaro, in danno di un giovane 27enne.<\/p>\n<p>E&#8217; stato proprio il giovane, nella tarda serata di ieri, a recarsi presso il centro polifunzionale della Polizia di Stato per chiedere aiuto denunciando l&#8217;aggressione da parte di 3 persone. I militari hanno immediatamente allertato la sala operativa fornendo le informazioni date dall\u2019uomo e in tempo reale sono state diramate alle pattuglie della volante. Fondamentali all&#8217;arresto sono state proprio l<strong>e descrizioni dei 3 malviventi fornite dal 27enne e dell\u2019automobile sulla quale si erano allontanati<\/strong> dopo averlo aggredito. Il conducente del veicolo, intercettato su viale Campanella, anzich\u00e9 fermarsi all\u2019Alt intimato dalla pattuglia della polizia, <strong>ha iniziato una spericolata fuga verso la tangenziale est<\/strong> mettendo a repentaglio l\u2019incolumit\u00e0 degli operatori e delle autovetture che incrociava nella folle fuga. <strong>Appena imboccata Via Gallucci gli occupanti hanno abbandonato la vettura per nascondersi in un portone dove gli agenti li hanno bloccati<\/strong>.<\/p>\n<p>Nei pressi dell\u2019ingresso dello stesso portone \u00e8 stata trovata una fel<strong>pa grigia intrisa di sangue, corrispondente alla descrizione fornita dalla vittima dell\u2019aggressione<\/strong>. Condotti negli uffici della questura, i tre sono stati identificati per V.A., pregiudicato catanzarese di 19 anni, V.G.D. catanzarese di 18 anni e C.A., catanzarese di 20 anni. Durante la perquisizione personale e del veicolo, \u00e8 stato r<strong>invenuto il pacchetto di sigarette rubato durante l\u2019aggressione<\/strong>. I tre giovani <strong>sono stati arrestati e su disposizione del P.M. di turno reclusi nella casa circondariale della citt\u00e0<\/strong>. Alla vittima dell\u2019 aggressione, condotta al pronto soccorso per le gravi lesioni plurime subite, sono stati diagnosticati venticinque giorni di prognosi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notte da incubo per un giovane 27enne aggredito da tre persone a Catanzaro. I malviventi, alla fine, gli hanno portato via solo un pacchetto di sigarette prima di fuggire in auto. La Squadra Volante li ha individuati, inseguiti e infine arrestati<\/p>\n","protected":false},"author":46,"featured_media":110794,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-110793","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/110793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=110793"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/110793\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/110794"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=110793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=110793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=110793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}