{"id":110808,"date":"2019-06-04T15:07:35","date_gmt":"2019-06-04T13:07:35","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cassano-riprendiamoci-palazzo-pontieri\/"},"modified":"2023-01-16T18:28:32","modified_gmt":"2023-01-16T17:28:32","slug":"296489-cassano-riprendiamoci-palazzo-pontieri","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/296489-cassano-riprendiamoci-palazzo-pontieri\/","title":{"rendered":"Cassano: riprendiamoci Palazzo Pontieri"},"content":{"rendered":"<h4>Ancora oggi, purtroppo, dopo una spesa milionaria, gli immobili non sono mai stati consegnati al Comune<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>CASSANO ALL\u2019IONIO &#8211; La <strong>commissione straordinaria di Cassano<\/strong>, in una comunicazione indirizzata alla direzione generale dell\u2019<strong>Aterp di Cosenza<\/strong>,<strong> ha richiesto il ripristino di Palazzo Pontieri-Gallo<\/strong>. Si tratta di uno dei tre palazzi gentilizi appartenuti a famiglie nobili cassanesi, come i palazzi Oriolo e Toscano, acquistati e ristrutturati dall\u2019Aterp per farne centri culturali e spazi di edilizia residenziale pubblica. Ancora oggi, purtroppo, dopo una spesa milionaria, gli immobili non sono mai stati consegnati al Comune, divenendo, nel frattempo preda dei vandali che li hanno sfregiati e depredati. \u00abAl fine di evitare l\u2019ulteriore degrado dell\u2019edificio, si richiede all\u2019azienda destinataria dell\u2019istanza, di provvedere con urgenza al ripristino delle porte d\u2019ingresso e degli impianti installati all\u2019interno dell\u2019edificio\u00bb. <strong>La commissione straordinaria composta dai vice prefetti Mario Muccio e Roberto Pacchiarotti e dalla dirigente di prefettura Rita Guida<\/strong>, con l\u2019occasione ha manifestato la disponibilit\u00e0 per un incontro finalizzato ad esaminare tempi e modalit\u00e0 di consegna e del relativo utilizzo da parte dell\u2019ente, del Palazzo gentilizio Pontieri-Gallo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ancora oggi, purtroppo, dopo una spesa milionaria, gli immobili non sono mai stati consegnati al Comune<\/p>\n","protected":false},"author":48,"featured_media":110809,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-110808","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/110808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=110808"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/110808\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/110809"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=110808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=110808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=110808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}