{"id":111094,"date":"2019-06-10T17:57:06","date_gmt":"2019-06-10T15:57:06","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/migranti-ospitati-in-albergo-abusivo-dalla-procura-lordinanza-di-sequestro\/"},"modified":"2023-01-16T18:28:52","modified_gmt":"2023-01-16T17:28:52","slug":"297866-migranti-ospitati-in-albergo-abusivo-dalla-procura-lordinanza-di-sequestro","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/297866-migranti-ospitati-in-albergo-abusivo-dalla-procura-lordinanza-di-sequestro\/","title":{"rendered":"Migranti ospitati in albergo abusivo: dalla Procura l&#8217;ordinanza di sequestro"},"content":{"rendered":"<h4>I fatti risalgono tra il 2016 e il 2017. Le indagini sono state coordinate dall&#8217;ufficio di Procura reggino. Il sequestro \u00e8 stato effettuato dai militari dell&#8217;Arma<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>MELITO PORTO SALVO (RC) &#8211; I carabinieri della Compagnia di Melito Porto Salvo hanno eseguito un provvedimento di sequestro preventivo emesso dal Tribunale di Reggio Calabria, su richiesta della Procura della Repubblica, della struttura alberghiera &#8220;Stella Marina&#8221;. L&#8217;albergo, per un anno, tra ottobre 2016 e ottobre 2017, era stato utilizzato per il servizio di accoglienza di migranti richiedenti protezione internazionale pur essendo carente, riferiscono gli investigatori, dei titoli edilizi di agibilit\u00e0, abitabilit\u00e0 e sicurezza in quanto composto da opere abusive.<\/p>\n<p>I militari hanno anche sequestrato le quote sociali ed il conto corrente della Leone srl, la societ\u00e0 che ha in gestione l&#8217;immobile oggetto di sequestro. Sequestrati anche i rapporti bancari, finanziari e assicurativi ed un quinto dei trattamenti retributivi, pensionistici ed assistenziali degli amministratori della Leone srl, sino al raggiungimento del profitto illecito, quantificato in 550 mila euro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I fatti risalgono tra il 2016 e il 2017. Le indagini sono state coordinate dall&#8217;ufficio di Procura reggino. Il sequestro \u00e8 stato effettuato dai militari dell&#8217;Arma<\/p>\n","protected":false},"author":44,"featured_media":111095,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-111094","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/111094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=111094"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/111094\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/111095"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=111094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=111094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=111094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}