{"id":111209,"date":"2019-06-12T15:49:43","date_gmt":"2019-06-12T13:49:43","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/bottino-sospetto-nellautocarro-e-la-refurtiva-di-diverse-rapine\/"},"modified":"2023-01-16T18:29:00","modified_gmt":"2023-01-16T17:29:00","slug":"298250-bottino-sospetto-nellautocarro-e-la-refurtiva-di-diverse-rapine","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/298250-bottino-sospetto-nellautocarro-e-la-refurtiva-di-diverse-rapine\/","title":{"rendered":"Bottino sospetto nell\u2019autocarro. \u00c8 la refurtiva di diverse rapine"},"content":{"rendered":"<h4>I due rumeni si divertono incendiando autovetture, sgozzando animali domestici e terrorizzando i residenti<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>CASSANO ALL&#8217;IONIO \u2013 <strong>Bottino sospetto nell\u2019autocarro.<\/strong> All\u2019interno dell\u2019autocarro fermato dalla Guardia di Finanza di Montegiordano a Roseto Capo Spulico con a bordo uomini di nazionalit\u00e0 rumena si trovava un bottino sospetto: taniche di gasolio vuote, tronchesi giganti solitamente usate per i furti, un piccone, dei passamontagna, una torcia e altri arnesi da scasso.<\/p>\n<p><strong>Il fermo rappresenta una svolta nelle indagini sulla banda che nelle scorse settimane ha ripulito una serie di villette tra Cassano e Francavilla. Uno dei due uomini \u00e8 riuscito a fuggire, mentre il secondo \u00e8 stato identificato in V.G., trentacinquenne rumeno e stato arrestato dai Finanzieri.<\/strong><\/p>\n<p>Sequestrato anche l\u2019autocarro utilizzato sia per caricare il gasolio agricolo rubato, sia per portare via piccoli mezzi agricoli come motozappe e falciatrici che venivano caricati facilmente sul mezzo.<\/p>\n<p>Non \u00e8 ancora chiaro se si tratti di una banda composta di soli stranieri. Entrano nelle villette facendo razzia di monili d\u2019oro, soldi, attrezzature utili per la rivendita quali motoseghe, motozappe e trattrici di piccole. Particolare, per\u00f2, la loro aggressivit\u00e0 dopo i furti. Infatti i due rumeni, finite le operazioni, proseguono incendiando autovetture, sgozzando animali domestici e terrorizzando i residenti.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I due rumeni si divertono incendiando autovetture, sgozzando animali domestici e terrorizzando i residenti<\/p>\n","protected":false},"author":47,"featured_media":111210,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-111209","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/111209","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/47"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=111209"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/111209\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/111210"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=111209"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=111209"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=111209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}