{"id":111420,"date":"2019-06-18T06:28:46","date_gmt":"2019-06-18T04:28:46","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/operazione-balboa-contro-cosca-di-ndrangheta-e-traffico-internazionale-di-cocaina\/"},"modified":"2023-01-16T18:29:14","modified_gmt":"2023-01-16T17:29:14","slug":"298951-operazione-balboa-contro-cosca-di-ndrangheta-e-traffico-internazionale-di-cocaina","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/298951-operazione-balboa-contro-cosca-di-ndrangheta-e-traffico-internazionale-di-cocaina\/","title":{"rendered":"Operazione \u201cBalboa\u201d contro cosca di &#8216;ndrangheta e traffico internazionale di cocaina"},"content":{"rendered":"<h4>Cinque persone sono state arrestate dai finanzieri di Reggio Calabria e del Servizio Centrale Investigazione Criminalit\u00e0 Organizzata nell&#8217;operazione denominata Balboa. Tutti presunti appartenenti ad un\u2019associazione per delinquere finalizzata al traffico internazionale di cocaina legata alla cosca di &#8216;ndrangheta dei Bellocco di Rosarno<\/h4>\n<h4><!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>REGGIO CALABRIA \u2013 Militari del c<strong>omando provinciale della Guardia di Finanza di Reggio Calabria<\/strong> e del <strong>Servizio Centrale Investigazione Criminalit\u00e0 Organizzata della Guardia di Finanza<\/strong> \u2013 con il coordinamento della Direzione Distrettuale Antimafia di Reggio Calabria diretta dal Procuratore Capo Giovanni Bombardieri \u2013 stanno dando esecuzione nelle province di Roma, Reggio Calabria e Sassari ad una Ordinanza di applicazione di misura cautelare emessa dal Giudice per le Indagini Preliminari del Tribunale di Reggio Calabria nei confronti dei sodali di un\u2019associazione per delinquere finalizzata al traffico internazionale di cocaina operante sotto l\u2019egida della cosca di \u2018ndrangheta \u201c<strong>Bellocco<\/strong>\u201d <strong>di Rosarno.<\/strong><\/p>\n<p>Il provvedimento giudiziario dispone l\u2019applicazione della custodia cautelare in carcere nei confronti di\u00a0<strong>Oliveri Umberto Emanuele<\/strong> classe 1987, <strong>Pep\u00e8 Domenico<\/strong> classe 1955, <strong>Galanti Alessandro<\/strong> classe 1981, <strong>Ponziani Antonio<\/strong> classe 1985 e <strong>Larosa Alessandro<\/strong> classe 1978. Tutti ritenuti responsabili a vario titolo dei reati di <strong>associazione per delinquere finalizzata al traffico internazionale di sostanze stupefacenti<\/strong>\u00a0per essersi associati tra loro in un <strong>gruppo criminale articolato su pi\u00f9 livelli<\/strong>, comprensivo di <strong>squadre di operatori portuali infedeli<\/strong>, allo scopo di commettere pi\u00f9 delitti, concretizzatisi nel reperire ed acquistare all\u2019estero, importare, trasportare in Italia attraverso navi in arrivo al porto di Gioia Tauro ed in altri porti nazionali, nonch\u00e9 commercializzare ingenti quantitativi di stupefacente del tipo cocaina, con l\u2019aggravante della transnazionalit\u00e0 e dell\u2019aver commesso i fatti al fine di agevolare l\u2019attivit\u00e0 della cosca di \u2018ndrangheta \u201cBellocco\u201d operante in Rosarno, zone limitrofe, altre zone d\u2019Italia e all\u2019estero. I predetti sono stati ristretti, su disposizione dell\u2019Autorit\u00e0 Giudiziaria, presso le competenti Case Circondariali.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/7278\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-298952\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/06\/Guardia-di-Finanza-649x400.jpg\" alt=\"\" width=\"548\" height=\"338\" title=\"\"><\/a><\/p>\n<h4>Fiumi di cocaina dal Sud America e Nord Europa<\/h4>\n<p>L\u2019operazione di polizia, convenzionalmente denominata \u201c<strong>Balboa<\/strong>\u201d, rappresenta l\u2019epilogo di una complessa attivit\u00e0 investigativa svolta dalla <strong>Sezione G.O.A. del Nucleo di Polizia Economico Finanziaria di Reggio Calabria<\/strong>, che ha permesso di accertare l\u2019esistenza di un gruppo criminale capeggiato da\u00a0<strong>Oliveri Umberto Emanuele<\/strong>, dominus alla <strong>continua ricerca di cocaina da far giungere nel porto di Gioia Tauro dal Sud America e dal Nord Europa (Belgio, Brasile, Argentina, Ecuador e Per\u00f9)<\/strong> e legato da stretto vincolo parentale a\u00a0<strong>Belocco Umberto<\/strong>, entrambi ritenuti partecipi \u2013 il Bellocco con ruolo di vertice \u2013 dell\u2019omonima cosca.<\/p>\n<p>Nel dettaglio, secondo i ruoli accertati nel corso delle articolate investigazioni, oltre al gi\u00e0 citato Oliveri, emergevano le figure di Galanti Alessandro, <strong>vero e proprio broker internazionale in contatto con i narcos<\/strong> produttori esteri della sostanza stupefacente, di Larosa Alessandro e Ponziani Antonio, impegnati a coadiuvare l\u2019Oliveri e il Galanti nell\u2019organizzazione delle illecite forniture, nonch\u00e9 di Pep\u00e8 Domenico, uomo di fiducia, che si occupava anch\u2019egli dell\u2019acquisto e dell\u2019importazione della droga.\u00a0Giunta in Italia, al porto di Gioia Tauro (RC)<strong>, la cocaina \u2013 occultata con modalit\u00e0 cd. \u201crip on\u201d all\u2019interno dei container<\/strong> in borsoni pronti ad essere prelevati \u2013 veniva esfiltrata da operatori portuali infedeli, incaricati dall\u2019Oliveri di recuperare lo stupefacente e di portarlo al di fuori del sedime portuale gioiese.<\/p>\n<p>Al riguardo, nell\u2019ambito dello stesso procedimento penale, sono stati complessivamente <strong>sottoposti a sequestro 527 panetti di cocaina purissima, per un peso complessivo di 598,520 kg<\/strong>, nonch\u00e9 sono state ricostruite plurime ulteriori importazioni di stupefacente per complessivi <strong>312 Kg di cocaina<\/strong>.\u00a0I soggetti destinatari degli odierni provvedimenti restrittivi hanno inoltre dimostrato di poter contare su una fitta rete di contatti, talmente ramificata, da essere in grado di recuperare lo stupefacente non solo dal porto di Gioia Tauro, ma anche da altri porti, sia nazionali che esteri, avvalendosi della forza intimidatrice esercitata dalla stessa \u201ccosca\u201d di appartenenza.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/7279\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-294560\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/05\/Sequestro-droga-gioia-Tauro3-650x400.jpg\" alt=\"\" width=\"522\" height=\"321\" title=\"\"><\/a><\/p>\n<h4>Porto di Gioia Tauro &#8220;vero e proprio snodo commerciale della droga&#8221;<\/h4>\n<p>Alla luce di tali risultanze \u2013 condividendo le argomentazioni prospettate dalla citata DDA coordinata, per l\u2019area tirrenica, dal Procuratore Aggiunto Gaetano Paci \u2013 il G.I.P. del Tribunale di Reggio Calabria, ritenuta sussistente la gravit\u00e0 indiziaria del contesto sopra delineato, ha emesso il provvedimento cautelare personale nei confronti delle citate persone r<strong>itenute responsabili, a vario titolo, dei reati di associazione per delinquere finalizzata al traffico internazionale di sostanze stupefacenti<\/strong> aggravata dall\u2019<strong>aver agevolato un\u2019associazione di tipo mafioso e dalla transnazionalit\u00e0<\/strong>.\u00a0L\u2019operazione \u201cBalboa\u201d ha ribadito l\u2019importanza strategica assunta nel tempo per le consorterie criminali di stampo mafioso dal porto di Gioia Tauro, vero e proprio snodo commerciale per l\u2019importazione di ingenti quantitativi di narcotico provenienti dal Sud America e dal resto d\u2019Europa.<\/p>\n<p>Importanza confermata sia dai recenti numerosi sequestri di cocaina purissima per centinaia e centinaia di kg operati dai militari della Guardia di Finanza di Reggio Calabria all\u2019interno della suddetta area portuale, dopo che nel 2018 si era assistito ad un calo vertiginoso degli stessi, sia dalle evidenze giudiziarie, in parte gi\u00e0 cristallizzate in sentenze di condanna, emerse con le operazioni condotte sempre dalla Sezione GOA della Guardia di Finanza reggina:<\/p>\n<ul>\n<li><strong>nel luglio 2014<\/strong>\u00a0allorquando, nell\u2019ambito dell\u2019<strong>operazione \u201cPuerto Liberado\u201d<\/strong>, furono eseguite 18 misure cautelari in carcere, cui sono seguite numerose condanne confermate in grado di appello con sentenza del 2017;<\/li>\n<li><strong>nel luglio 2016<\/strong>, nell\u2019ambito dell\u2019<strong>operazione \u201cVulcano\u201d<\/strong>, quando furono eseguiti 15 provvedimenti cautelari personali disarticolando un\u2019associazione per delinquere finalizzata al traffico internazionale di cocaina per conto delle potenti cosche di \u2018ndrangheta\u00a0<strong>Mol\u00e8<\/strong>,\u00a0<strong>Piromalli<\/strong>,\u00a0<strong>Alvaro<\/strong>,\u00a0<strong>Crea<\/strong>\u00a0e\u00a0<strong>Pesce<\/strong>. Anche in questa occasione tutti i 22 imputati che hanno scelto il rito abbreviato sono stati condannati dal G.U.P. del locale Tribunale.<\/li>\n<\/ul>\n<p>L\u2019attivit\u00e0 svolta costituisce ennesima testimonianza delle sempre costanti attenzione ed impegno e della perfetta sinergia con la quale la Procura della Repubblica e la Guardia di Finanza di Reggio Calabria intervengono nel contrasto al traffico internazionale di sostanze stupefacenti, da sempre ritenuto il principale canale di finanziamento delle cosche di \u2018ndrangheta operanti nella provincia reggina.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cinque persone sono state arrestate dai finanzieri di Reggio Calabria e del Servizio Centrale Investigazione Criminalit\u00e0 Organizzata nell&#8217;operazione denominata Balboa. Tutti presunti appartenenti ad un\u2019associazione per delinquere finalizzata al traffico internazionale di cocaina legata alla cosca di &#8216;ndrangheta dei Bellocco di Rosarno<\/p>\n","protected":false},"author":46,"featured_media":111421,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-111420","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/111420","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=111420"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/111420\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/111421"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=111420"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=111420"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=111420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}