{"id":111534,"date":"2019-06-20T06:13:37","date_gmt":"2019-06-20T04:13:37","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/comune-di-cosenza-a-rischio-dissesto-incontro-lunedi-i-cittadini-devono-essere-informati\/"},"modified":"2023-01-16T18:29:22","modified_gmt":"2023-01-16T17:29:22","slug":"299363-comune-di-cosenza-a-rischio-dissesto-incontro-lunedi-i-cittadini-devono-essere-informati","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/299363-comune-di-cosenza-a-rischio-dissesto-incontro-lunedi-i-cittadini-devono-essere-informati\/","title":{"rendered":"Comune di Cosenza a rischio dissesto, incontro luned\u00ec: &#8220;I cittadini devono essere informati&#8221;"},"content":{"rendered":"<h4>Preoccupa il provvedimento della Corte dei Conti sullo stato delle casse del Comune di Cosenza che vede imminente anche la dichiarazione dello stato di dissesto dell&#8217;ente.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Quali ripercussioni avr\u00e0 sui cittadini un&#8217;eventuale dichiarazione di dissesto finanziario? Se lo chiedono <strong>Avanti Cosenza, Buongiorno Cosenza, Cosenza in Comune per un\u2019altra idea di citt\u00e0, Cosenza socialista, Laboratorio Riformista, Oltre i colori, Italia in comune sezione 25 aprile Cosenza,<\/strong> che lanciano l&#8217;allarme e chiedono maggiore chiarezza soprattutto nei confronti dei cittadini. L\u2019esito dell\u2019udienza convocata a luglio infatti, vista la delibera n. 66\/2019 della Corte dei Conti, prospetta una situazione che vede il comune di Cosenza accumulare nuovo deficit e potrebbero essere i cittadini a dover &#8216;pagare&#8217;. E le associazioni considerano &#8220;lo stato di dissesto alla pari di un evento catastrofico per l\u2019economia della citt\u00e0 rispetto a cui le categorie professionali, gli imprenditori, le associazioni sindacali e tutti i cittadini vanno adeguatamente informati. Ne valutiamo con estrema preoccupazione i pesanti effetti sulle categorie sociali pi\u00f9 deboli&#8221;.<\/p>\n<p>A rischio ci sarebbero anche servizi molto importanti per le famiglie cosentine come quelli relativi ad asili nido e mense scolastiche. Nel frattempo \u00e8 stata convocata per <strong>luned\u00ec prossimo 24 giugno, alle ore 11, nella Sala CONI di Piazza Matteotti<\/strong>, una conferenza stampa incentrata sul tema: Stato di dissesto comune di Cosenza: previsioni e scenari per i cittadini.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Preoccupa il provvedimento della Corte dei Conti sullo stato delle casse del Comune di Cosenza che vede imminente anche la dichiarazione dello stato di dissesto dell&#8217;ente.<\/p>\n","protected":false},"author":42,"featured_media":111535,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-111534","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/111534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=111534"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/111534\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/111535"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=111534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=111534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=111534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}