{"id":111732,"date":"2019-06-24T14:29:16","date_gmt":"2019-06-24T12:29:16","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/rende-nuovi-interventi-derattizzazione-e-disinfestazione-le-zone-interessate\/"},"modified":"2023-01-16T18:29:35","modified_gmt":"2023-01-16T17:29:35","slug":"299987-rende-nuovi-interventi-derattizzazione-e-disinfestazione-le-zone-interessate","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/299987-rende-nuovi-interventi-derattizzazione-e-disinfestazione-le-zone-interessate\/","title":{"rendered":"Rende, nuovi interventi di derattizzazione e disinfestazione. Le zone interessate"},"content":{"rendered":"<h4>L\u2019amministrazione comunale di Rende comunica che da mercoled\u00ec 26 giugno a venerd\u00ec 28 giugno saranno interessate nuove zone nella disinfestazione e derattizzazione programmata nel periodo estivo. Ecco le aree interessate<\/h4>\n<p><!--more--><\/p>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>RENDE &#8211; Dopo l&#8217;intervento nei giorni scorsi, il Comune di Rende effettuer\u00e0 una nuova operazione di\u00a0disinfestazione <em>lotta alle alate\u00a0<\/em>in programma <strong>mercoled\u00ec 26, gioved\u00ec 27 e venerd\u00ec 28 giugno<\/strong>. Ecco nel dettaglio <strong>le nuove zone interessate dall&#8217;intervento<\/strong>.<\/p>\n<p><strong>1 &#8211; Mercoled\u00ec 26 giugno dalle ore 24:00 in poi<\/strong>: Via Torino, Via Cosenza, Via Bari, Via Napoli, Via Catanzaro, Via Firenze, Via Kennedy, Via Busento, Via Crati, Via Valle Del Neto, Via Pertini, Via Brodolini, Via Allende, Via Della Resistenza, Via Cavour, Via Fratelli Bandiera, Via Don Minzoni, Via Ciro Menotti, Via Morelli, Via Mameli, Via Principe<\/p>\n<p><strong>2 &#8211; Gioved\u00ec 27 giugno dalle ore 23:00 in poi<\/strong>: S. Ianni, Contrada Forge Vecchie, Via della Piagentina, Contrada Malvitani, Ponte della Canaletta, Via Alessandro Manzoni, Via Molinaro, Via G. Parini, Via Palladio, Via Campana, Via De Chirico e varie traverse, Contrada Failla, Via Modigliani, Via Botticelli, Sant&#8217;Agostino<\/p>\n<p><strong>3 &#8211; Venerd\u00ec 28 giugno dalle ore 24:00 in poi<\/strong>: Via Verdi, Via Cilea, Via Mascagni, Via Puccini, Residenze Universitarie Palazzo &#8220;Nervoso&#8221;, Via Cimarosa, Via Alessandro Volta, Via Galilei, Piazza Santo Sergio, Via Galvani, Via Leondardo Da Vinci, Via Meucci, Via Edison, Via Marconi, Via Saviano e zona UNICAL, Via Vespasiano Gonzaga<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019amministrazione comunale di Rende comunica che da mercoled\u00ec 26 giugno a venerd\u00ec 28 giugno saranno interessate nuove zone nella disinfestazione e derattizzazione programmata nel periodo estivo. Ecco le aree interessate<\/p>\n","protected":false},"author":46,"featured_media":111733,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[44],"tags":[],"class_list":["post-111732","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/111732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=111732"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/111732\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/111733"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=111732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=111732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=111732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}