{"id":111754,"date":"2019-06-24T19:41:44","date_gmt":"2019-06-24T17:41:44","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/lamezia-inchiesta-su-aeroporto-15-imputati-a-giudizio\/"},"modified":"2023-01-16T18:29:36","modified_gmt":"2023-01-16T17:29:36","slug":"300060-lamezia-inchiesta-su-aeroporto-15-imputati-a-giudizio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/300060-lamezia-inchiesta-su-aeroporto-15-imputati-a-giudizio\/","title":{"rendered":"Lamezia, inchiesta su aeroporto: 15 imputati a giudizio"},"content":{"rendered":"<h4>Quindici imputati a processo, due prosciolti e tre ammessi al rito abbreviato: \u00e8 questa la decisione del gup di Lamezia Terme Rossella Prignani, per presunte irregolarit\u00e0 nella conduzione della Sacal<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>LAMEZIA TERME (CZ) &#8211; La societ\u00e0 di gestione dello scalo lametino e, adesso, anche degli altri aeroporti calabresi. Il processo \u00e8 stato fissato per il 24 settembre prossimo davanti al Tribunale. Sono stati rinviati a giudizio i componenti del Consiglio di amministrazione della Sacal in carica nel 2017 fra i quali l&#8217;allora presidente, l&#8217;imprenditore catanzarese Massimo Colosimo, l&#8217;ex direttore generale Pierluigi Mancuso, l&#8217;ex presidente della Provincia di Catanzaro Enzo Bruno, l&#8217;imprenditore catanzarese Floriano Noto, l&#8217;ex vicepresidente Gianpaolo Bevilacqua.<\/p>\n<p>A processo anche il dipendente Enav Vincenzo Bruno Scalzo, il dirigente regionale Giuseppe Mancini, il funzionario della Provincia Floriano Siniscalco, l&#8217;allora vice sindaco di San Mango d&#8217;Aquino Pasquale Torquato, le dipendenti Sacal Sabina Mileto ed Ester Michienzi, la direttrice del centro per l&#8217;impiego di Lamezia Angelina Astorino, il maresciallo dei carabinieri Marcello Mendicino, l&#8217;ex direttore generale Pasquale Cleric\u00f2, e Giuseppe Vincenzo Mancuso. Stralciata, per difetti di notifica, la posizione dell&#8217;imprenditore lametino Emanuele Ion\u00e0. Gli imputati sono accusati, a vario titolo, di corruzione, peculato, falso, abuso d&#8217;ufficio e concussione. Sono stati prosciolti Ferdinando Saracco e Luigi Silipo. Il processo proseguir\u00e0 domani per i tre imputati che hanno scelto il rito abbreviato, l&#8217;ex sindaco di Lamezia Paolo Mascaro, il dipendente Sacal Francesco Buffone e l&#8217;imprenditore catanzarese Giuseppe Gatto in qualit\u00e0 di consigliere di amministrazione. Al centro dell&#8217;inchiesta condotta dalla Guardia di finanza e della Polizia di frontiera presunte irregolarit\u00e0 nella gestione delle assunzioni con un&#8217;applicazione irregolare del progetto &#8220;Garanzia giovani&#8221;, finanziato con fondi pubblici.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quindici imputati a processo, due prosciolti e tre ammessi al rito abbreviato: \u00e8 questa la decisione del gup di Lamezia Terme Rossella Prignani, per presunte irregolarit\u00e0 nella conduzione della Sacal<\/p>\n","protected":false},"author":44,"featured_media":111755,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-111754","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/111754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=111754"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/111754\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/111755"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=111754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=111754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=111754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}