{"id":111756,"date":"2019-06-24T22:53:41","date_gmt":"2019-06-24T20:53:41","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/operazione-willy-accuse-ribaltate-imputati-assolti-in-appello\/"},"modified":"2023-01-16T18:29:36","modified_gmt":"2023-01-16T17:29:36","slug":"300063-operazione-willy-accuse-ribaltate-imputati-assolti-in-appello","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/300063-operazione-willy-accuse-ribaltate-imputati-assolti-in-appello\/","title":{"rendered":"Operazione Willy, accuse ribaltate: imputati assolti in appello"},"content":{"rendered":"<h4>Su di loro pendeva la grave accusa di avere incendiato un&#8217;auto e per questo condannati in primo grado a quasi quattro anni di carcere. A scagionarli le indagini della difesa<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>ROGLIANO (CS) &#8211; La Corte di Appello di Catanzaro, presieduta dal Presidente Bianchi, ha ribaltato le accuse nei confronti di due persone di Rogliano \u2013 O.R.J. e P.G. \u2013 che il 2 maggio 2016 erano state arrestate nell\u2019ambito dell&#8217;operazione Willy operazione condotta dai carabinieri di Rogliano, in forza della quale il Gip di Cosenza Branda aveva emesso diverse ordinanze di custodia cautelare in carcere nei confronti di varie persone tra Rogliano e Cosenza,\u00a0 in relazione a numerosi episodi di detenzione illecita e spaccio di sostanze stupefacenti.<\/p>\n<p>Per i due roglianesi \u2013 difesi entrambi dall\u2019Avvocato Antonella Rizzuto del Foro di Cosenza &#8211; pendeva anche <strong>la grave accusa di avere incendiato, nella notte del 1\u00b0 luglio 2013, l\u2019autovettura di propriet\u00e0 di N.F<\/strong>., che, per tale motivo, si era costituito parte civile in giudizio al fine di ottenere il risarcimento dei danni dallo stesso patiti.<\/p>\n<p>Dopo una incessante istruttoria dibattimentale, sia pure ridimensionate diverse accuse in materia di stupefacenti, gli stessi erano stati <strong>condannati dal Tribunale di Cosenza Ianni, rispettivamente alla pena di 3 anni di reclusione il primo e 3 anni e 8 mesi di reclusione il secondo, nonch\u00e9, con specifico riferimento all\u2019accusa di incendio<\/strong>, riqualificato nel delitto di danneggiamento seguito da incendio, anche al pagamento in solido di una provvisionale di 5000 euro immediatamente esecutiva in favore della persona offesa costituitasi parte civile, motivo per cui gli stessi si erano visti subito recapitare un decreto ingiuntivo per provvedere al pagamento delle spese di risarcimento.<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_300064\" style=\"width: 313px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-300064\" class=\"wp-image-300064\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/06\/4e5dbc59-a706-452a-bfab-8059a32fe36d.jpg\" alt=\"\" width=\"303\" height=\"404\" title=\"\"><p id=\"caption-attachment-300064\" class=\"wp-caption-text\">L&#8217;avvocato penalista Antonella Rizzuto<\/p><\/div>\n<p>&nbsp;<\/p>\n<p>Oggi la Corte di Appello ha notevolmente <strong>ridotto la pena comminata in primo grado ai due imputati<\/strong>, nonostante il parere contrario duramente espresso dal Procuratore Generale rappresentato Salvatore di Maio, concedendo ad entrambi <strong>il beneficio della sospensione condizionale della pena in relazione solo a residue contestazioni in materia di detenzione illecita di sostanze stupefacenti e assolvendoli invece per altre con la formula perch\u00e9 il fatto non sussiste.<\/strong><\/p>\n<p><strong>Diversamente, gli stessi sono stati assolti dalla grave accusa di danneggiamento seguito da incendio, per non aver commesso il fatto, con conseguente revoca delle statuizioni civili della sentenza appellata.<\/strong><\/p>\n<p>Gi\u00e0 nei motivi di appello <strong>l\u2019Avvocato Antonella Rizzuto<\/strong> aveva evidenziato con forza come ci si trovasse dinanzi a un processo che ben avrebbe potuto e dovuto avere un esito diverso &#8211; sia in punto di responsabilit\u00e0 degli imputati, sia e non di meno in punto di trattamento sanzionatorio &#8211; se solo si fosse tenuto conto di <strong>tutte le circostanze emerse nel dibattimento<\/strong>; circostanze che, in pi\u00f9 di un\u2019occasione, avevano dimostrato non solo la fallacia delle indagini, ma, ancor di pi\u00f9, un <em>modus operandi<\/em> \u2013 quale quello adoperato dai militari &#8211; non proprio corretto e, in quanto tale, meritevole di essere censurato o, comunque, capace di insinuare ragionevoli dubbi dinanzi ai quali alcuna condanna pu\u00f2 essere pronunciata.<\/p>\n<p>La Corte ha cos\u00ec accolto le argomentazioni difensive puntualmente ribadite in udienza, le quali hanno dimostrato l\u2019estraneit\u00e0 degli imputati in ordine al grave fatto illecito agli stessi contestato,\u00a0 nonostante le intercettazioni effettuate e il servizio di geolocalizzazione alle stesse associato, che invece per il Tribunale di Cosenza avevano rappresentato la principale fonte di prova offerta dall\u2019Accusa.<\/p>\n<p>Nel collegio difensivo compaiono anche gli avvocati Pasquale Vaccaro difensore di M.I. condannata in primo grado a 1 anno di reclusione con pena sospesa, la cui pena in appello \u00e8 stata ridotta a soli 4 mesi e Antonio Aloe del Foro di Cosenza difensore di C.S., che in primo grado era stato assolto e per il quale il Pubblico Ministero aveva proposto appello, rigettato oggi stesso dalla Corte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Su di loro pendeva la grave accusa di avere incendiato un&#8217;auto e per questo condannati in primo grado a quasi quattro anni di carcere. A scagionarli le indagini della difesa<\/p>\n","protected":false},"author":37,"featured_media":111757,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42,28],"tags":[],"class_list":["post-111756","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/111756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=111756"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/111756\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/111757"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=111756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=111756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=111756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}