{"id":111835,"date":"2019-06-26T13:56:13","date_gmt":"2019-06-26T11:56:13","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosenza-progetto-safe-point-nel-centro-storico-un-ambulatorio-della-croce-rossa\/"},"modified":"2023-01-16T18:29:41","modified_gmt":"2023-01-16T17:29:41","slug":"300293-cosenza-progetto-safe-point-nel-centro-storico-un-ambulatorio-della-croce-rossa","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/300293-cosenza-progetto-safe-point-nel-centro-storico-un-ambulatorio-della-croce-rossa\/","title":{"rendered":"Cosenza: progetto &#8220;Safe Point&#8221;. Nel centro storico un ambulatorio della Croce Rossa"},"content":{"rendered":"<h4>La Croce Rossa a Palazzo Caselli-Vaccaro nel centro storico per il progetto &#8220;Centro storico-Safe Point, uno spazio sicuro&#8221;. Firmata a Palazzo dei Bruzi la convenzione. Sar\u00e0 attivato un ambulatorio, un punto per la distribuzione di farmaci gratuiti e viveri, un centro d&#8217;ascolto <strong>e supporto psicosociale<\/strong><\/h4>\n<p><!--more--><\/p>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>COSENZA &#8211; Firmata a Palazzo dei Bruzi, <strong>tra il Comune e il Comitato di Cosenza della Croce Rossa<\/strong>, una convenzione in virt\u00f9 della quale l&#8217;Amministrazione comunale <strong>concede in uso temporaneo e a titolo gratuito<\/strong>, una <strong>porzione d&#8217;immobile al piano terra di Palazzo Caselli Vaccaro di via Giostra Vecchia<\/strong>. Nei locali concessi dal Comune, la Croce Rossa attuer\u00e0 il<strong> progetto \u201cCentro storico-Safe Point, uno spazio sicuro<\/strong>\u201d, garantendo <strong>una serie di servizi ai cittadini, soprattutto agli anziani residenti nel centro storico, alle famiglie indigenti e ai minori.<\/strong><\/p>\n<h4>Ambulatorio, centro d&#8217;ascolto e distribuzione farmaci<\/h4>\n<p>Tra i punti previsti dalla convenzione c&#8217;\u00e8 l&#8217;att<strong>ivazione di un&#8217;ambulatorio-infermeria<\/strong> gestito dalle infermiere volontarie, come punto sanitario per il <strong>controllo della pressione arteriosa e della glicemia<\/strong>, con eventuale possibilit\u00e0 di <strong>prenotare una visita con medico specialistico<\/strong> e beneficiare di eventuale <strong>assistenza con erogazione di farmaci gratuiti<\/strong> (donati dal Banco farmaceutico). Sar\u00e0, inoltre, svolta <strong>attivit\u00e0 di socializzazione per i minori e data assistenza alle famiglie indigenti<\/strong>.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/7406\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-72305\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2016\/01\/croce-rossa-ital\u00f2iana-599x400.jpg\" alt=\"\" width=\"541\" height=\"361\" title=\"\"><\/a><\/p>\n<h4>Distribuzione di viveri e centro d&#8217;ascolto<\/h4>\n<p>Il <strong>Safe Point della Croce Rossa<\/strong> nel centro storico funger\u00e0 anche da <strong>punto di distribuzione per viveri alle famiglie e ai singoli in stato di difficolt\u00e0<\/strong>, per come previsto dal Banco Alimentare, ma anche da<strong> punto di orientamento ai servizi del territorio per gli indigenti<\/strong> e da <strong>centro di ascolto e supporto psicosociale<\/strong>.<br \/>\nPer la corretta attuazione della convenzione, la Croce Rossa metter\u00e0 a disposizione figure professionali che presteranno la loro attivit\u00e0 gratuitamente. <strong>La concessione avr\u00e0 la durata di un anno e potr\u00e0 essere prorogata su richiesta scritta<\/strong>. Alla firma della convenzione erano presenti, per il Comune, il Sindaco Mario Occhiuto e l&#8217;Assessore alla crescita economica urbana e alle attivit\u00e0 economiche e produttive Loredana Pastore, per la Croce Rossa, il Presidente del Comitato di Cosenza, dottor Antonio Schettini.\u00a0 Tanto il Sindaco Occhiuto quanto l&#8217;Assessore Pastore hanno espresso soddisfazione per l&#8217;intesa con il Comitato di Cosenza della Croce Rossa, perch\u00e9 consente di<strong> fare rete con il mondo del volontariato<\/strong> per affrontare in maniera partecipata i bisogni sociali della citt\u00e0 e soprattutto del centro storico.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Croce Rossa a Palazzo Caselli-Vaccaro nel centro storico per il progetto &#8220;Centro storico-Safe Point, uno spazio sicuro&#8221;. Firmata a Palazzo dei Bruzi la convenzione. Sar\u00e0 attivato un ambulatorio, un punto per la distribuzione di farmaci gratuiti e viveri, un centro d&#8217;ascolto e supporto psicosociale<\/p>\n","protected":false},"author":34,"featured_media":111836,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-111835","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/111835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=111835"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/111835\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/111836"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=111835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=111835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=111835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}