{"id":112133,"date":"2019-07-01T19:19:20","date_gmt":"2019-07-01T17:19:20","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/sanita-calabria-si-e-dimesso-subcommissario-calabria-thomas-schael\/"},"modified":"2023-01-16T18:30:02","modified_gmt":"2023-01-16T17:30:02","slug":"301318-sanita-calabria-si-e-dimesso-subcommissario-calabria-thomas-schael","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/301318-sanita-calabria-si-e-dimesso-subcommissario-calabria-thomas-schael\/","title":{"rendered":"Sanit\u00e0 Calabria: si \u00e8 dimesso subcommissario Calabria Thomas Schael"},"content":{"rendered":"<h4>Ad annunciarlo in un comunicato stampa il ministro della salute Giulia Grillo che gi\u00e0 annuncia la prossima nomina<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>ROMA &#8211; &#8220;Ho ricevuto nelle scorse ore le dimissioni di Thomas Schael, per ragioni personali, dall&#8217;incarico di subcommissario per l&#8217;attuazione del piano di rientro sanitario in Calabria&#8221;. Lo rende noto, in un comunicato, il ministro della Salute Giulia Grillo. &#8220;Ringrazio il dottor Schael per tutto il lavoro svolto fin qui. Andremo avanti con impegno e determinazione per la riorganizzazione della sanit\u00e0 calabrese e nei prossimi giorni &#8211; conclude Grillo &#8211; nomineremo il nuovo subcommissario&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ad annunciarlo in un comunicato stampa il ministro della salute Giulia Grillo che gi\u00e0 annuncia la prossima nomina<\/p>\n","protected":false},"author":44,"featured_media":112134,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-112133","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/112133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=112133"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/112133\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/112134"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=112133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=112133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=112133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}