{"id":112371,"date":"2019-07-05T09:35:39","date_gmt":"2019-07-05T07:35:39","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/amaco-in-commissione-trasporti-confronto-tra-sindacati-e-amministratore-unico2\/"},"modified":"2023-01-16T18:30:18","modified_gmt":"2023-01-16T17:30:18","slug":"302067-amaco-in-commissione-trasporti-confronto-tra-sindacati-e-amministratore-unico2","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/302067-amaco-in-commissione-trasporti-confronto-tra-sindacati-e-amministratore-unico2\/","title":{"rendered":"Amaco: in Commissione trasporti confronto tra sindacati e Amministratore Unico"},"content":{"rendered":"<h4>Le questioni dell&#8217;Amaco, che nelle scorse settimane avevano agitato i lavoratori e le sigle sindacali, sono state affrontate nel corso di una riunione della Commissione trasporti di Palazzo dei Bruzi<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; La commissione, presieduta dal consigliere comunale Gisberto Spadafora ha visto la partecipazione anche dell&#8217;Assessore alla mobilit\u00e0 sostenibile Michelangelo Spataro ed ha affrontato le problematiche sollevate dalle sigle sindacali ed in particolare dalla Uil trasporti e dalla Filt CGIL, riguardanti le indennit\u00e0 accessorie che non erano state ancora corrisposte da Amaco, la cessione del quinto dello stipendio ed il transito di dipendenti nella nuova societ\u00e0 ASMC (Azienda dei servizi per la mobilit\u00e0 di Cosenza) e il successivo distacco nuovamente in Amaco.<\/p>\n<p>La seduta \u00e8 stata introdotta dal Presidente Gisberto Spadafora che ha auspicato un <strong>confronto costruttivo<\/strong> tra le parti volto a far tornare il sereno in azienda. Spadafora ha registrato <em>\u201cil forte impegno dell&#8217;Amministratore Unico Posteraro, considerate le difficolt\u00e0 oggettive ed importanti dell&#8217;azienda ed ha esortato a trovare un punto d&#8217;incontro per il buon andamento dell&#8217;Amaco e la salvaguardia dei lavoratori. C&#8217;\u00e8 chi <\/em>\u2013 ha aggiunto il Presidente della Commissione trasporti \u2013<em> non perde occasione per denigrare l&#8217;azione dell&#8217;Amministrazione comunale, ma il nostro impegno, anche rispetto alle questioni che attengono al trasporto pubblico locale, \u00e8 massimo e continuer\u00e0 ad essere tale senza cedimenti alle polemiche pretestuose\u201d.<\/em><\/p>\n<p>L&#8217;Amministratore Unico di Amaco, <strong>Paolo Posteraro<\/strong> ha risposto alle osservazioni dei sindacati sottolineando, rispetto alla <strong>cessione dei quinti dello stipendio<\/strong> che l&#8217;impegno che aveva preso personalmente, e cio\u00e8 quello di mettersi in regola, non appena la Regione avesse riconosciuto i rimborsi per i contratti collettivi, per l&#8217;annualit\u00e0 2018, \u00e8 stato ampiamente rispettato: <em>\u201cLa Regione \u2013 <\/em>ha detto Posteraro <em>&#8211; ha pagato il 28 giugno il 90% e noi abbiamo pagato il 100% delle cessioni dei quinti\u201d. <\/em>Anche sul fronte dei <strong>buoni pasto<\/strong>, Posteraro ha rassicurato i sindacati:<em> \u201cabbiamo fatto un bonifico alla societ\u00e0 che li eroga e stiamo aspettando che sblocchino la posizione\u201d.<\/em><\/p>\n<p><strong>Sulla spesa, l&#8217;Amministratore Unico di Amaco<\/strong> \u00e8 stato circostanziato fornendo i dati relativi al 2018: <em>\u201cspendiamo per il personale circa 6 milioni e 800 mila euro -ha detto, mentre la Regione, per i rimborsi dei contratti collettivi, dovrebbe versarci circa 720 mila euro, pi\u00f9 del 10%. Noi abbiamo fatto fronte per tutto il 2018 e per i primi sei mesi del 2019 a tutti gli impegni, nonostante mancasse l&#8217;11% di quel che dovevamo percepire. La coperta, naturalmente, se si tira da una parte, \u00e8 corta dall&#8217;altra. Potevamo non versare la tredicesima o saltare, ad esempio, una annualit\u00e0 di stipendio, ma abbiamo preferito garantire le retribuzioni nette ai dipendenti. Nonostante le inadempienze da parte della Regione, siamo, purtroppo, andati in ritardo con le cessioni dei quinti o con i ticket&#8221;.<\/em><\/p>\n<p>Sul <strong>transito dei dipendenti da Amaco ad ASMC, Posteraro <\/strong>ha spiegato:<em> \u201cavevo assicurato che nessun dipendente sarebbe stato costretto a transitare in AMSC e cos\u00ec nessun dipendente \u00e8 stato costretto. Ci sono dei dipendenti, per\u00f2, che di loro iniziativa hanno chiesto di transitare e sono stati accontentati\u201d.<\/em><\/p>\n<p>Su un ultimo punto sollevato dalle sigle sindacali, in un documento che era stato presentato alla commissione trasporti, e cio\u00e8 la costituzione delle reti di impresa, ha aggiunto: <em>\u201cl&#8217;Amaco ha proceduto alla costituzione di due reti di impresa, una con la partecipata ASMC, volta a razionalizzare l&#8217;impiego del personale, e l&#8217;altra con il Consorzio Autolinee, al fine di migliorare i servizi prestati all&#8217;utenza dell&#8217;area urbana\u201d<\/em>. E i sindacati hanno lamentato che su questo punto non c&#8217;era stata una discussione.<\/p>\n<p><em>\u201cLo Statuto dell&#8217;Amaco &#8211; ha aggiunto Posteraro &#8211; attribuisce all&#8217;Amministratore unico i pi\u00f9 ampi poteri di ordinaria e straordinaria amministrazione. Nonostante questo, abbiamo, oltre a chiedere il via libera agli organi di controllo, per entrambe le reti di impresa, chiesto l&#8217;autorizzazione del Sindaco di Cosenza in qualit\u00e0 di socio\u201d.<\/em><\/p>\n<p>Paolo Posteraro ha nel corso della commissione allontanato qualsiasi preoccupazione: \u201c<em>Il contratto di rete\u00a0 non modifica lo status della societ\u00e0, n\u00e9 la compagine e i suoi rapporti giuridici, attivi e passivi. E&#8217; un banalissimo contratto di diritto privato, tra Amaco e il Consorzio, e tra Amaco e ASMC, che l&#8217;azienda ha sottoscritto praticamente a costo zero. Con ASMC \u00e8 stato sottoscritto per migliorare la gestione del personale e delle infrastrutture che possediamo, con il Consorzio l&#8217;obiettivo \u00e8 molto pi\u00f9 semplice. Nel momento in cui ci avviamo verso la citt\u00e0 unica, potremmo pagare lo scotto di avere due trasporti pubblici differenti. Per superare questo problema, abbiamo intrattenuto una fitta corrispondenza <strong>con Ferrovie della Calabria<\/strong>, ma quando ci siamo resi conto che l&#8217;integrazione con Ferrovie, che non \u00e8 impossibile, \u00e8 rimasta in una situazione di stallo, si \u00e8 cercata l&#8217;unica soluzione alternativa e cio\u00e8 con l&#8217;unico gestore privato che ha linee che combaciano con le nostre e che vanno a <strong>Rende, all&#8217;Unical e a Castrolibero, e cio\u00e8 il Consorzio Autolinee<\/strong>. Questo non comporta n\u00e9 costi, n\u00e9 mutazione della situazione societaria, n\u00e9 trasferimento di dipendenti. In prospettiva, dovrebbe, invece, portare ad un piano di esercizio che sia congiunto e che elimini gli sprechi e i raddoppi di linea, andando a vantaggio dell&#8217;utenza e della societ\u00e0 stesse. Sar\u00e0 tutto pi\u00f9 razionale senza che Amaco ci rimetta un solo euro\u201d.<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-237965 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/09\/amaco.png\" alt=\"\" width=\"436\" height=\"346\" title=\"\"><\/p>\n<h3>La parola ai sindacati<\/h3>\n<p>Dopo Posteraro hanno preso la parola alcuni dei sindacalisti presenti. Per <strong>Mario Litrenta, segretario di Uil trasporti<\/strong> <em>\u201cla verit\u00e0 non sta nelle parole dell&#8217;Amministratore unico, perch\u00e9 l&#8217;Amaco per 3 o 4 anni consecutivi ha chiuso il bilancio in negativo, mentre quest&#8217;anno Posteraro dice che lo ha chiuso con un attivo di 30 mila euro. Ma 30 mila euro \u2013 ha detto ancora Litrenta &#8211; non bastano neanche a pagare le quote sindacali che l&#8217;azienda si trattiene e non versa da due anni e mezzo a questa parte. L&#8217;azienda dovrebbe contattare periodicamente le RSA e dovrebbe avere un atteggiamento pi\u00f9 trasparente ed aperto\u201d.<\/em><\/p>\n<p>Il segretario della <strong>Filt Cisl, Mandoliti<\/strong> ha poi esternato alcune preoccupazioni per la salvaguardia dei livelli occupazionali: <em>\u201cBisogna avere davanti la prospettiva di cercare di salvare il salvabile e varare la piattaforma contrattuale con l&#8217;azienda che metteremo alla votazione del personale. Occorre adoperarsi per il rilancio dell&#8217;azienda\u201d. <\/em><\/p>\n<p>E&#8217; stata poi la volta dei <strong>consiglieri Piercarlo Chiappetta, Luca Gervasi e Giuseppe D&#8217;Ippolito: <\/strong><em>\u201cFaccio politica secondo la mia coscienza \u2013 ha detto Chiappetta &#8211; e quando vedo qualcosa che non mi quadra, io non taccio, parlo. Non entro nel merito delle richieste dei sindacati, per\u00f2 devo esternare alcune mie perplessit\u00e0 personali\u201d.<\/em><\/p>\n<p>Le perplessit\u00e0 di Chiappetta si appuntano soprattutto sul dialogo avviato con il Consorzio Autolinee<em> \u201cche \u2013 ha detto \u2013 all&#8217;epoca del Bin bus per l&#8217;Universit\u00e0 ha fatto le barricate. E&#8217; chiaro che oggi <\/em>\u2013 ha aggiunto &#8211;<em> mi meraviglio quando vedo che stiamo costruendo un rapporto con il Consorzio autolinee e non con chi avrebbe meglio dialogato con noi. Il pericolo che noi corriamo \u00e8 che questa societ\u00e0 possa utilizzare le sue risorse economiche e patrimoniali per farsi forte sulla nostra azienda\u201d.<\/em> E Chiappetta si \u00e8 detto favorevole a riavviare l&#8217;interlocuzione con Ferrovie della Calabria, alla luce del fatto che \u00e8 stato nominato da poco un nuovo management.<\/p>\n<p>Da Luca Gervasi \u00e8 venuta, all&#8217;indirizzo dell&#8217;Amministratore Unico Paolo Posteraro solo una domanda: <em>\u201cquanti debiti ha l&#8217;Amaco e come possono essere recuperati?\u201d<\/em> pronta la risposta del numero uno dell&#8217;Amaco:<em> \u201cI debiti di Amaco sono indicati nel bilancio che \u00e8 pubblico e che chiunque pu\u00f2 consultare. Una parte dei debiti sono non scaduti e non lo saranno a breve scadenza (come i TFR), altri debiti li abbiamo nei confronti dell&#8217;erario, mentre tra i debiti gi\u00e0 scaduti ci sono quelli verso i fornitori. Il resto sono debiti nei confronti degli enti di previdenza\u201d.<\/em>E <strong>Posteraro ha indicato tre modi per recuperarli<\/strong>:<em> \u201cnon generando nuovi debiti e lo abbiamo fatto chiudendo il bilancio in utile, pagare il pregresso con l&#8217;avanzo di cassa e incassare i crediti incagliati. In questa direzione abbiamo incassato un milione e mezzo dalla Regione e 800 mila euro dal Comune&#8221;.<\/em><\/p>\n<p>Per il consigliere <strong>Giuseppe D&#8217;Ippolito<\/strong> <em>\u201c\u00e8 importante invitare le sigle sindacali a trovare una possibilit\u00e0 di interlocuzione con l&#8217;azienda, ai fini del suo rilancio. Spero che il ritorno operativo dell&#8217;Assessore Spataro possa ricondurre la discussione nell&#8217;alveo politico. Dobbiamo valutare le possibilit\u00e0 di crescita dell&#8217;azienda e, ovviamente, la sua sopravvivenza che deve essere per tutti una sorta di stella polare\u201d.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Le conclusioni sono state tratte dall&#8217;Assessore Michelangelo Spataro:\u00a0<\/strong><em>\u201cL&#8217;Amaco \u00e8 un&#8217;azienda alla quale teniamo molto. Da oggi in poi, l&#8217;Amaco, attraverso la sua societ\u00e0, pu\u00f2 stringere accordi con l&#8217;Amministrazione ed avere in house affidamenti che altrimenti sarebbero dovuti andare a gara. Con molta tranquillit\u00e0, ho assistito in maniera diretta alle vicende e dinamiche dell&#8217;Amaco e mi meraviglio che vengano fatte delle osservazioni sul lavoro dell&#8217;Amministratore Unico. Le ristrettezze economiche sono tali per tutti. Non dimentichiamo<\/em> \u2013 ha aggiunto Spataro \u2013 i<em> 900 mila euro di tagli lineari dalla Regione. Negli ultimi anni c&#8217;\u00e8 stata un&#8217;evoluzione cos\u00ec strana da parte della Regione Calabria. Le Ferrovie della Calabria hanno avuto somme considerevoli. Ferrovie ha portato a passeggio l&#8217;Amaco per un paio di anni. L&#8217;Amaco<\/em> \u2013 ha proseguito l&#8217;Assessore Spataro <em>&#8211; \u00e8 un&#8217;azienda difficile che ha bisogno di tutte le forze in campo e tutti devono assicurare il massimo impegno. Occorre individuare un partner forte per essere competitivi sul mercato e non farsi trovare impreparati quando saranno bandite le gare. Ci vuole un progetto. Mi auguro che il futuro governatore della Calabria sappia affrontare anche questa problematica. Si deve badare a salvaguardare i livelli occupazionali e remunerare i dipendenti mensilmente\u201d.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le questioni dell&#8217;Amaco, che nelle scorse settimane avevano agitato i lavoratori e le sigle sindacali, sono state affrontate nel corso di una riunione della Commissione trasporti di Palazzo dei Bruzi<\/p>\n","protected":false},"author":42,"featured_media":112372,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-112371","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/112371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=112371"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/112371\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/112372"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=112371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=112371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=112371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}