{"id":112655,"date":"2019-07-11T11:37:25","date_gmt":"2019-07-11T09:37:25","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/regionali-a-fuscaldo-apre-il-punto-dincontro-mario-occhiuto-presidente\/"},"modified":"2023-01-16T18:30:36","modified_gmt":"2023-01-16T17:30:36","slug":"302955-regionali-a-fuscaldo-apre-il-punto-dincontro-mario-occhiuto-presidente","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/302955-regionali-a-fuscaldo-apre-il-punto-dincontro-mario-occhiuto-presidente\/","title":{"rendered":"Regionali, a Fuscaldo apre il punto d&#8217;incontro &#8220;Mario Occhiuto Presidente&#8221;"},"content":{"rendered":"<h4>Si tratta del primo punto d&#8217;incontro &#8220;Mario Occhiuto Presidente&#8221; che sar\u00e0 inaugurato domani sera nel centro tirrenico del cosentino. Sar\u00e0 lo stesso Occhiuto a tagliare il nastro<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>FUSCALDO (CS) &#8211; E&#8217; prevista per domani sera, venerd\u00ec 12 12 luglio alle ore 21,30 a Fuscaldo l&#8217;inaugurazione del primo punto d&#8217;incontro dei<strong> &#8220;comitati Mario Occhiuto presidente&#8221;.<\/strong> Si tratta di un luogo di aggregazione, ma anche di discussione e confronto sui temi legati al programma di Occhiuto presidente.<\/p>\n<p>Una scelta, quella di inaugurare un punto di incontro nella cittadina del tirreno cosentino, che non \u00e8 casuale ma \u00e8 allineata alle linee guida del <strong>programma elettorale del sindaco di Cosenza in vista delle prossime regionali e<\/strong> in particolar modo, nella scelta di <strong>valorizzare i luoghi di interesse storico della Calabria<\/strong> e dare un nuovo impulso al turismo.<\/p>\n<p>Fuscaldo infatti,\u00a0 \u00e8 una citt\u00e0 dalla tradizione ultramillenaria che unisce alle tante bellezze storico artistiche anche quelle naturali legate soprattutto al suo <strong>mare<\/strong>. Le sue origini\u00a0 risalgono al V secolo ed ospita numerosi monumenti e luoghi d&#8217;interesse, a partire dalla Chiesa Matrice che risale al 1166. Un luogo ritenuto ideale per parlare di nuovi percorsi di turismo sostenibile.<\/p>\n<p>A tagliare il nastro sar\u00e0 proprio Mario Occhiuto, che sar\u00e0 accompagnato dall&#8217;assessore alle attivit\u00e0 economiche e produttive del Comune di Cosenza, Loredana Pastore e dal consigliere comunale Gisberto Spadafora.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si tratta del primo punto d&#8217;incontro &#8220;Mario Occhiuto Presidente&#8221; che sar\u00e0 inaugurato domani sera nel centro tirrenico del cosentino. Sar\u00e0 lo stesso Occhiuto a tagliare il nastro<\/p>\n","protected":false},"author":42,"featured_media":112656,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28,576],"tags":[],"class_list":["post-112655","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","category-tirreno"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/112655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=112655"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/112655\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/112656"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=112655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=112655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=112655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}