{"id":112791,"date":"2019-07-13T16:37:26","date_gmt":"2019-07-13T14:37:26","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/san-giovanni-in-fiore-blitz-dellarma-sequestrati-oltre-700-grammi-di-droga-3-arresti\/"},"modified":"2023-01-16T18:30:45","modified_gmt":"2023-01-16T17:30:45","slug":"303355-san-giovanni-in-fiore-blitz-dellarma-sequestrati-oltre-700-grammi-di-droga-3-arresti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/303355-san-giovanni-in-fiore-blitz-dellarma-sequestrati-oltre-700-grammi-di-droga-3-arresti\/","title":{"rendered":"San Giovanni in Fiore: blitz dell&#8217;Arma sequestrati oltre 700 grammi di droga, 3 arresti"},"content":{"rendered":"<h4>Sequestrati 240 grammi di hashish, 340 grammi di marijuana, 130 grammi di cocaina, nonch\u00e9 due bilancini di precisione e la somma di 540 euro<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>Proseguono senza sosta le attivit\u00e0 di contrasto allo spaccio di sostanze stupefacenti sul territorio della provincia da parte Carabinieri del Comando Provinciale di Cosenza.<\/p>\n<p>Nell\u2019ambito di un servizio straordinario di controllo del territorio finalizzato alla repressione dei reati in materia di stupefacenti, i militari della Stazione di San Giovanni in Fiore, coordinati dal personale della Compagnia di Cosenza, hanno tratto in arresto in flagranza 3 ragazzi, di cui due cosentini in trasferta aventi 29 e 20 anni ed un san giovannese di 29 anni, sopresi con un grosso quantitativo di droga pronto per essere immesso sul mercato di quel comune.<\/p>\n<p>Nello specifico, i carabinieri operanti, insospettiti dalla presenza di un\u2019autovettura con a bordo due ragazzi mai visti prima, decidevano di seguirli ed osservare i loro movimenti, fino ad arrivare ad un magazzino dove ad attenderli vi era un noto ragazzo del posto. A questo punto, i militari notando lo strano intrattenersi nel deposito dei tre, organizzavano ed effettuavano un\u2019incursione nel corso della quale rinvenivano un grosso quantitativo di sostanze stupefacenti, quantificato in 240 gr. di \u201chashish\u201d, 340 gr. di \u201cmarijuana\u201d, parte della quale gi\u00e0 suddivisa in dosi contenute in bustine di plastica, 130 gr. di \u201ccocaina\u201d, nonch\u00e9 due bilancini di precisione e la somma di 540,00 euro, in banconota di vario taglio.<\/p>\n<p>Gli arrestati, su disposizione del Pubblico Ministero di turno presso la Procura di Cosenza informato nell\u2019immediatezza delle operazioni compiute, sono stati sottoposti al regime degli arresti domiciliari in attesa dell\u2019udienza di convalida.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-303356 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/07\/Presentazione-standard1.jpg\" alt=\"\" width=\"550\" height=\"674\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sequestrati 240 grammi di hashish, 340 grammi di marijuana, 130 grammi di cocaina, nonch\u00e9 due bilancini di precisione e la somma di 540 euro<\/p>\n","protected":false},"author":44,"featured_media":112792,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-112791","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/112791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=112791"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/112791\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/112792"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=112791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=112791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=112791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}