{"id":112807,"date":"2019-07-14T18:07:35","date_gmt":"2019-07-14T16:07:35","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/collina-in-fiamma-evacuate-abitazioni\/"},"modified":"2023-01-16T18:30:47","modified_gmt":"2023-01-16T17:30:47","slug":"303385-collina-in-fiamma-evacuate-abitazioni","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/303385-collina-in-fiamma-evacuate-abitazioni\/","title":{"rendered":"Collina in fiamme, evacuate abitazioni"},"content":{"rendered":"<h4>Un incendio divampato in una zona rurale si \u00e8 esteso fino a raggiungere il centro abitato<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>ACQUARO (VV) &#8211; Un incendio di notevoli dimensioni \u00e8 in atto in localit\u00e0 Malamotta, nel comune di Acquaro, centro delle Preserre Vibonesi. Ad andare a fuoco una delle colline a ridosso del centro abitato. Le fiamme hanno in poco tempo divorato tutta la vegetazione dell&#8217;intero costone fino a lambire le abitazioni che, nel frattempo, sono state fatte sgomberare. <strong>Numerose le segnalazioni al 115 da parte di cittadini preoccupati per le loro case<\/strong>. Le operazioni di spegnimento sono ancora in corso.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right;\">Immagine di repertorio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un incendio divampato in una zona rurale si \u00e8 esteso fino a raggiungere il centro abitato<\/p>\n","protected":false},"author":43,"featured_media":112808,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-112807","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/112807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=112807"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/112807\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/112808"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=112807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=112807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=112807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}