{"id":112809,"date":"2019-07-15T04:35:25","date_gmt":"2019-07-15T02:35:25","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/incendio-distrugge-un-deposito-di-giocattoli\/"},"modified":"2023-01-16T18:30:47","modified_gmt":"2023-01-16T17:30:47","slug":"303391-incendio-distrugge-un-deposito-di-giocattoli","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/303391-incendio-distrugge-un-deposito-di-giocattoli\/","title":{"rendered":"Incendio distrugge un deposito di giocattoli"},"content":{"rendered":"<h4>Secondo i primi accertamenti dei vigili del fuoco l&#8217;incendio si sarebbe sviluppato all&#8217;interno di un deposito di un&#8217;attivit\u00e0 commerciale di giocattoli<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>REGGIO CALABRIA &#8211; Vigili del fuoco ancora al lavoro ieri sera per un incendio divampato all\u2019interno dei locali del Toys Center in via De Nava, a Reggio Calabria per spegnere l\u2019incendio ed evitare il coinvolgimento degli edifici adiacenti, in particolare un&#8217;officina e il piano superiore che ospita l&#8217;area vendita del Toys Center. Sul posto i pompieri con due autopompe serbatoio, supportate da un&#8217;autobotte e dal carro bombole, necessario ad apportare la riserva d&#8217;aria ai vigili che sono in azione, avvolti da una coltre di fumo, ma anche le forze dell&#8217;ordine. Dopo ore di lavoro i vigili del fuoco di Reggio Calabria hanno domato le fiamme e messo in sicurezza il magazzino. Ora resta da capire se il rogo sia di natura accidentale o dolosa.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-303393 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/07\/incendio-toys-center-reggio-calabria-02.jpg\" alt=\"\" width=\"503\" height=\"329\" title=\"\"><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-303392 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/07\/incendio-toys-center-reggio-calabria-01.jpg\" alt=\"\" width=\"517\" height=\"276\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Secondo i primi accertamenti dei vigili del fuoco l&#8217;incendio si sarebbe sviluppato all&#8217;interno di un deposito di un&#8217;attivit\u00e0 commerciale di giocattoli<\/p>\n","protected":false},"author":42,"featured_media":112810,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-112809","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/112809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=112809"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/112809\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/112810"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=112809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=112809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=112809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}