{"id":113215,"date":"2019-07-22T08:55:25","date_gmt":"2019-07-22T06:55:25","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosenza-pastore-e-spadafora-non-prendiamo-lezioni-dalle-cassandre-di-turno\/"},"modified":"2023-01-16T18:31:15","modified_gmt":"2023-01-16T17:31:15","slug":"304752-cosenza-pastore-e-spadafora-non-prendiamo-lezioni-dalle-cassandre-di-turno","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/304752-cosenza-pastore-e-spadafora-non-prendiamo-lezioni-dalle-cassandre-di-turno\/","title":{"rendered":"Cosenza, Pastore e Spadafora: \u00abnon prendiamo lezioni dalle &#8220;Cassandre di turno&#8221;\u00bb"},"content":{"rendered":"<h4>Continua il botta e risposta sulla sentenza della Sezione regionale della Corte dei Conti relativa alla situazione delle casse del Comune di Cosenza. A prendere le difese del sindaco Loredana Pastore e Gisberto Spadafora<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA \u2013 L&#8217;assessore alle Attivit\u00e0 economiche e produttive della citt\u00e0 di Cosenza, <strong>Loredana Pastore<\/strong> e il consigliere comunale di Cosenza, <strong>Gisberto Spadafora<\/strong> attaccano le Cassandre che sperano nel dissesto dopo esserne state le artefici. &#8220;Leggiamo in queste ore reazioni scomposte sulla sentenza della Sezione Regionale della Corte dei Conti, quasi che qualcuno sia felice che venga dichiarato il dissesto per Palazzo dei Bruzi. Certamente non possiamo sottovalutare una vicenda cos\u00ec complessa, ma nemmeno prendere lezioni da chi ha originato la voragine nei conti del Comune&#8221;.<\/p>\n<p>&#8220;Ricordiamo &#8211; scrivono &#8211; che<strong> quando Mario Occhiuto si \u00e8 insediato nel 2011<\/strong> si \u00e8 trovato di fronte ad un bivio: o dichiarare subito il dissesto o accedere alla nuova normativa sul pre-dissesto. Si \u00e8 scelta responsabilmente questa seconda strada avviando un&#8217;opera di risanamento faticosa e resa ancora pi\u00f9 complicata dal sorgere di tanto in tanto di nuovi debiti prima occulti. <strong>Lo sforzo per il risanamento finanziario \u00e8 stato importante<\/strong> perch\u00e9 si \u00e8 cercato di garantire comunque alla Citt\u00e0 i servizi, mentre attraverso fondi europei e comunitari si rendeva Cosenza sempre pi\u00f9 attrattiva&#8221;.<\/p>\n<p>&#8220;Vista la situazione, dunque,<strong> la sentenza dei magistrati contabili calabresi era quasi scontata<\/strong>. Ma alle <strong>&#8220;Cassandre di turno&#8221;<\/strong> suggeriamo di raffreddare per il momento i loro entusiasmi perch\u00e9 il dissesto non \u00e8 stato ancora dichiarato. Un altro giudice dovr\u00e0 esprimersi e sono le Sezioni Riunite della Corte dei Conti che gi\u00e0 nel 2014 hanno ribaltato i pronunciamenti dei giudici calabresi accogliendo i rilievi del Comune. Invitiamo tutti dunque alla prudenza e soprattutto ad evitare su un tema cos\u00ec delicato la strumentalizzazione politica. Ci saranno tempi e temi su cui confrontarci politicamente ma solo chi \u00e8 a corto di argomenti pu\u00f2 tifare per un epilogo che, dimenticandolo, lui stesso ha determinato, e che sarebbe una vera iattura per la Citt\u00e0 e per i cittadini&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Continua il botta e risposta sulla sentenza della Sezione regionale della Corte dei Conti relativa alla situazione delle casse del Comune di Cosenza. A prendere le difese del sindaco Loredana Pastore e Gisberto Spadafora<\/p>\n","protected":false},"author":42,"featured_media":113216,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-113215","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/113215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=113215"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/113215\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/113216"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=113215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=113215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=113215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}