{"id":113618,"date":"2019-07-29T16:04:44","date_gmt":"2019-07-29T14:04:44","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/presunto-pusher-viaggiava-in-moto-con-a-bordo-della-cocaina\/"},"modified":"2023-01-16T18:31:42","modified_gmt":"2023-01-16T17:31:42","slug":"305841-presunto-pusher-viaggiava-in-moto-con-a-bordo-della-cocaina","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/305841-presunto-pusher-viaggiava-in-moto-con-a-bordo-della-cocaina\/","title":{"rendered":"Presunto pusher viaggiava in moto con a bordo cocaina e contanti"},"content":{"rendered":"<h4>L&#8217;uomo \u00e8 stato fermato e tratto in arresto dai carabinieri<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>CROTONE &#8211; Presunto pusher in manette. I carabinieri del Nucleo operativo e radiomobile della Compagnia di Petilia Policastro, nel Crotonese, hanno tratto in arresto un 40enne del luogo per detenzione ai fini di spaccio di sostanza stupefacente. In particolare i carabinieri, dopo aver fermato l\u2019uomo a bordo di un ciclomotore durante un controllo alla circolazione stradale, lo hanno sottoposto a perquisizione personale e veicolare, rinvenendo <strong>14 dosi di cocaina e circa tremila euro in contanti.<\/strong> La sostanza stupefacente e il denaro sono stati sequestrati.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;uomo \u00e8 stato fermato e tratto in arresto dai carabinieri<\/p>\n","protected":false},"author":43,"featured_media":113619,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[547],"class_list":["post-113618","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-droga"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/113618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=113618"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/113618\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/113619"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=113618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=113618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=113618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}