{"id":113732,"date":"2019-07-31T08:49:04","date_gmt":"2019-07-31T06:49:04","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/operazione-libri-il-senatore-magorno-si-autosospende-dal-pd\/"},"modified":"2023-01-16T18:31:50","modified_gmt":"2023-01-16T17:31:50","slug":"306063-operazione-libri-il-senatore-magorno-si-autosospende-dal-pd","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/306063-operazione-libri-il-senatore-magorno-si-autosospende-dal-pd\/","title":{"rendered":"Operazione Libri, il senatore Magorno si autosospende dal Pd"},"content":{"rendered":"<h4>&#8220;Le notizie relative all&#8217;operazione anti &#8216;ndrangheta contro il clan Libri impongono un serio intervento del Pd nazionale in Calabria&#8221;<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CATANZARO &#8211; Con queste parole il senatore Ernesto Magorno annuncia la sua temporanea sospensione dal partito Democratico.\u00a0 &#8220;Mi autosospendo dal partito fino a quando non si far\u00e0 chiarezza&#8221;. La decisione giunge in relazione agli esiti dell&#8217;operazione della Polizia di Stato contro la cosca Libri della &#8216;ndrangheta di Reggio Calabria che ha portato all&#8217;arresto, ai domiciliari, del capogruppo del Pd alla Regione Calabria Seby Romeo. &#8220;Un plauso alla magistratura e agli uomini che, in queste ore &#8211; ha aggiunto Magorno &#8211; hanno sferrato un deciso colpo alla &#8216;Ndrangheta colpendo la cosca Libri. Uniti per una Calabria migliore e quindi libera da certe logiche&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Le notizie relative all&#8217;operazione anti &#8216;ndrangheta contro il clan Libri impongono un serio intervento del Pd nazionale in Calabria&#8221;<\/p>\n","protected":false},"author":44,"featured_media":113733,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-113732","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/113732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=113732"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/113732\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/113733"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=113732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=113732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=113732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}