{"id":113752,"date":"2019-07-31T11:39:59","date_gmt":"2019-07-31T09:39:59","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/operazione-libri-tra-arrestati-ce-il-presidente-di-ance-calabria\/"},"modified":"2023-01-16T18:31:52","modified_gmt":"2023-01-16T17:31:52","slug":"306088-operazione-libri-tra-arrestati-ce-il-presidente-di-ance-calabria","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/306088-operazione-libri-tra-arrestati-ce-il-presidente-di-ance-calabria\/","title":{"rendered":"Operazione Libri: tra gli arrestati c&#8217;\u00e8 il presidente di Ance Calabria"},"content":{"rendered":"<h4>Berna, che ha 47 anni, imprenditore del settore edilizio, immobiliare e della ristorazione, con l&#8217;accusa di associazione mafiosa<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>REGGIO CALABRIA &#8211; C&#8217;\u00e8 anche Francesco Berna, presidente di Ance Calabria, l&#8217;associazione dei costruttori edili che fa capo a Confindustria, tra le persone arrestate nell&#8217;ambito dell&#8217;operazione della Polizia di Stato, coordinata dalla Dda di Reggio Calabria, contro la cosca Libri, che ha portato all&#8217;arresto di 17 persone, 12 in carcere e 5 ai domiciliari. Berna, che ha 47 anni, imprenditore del settore edilizio, immobiliare e della ristorazione, con l&#8217;accusa di associazione mafiosa. Arrestato anche il fratello Demetrio di 46 anni in passato consigliere comunale e assessore nel Comune di Reggio Calabria. Secondo quanto riferito dagli inquirenti i fratelli Berna sarebbero &#8220;diretta espressione della cosca Libri&#8221; e &#8220;in quanto tali, da un lato hanno sempre goduto della protezione dei soggetti apicali della citata consorteria di &#8216;ndrangheta, riuscendo ad avviare e far crescere in modo esponenziale le proprie attivit\u00e0 imprenditoriali, dall&#8217;altro l&#8217;hanno, a loro volta, finanziata&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berna, che ha 47 anni, imprenditore del settore edilizio, immobiliare e della ristorazione, con l&#8217;accusa di associazione mafiosa<\/p>\n","protected":false},"author":44,"featured_media":113753,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-113752","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/113752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=113752"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/113752\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/113753"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=113752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=113752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=113752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}