{"id":113758,"date":"2019-07-31T12:58:55","date_gmt":"2019-07-31T10:58:55","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/operazioni-libri-lo-stato-smantella-una-delle-cosche-piu-agguerrite-video\/"},"modified":"2023-01-16T18:31:52","modified_gmt":"2023-01-16T17:31:52","slug":"306099-operazioni-libri-lo-stato-smantella-una-delle-cosche-piu-agguerrite-video","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/306099-operazioni-libri-lo-stato-smantella-una-delle-cosche-piu-agguerrite-video\/","title":{"rendered":"Operazioni Libri, lo Stato smantella una delle cosche pi\u00f9 agguerrite (Video)"},"content":{"rendered":"<h4>L&#8217;inchiesta ha dimostrato come l&#8217;organizzazione avesse messo le mani su diversi settori economici di Reggio Calabria, attraverso il controllo di diverse societ\u00e0<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>REGGIO CALABRIA &#8211; L&#8217;operazione &#8220;Libro Nero&#8221; emesse 17 misure cautelari nei confronti di Antonino Caridi 59 anni detenuto nel carcere di Ascoli Piceno; Giuseppe Libri 61 anni; Rosa Libri 58 anni; Saverio Pellican\u00f2 58 anni; Giuseppe Putort\u00ec 52 anni; Gianpaolo Sarica 43 anni; Cristofaro Zimbato 43 anni; Giuseppe La Porta 38 anni; Antonio Presto 62 anni; Giuseppe Demetrio Tortorella 66 anni; Demetrio Berna 46 anni; Francesco Berna (presidente Ance Reggio Calabria) 47 anni; Stefano Sartiano 61 anni; Demetrio Naccari Carlizzi (consigliere regionale) 52 anni; Alessandro Nicol\u00f2 (consigliere regionale) 58 anni; Sebastiano Seby Romeo 44 anni; Francesco Romeo (Guardia di Finanza) 53 anni; Concetto Lagan\u00e0 (esponente Pd) 52 anni; Pasquale Repaci 62 anni; Antonio Zindato 32 anni<\/p>\n<p>Arresti domiciliari per <strong>Giuseppe Putort\u00ec, Demetrio Giuseppe Tortorella, Sebastiano Romeo, Francesco Romeo, Concetto Lagan\u00e0<\/strong>.<\/p>\n<p>Arresti in carcere per <strong>Antonio Caridi, giuseppe Libri, Rosa Libri, Saverio Pellican\u00f2, Gianpaolo Sarica, Giuseppe Serrano, Giuseppe La Porta, Demetrio Berna, Francesco Berna, Stefano Sartiano, Alessandro Nicol\u00f2, Antonio Zindato<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-306104\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/07\/576e4606-aa01-4aa1-9244-6797df59dc48.jpg\" alt=\"\" width=\"1600\" height=\"900\" title=\"\"><\/p>\n<h2><\/h2>\n<h2>LA CONFERENZA STAMPA<\/h2>\n<p>Tenuta una <strong>conferenza stampa<\/strong> alla presenza del capo della Dda di Reggio Calabria <strong>Giovanni Bombardieri<\/strong>, del direttore della Direzione centrale anticrimine (Dac) della Polizia, del questore di Reggio e del direttore dello Sco. \u00ab\u00c8 una operazione che sottolinea l&#8217;efficace capacit\u00e0 di risposta dello Stato contro una delle cosche di &#8216;ndrangheta tra le pi\u00f9 agguerrite d&#8217;Italia per capacit\u00e0 di infiltrare la politica e le pubbliche amministrazioni per i propri interessi criminali&#8221;. A dirlo il capo della Dda di Reggio Calabria <strong>Giovanni Bombardieri<\/strong>, nel corso della conferenza sull&#8217;operazione &#8220;Libro Nero&#8221; che ha portato all&#8217;arresto, tra gli altri, del <strong>consigliere regionale di Fratelli d&#8217;Italia Alessandro Nicol\u00f2, e ai domiciliari il capogruppo Pd in Consiglio regionale Sebastiano Romeo<\/strong>. Su Romeo &#8211; hanno detto gli inquirenti &#8211; sono in corso ulteriori indagini connesse con l&#8217;operazione &#8220;Libro Nero&#8221;.<\/p>\n<p>&#8220;Il dettaglio degli interessi criminali della cosca Libri &#8211; ha continuato Bombardieri &#8211; emerge in tutta la sua gravit\u00e0 nelle intercettazioni dentro lo studio <strong>dell&#8217;odontoiatra Giuseppe Demetrio Tortorella<\/strong>, gi\u00e0 <strong>assessore all&#8217;Urbanistica del Comune di Reggio Calabria<\/strong> negli anni &#8217;90, locale in cui si discutevano, in veri e propri summit, gli obiettivi politici della cosca, a prescindere da ogni schieramento, di centrosinistra e di centrodestra, obiettivi legati all&#8217;ottenimento di lavori pubblici, licenze amministrative, assunzioni di favore, da chiedere ai politici che erano stati sostenuti elettoralmente dalla cosca Libri. Le indagini hanno anche verificato le testimonianze rese dal <strong>collaboratore Enrico De Rosa<\/strong>, un immobiliarista a disposizione dei Libri, che ha contribuito a configurare uno scenario di valore investigativo proprio per la sua vicinanza ai vertici di comando della cosca, che si sono saldate con il lavoro della squadra mobile, coordinata dai colleghi Stefano Musolino e Walter Ignazitto&#8221;.<\/p>\n<p>&#8220;In una delle intercettazioni &#8211; ha detto ancora Bombardieri &#8211; Tortorella si vantava di avere condizionato la politica urbanistica del Comune di Reggio, promuovendo soprattutto l&#8217;area di &#8216;Cannav\u00f2&#8217;, la circoscrizione della periferia est in cui vivevano i Libri e altri indagati. Tortorella, inoltre, si lamentava del comportamento di alcuni politici che accusava di averlo abbandonato perch\u00e9 amico dell&#8217;avv. Paolo Romeo, sotto processo nell&#8217;inchiesta &#8216;Ghota&#8217;&#8221;. &#8220;<strong>I Libri<\/strong> &#8211; ha affermato Francesco Messina, direttore centrale anticrimine della Polizia di Stato &#8211; <strong>avevano esportato il loro &#8216;modello&#8217; anche in altre regioni del nord e le loro imprese di riferimento, come quella dei Berna, erano &#8216;intoccabili&#8217; perch\u00e9 ogni loro cantiere veniva &#8216;presentato&#8217; ai vari referenti dei &#8216;locale&#8217; di &#8216;ndrangheta, come &#8216;cosa appartenente ai Libri<\/strong>&#8216;.<\/p>\n<p>Con questa operazione non solo \u00e8 stata disarticolata l&#8217;ala militare della cosca Libri, ma lo Stato ha messo le mani sull&#8217;economia della cosca stessa&#8221;. Il questore Maurizio Vallone, nel suo intervento, ha parlato di &#8220;scoperta di gangli delicati della cosca Libri&#8221;, mentre il dirigente della Squadra Mobile Francesco Ratt\u00e0, ha ricordato &#8220;come spesso, alla presenza di Nicol\u00f2 e dei fratelli Berna, si discutessero di come favorire la cosca Libri nelle varie attivit\u00e0 amministrative e nell&#8217;acquisizione degli appalti&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-306105\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/07\/7f47cde4-288b-4ce5-8ad1-a7f695c295df.jpg\" alt=\"\" width=\"900\" height=\"676\" title=\"\"><\/p>\n<h2><\/h2>\n<h2>LE CENE POLITICHE VERI SUMMIT DI &#8216;NDRINA<\/h2>\n<p>\u00abLa &#8216;ndrangheta a Reggio Calabria non \u00e8 solo estorsioni con esplosivi, con minacce ma anche interazioni di cosche storiche della citt\u00e0 in ambito politico &#8211; dichiara il Procuratore capo Bombardieri ai giornalisti a fine conferenza stampa &#8211; . Questa indagine grazie all&#8217;impegno della squadra mobile della questura di Reggio Calabria, del servizio centrale operativo Sco e della Dac ha dimostrato come alla cosca Libri fossero riferibili direttamente espressioni politiche e imprenditoriali di primissimo livello che evidentemente attengono agli investimenti che in ambito imprenditoriale e politico la stessa cosca faceva. Su questo si sono soffermati in maniera specifica gli stessi collaboratori di giustizia. hanno fatto riferimento a questi soggetti come espressione della cosca Libri. In particolare un collaboratore ha proprio specificato &#8220;si scrive Libri si dice Berna&#8221; proprio per fare emergere come ci fosse un coinvolgimento diretto degli imprenditori nella cosca Libri. Un coinvolgimento che gli stessi imprenditori in un secondo momento hanno cercato di allontanare non comparendo in pubblico e cercando di tenere le distanze da questi ambienti criminali<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_306101\" style=\"width: 910px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-306101\" class=\"wp-image-306101 size-full\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/07\/bombardieri.jpg\" alt=\"\" width=\"900\" height=\"506\" title=\"\"><p id=\"caption-attachment-306101\" class=\"wp-caption-text\">il capo della Dda di Reggio Calabria Giovanni Bombardieri<\/p><\/div>\n<p>&nbsp;<\/p>\n<p>In ambiente politico un collaboratore facendo riferimento ad una di queste cene a cui ha partecipato sulla ionica reggina &#8220;<strong>pi\u00f9 che una cena elettorale sembrava un vero e proprio summit della &#8216;ndrangheta a cui partecipavano gli esponenti politici insieme ad esponenti criminali di primo livello&#8221;<\/strong>.<\/p>\n<p>Intanto occorre dire che la &#8216;ndrangheta non ha colore politico quello che emerge da questa indagine e dai commenti che alcuni indagati fanno alla luce dei risultati elettorali \u00e8 quello di dire &#8220;abbiamo vinto con Tizio, con Caio e Semprione. E l&#8217;investimento diversificato che la &#8216;ndrangheta fa per poi contare su un ritorno, indipendentemente dal risultato concreto di quella specifica elezione. Voglio precisare poi che per quanto riguarda la vicenda del politico <strong>Sebastiano Romeo<\/strong> non \u00e8 direttamente collegabile alla vicenda dei Libri. si tratta di un episodio specifico che \u00e8 emerso nel corso di questa indagine ma non ha oggetto vicinanza specifica alla costa. Per quanto riguarda <strong>Naccari<\/strong> c&#8217;\u00e8 stata una richiesta di misura cautelare che il Gip ha ritenuto di rigettare sotto il profilo della mancanza di esigenze cautelari pur ritenendo il quadro indiziario grave\u00bb<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"Operazione Dda Libri Rc\" width=\"740\" height=\"416\" src=\"https:\/\/www.youtube.com\/embed\/YkdXln7JRRs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"Operazione Dda Libri Rc 1\" width=\"740\" height=\"416\" src=\"https:\/\/www.youtube.com\/embed\/_flHBCVem7I?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;inchiesta ha dimostrato come l&#8217;organizzazione avesse messo le mani su diversi settori economici di Reggio Calabria, attraverso il controllo di diverse societ\u00e0<\/p>\n","protected":false},"author":37,"featured_media":113759,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-113758","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/113758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=113758"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/113758\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/113759"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=113758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=113758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=113758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}