{"id":113912,"date":"2019-08-02T14:34:30","date_gmt":"2019-08-02T12:34:30","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/ti-abortiremo-noi-minacce-di-morte-al-prete-che-dirige-il-giornale-cei\/"},"modified":"2023-01-16T18:32:03","modified_gmt":"2023-01-16T17:32:03","slug":"306396-ti-abortiremo-noi-minacce-di-morte-al-prete-che-dirige-il-giornale-cei","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/306396-ti-abortiremo-noi-minacce-di-morte-al-prete-che-dirige-il-giornale-cei\/","title":{"rendered":"&#8220;Ti abortiremo noi&#8221;, minacce di morte al prete che dirige il giornale della Cei"},"content":{"rendered":"<h4>La lettera minatoria \u00e8 stata recapitata nella cassetta della posta della redazione de L&#8217;Avvenire di Calabria<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>REGGIO CALABRIA\u00a0&#8211; &#8220;Tua madre doveva abortirti. Ti abortiremo noi. Prete di merda&#8221;. Questo il messaggio, firmato &#8220;Riscossa Arcobaleno&#8221;, fatto recapitare ieri mattina a don Davide Imeneo, direttore de &#8220;L&#8217;Avvenire di Calabria&#8221;, depositato all&#8217;interno della buca delle lettere della sede della redazione del giornale a Reggio Calabria. Alla base del messaggio, su cui don Davide ha presentato regolare denuncia, secondo quanto scrive stamani &#8220;Avvenire&#8221;, ci sarebbe il<strong> disappunto per un articolo pubblicato il 29 luglio scorso sul sito del giornale dal titolo &#8220;Caro Falcomat\u00e0, basta doppia morale sui diritti&#8221;.<\/strong> Un articolo, scrive Avvenire, &#8220;diretto al sindaco di Reggio Calabria Giuseppe Falcomat\u00e0 del PD, che due giorni prima, in occasione della sua presenza al Gay Pride locale, aveva postato sul suo profilo facebook delle considerazioni sull&#8217;iniziativa citando espressamente un frase di don Italo Calabr\u00f2, &#8216;padre&#8217; della Caritas diocesana reggina.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Quel &#8216;nessuno escluso&#8217; &#8211; scrive il giornale della Cei &#8211; che don Calabr\u00f2 utilizzava riferendosi agli emarginati.<\/strong> Partendo da questo spunto, quindi, la redazione de &#8216;L&#8217;Avvenire di Calabria&#8217; voleva aprire un dialogo pubblico con Falcomat\u00e0 sui diritti negati a Reggio Calabria&#8221;. Il giorno seguente, sempre stando al racconto di &#8220;Avvenire&#8221;, &#8220;gran parte dei giornali locali aveva ripreso la nota senza tradirne il significato autentico&#8221;, anche in considerazione del fatto che &#8220;nell&#8217;articolo non vi era nessuna frase discriminatoria verso le persone omosessuali, n\u00e9 sugli organizzatori del gay pride reggino. Tutti tranne l&#8217;unica testata online nazionale che si \u00e8 interessata al caso, il portale di riferimento della comunit\u00e0 Lgbt Gaynews.it che, oltre ad omettere alcune parti dell&#8217;articolo, ha voluto attaccare direttamente uno degli autori dello stesso, ossia don Davide Imeneo&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<h2>LA SOLIDARIETA&#8217;<\/h2>\n<p>&#8220;Esprimo la mia vicinanza al direttore dell&#8217;Avvenire di Calabria, don Davide Imeneo, destinatario di una missiva dai caratteri intimidatori firmata da un movimento &#8216;arcobaleno&#8217; e il cui rilievo non \u00e8 degno di nota. Ma ci troviamo dinanzi ad un episodio che offende non solo la comunit\u00e0 cattolica che nelle pagine del periodico &#8216;Avvenire&#8217; scorge una guida e un punto di riferimento al quale affidarsi, ma per l&#8217;intera collettivit\u00e0 democratica stimolata al dibattito e alla riflessione rispetto alcuni argomenti che, a mio modesto avviso, dovrebbero essere imprescindibili nella vita di ciascuno di noi&#8221;. Lo afferma, in una nota, Giuseppe Neri, segretario questore del Consiglio regionale. &#8220;L&#8217;episodio sgradevole &#8211; prosegue Neri &#8211; \u00e8 da ricollegare certamente all&#8217;editoriale di don Davide di luned\u00ec scorso, con il quale intendeva sollecitare un dibattito ed un approfondimento su alcuni temi di politica sociale, con il sindaco Giuseppe Falcomat\u00e0, a seguito della sua presenza al Gay Pride locale. Temi dal mio punto di vista, di ordinaria attualit\u00e0 e di straordinaria importanza, che <strong>non hanno neanche minimamente sfruttato frasi o insinuazioni discriminatorie verso le persone omosessuali, n\u00e9 tantomeno verso i promotori del Gay Pride reggino&#8221;<\/strong>. &#8220;L&#8217;intervento del direttore Imeneo era riferito &#8211; prosegue Neri &#8211; alla mancanza di taluni servizi minimi per giovani e &#8216;famiglie&#8217;, e per i quali si attendono posizioni sulle politiche sociali della citt\u00e0 di Reggio. Dunque un passaggio che non aveva ad oggetto un orientamento sulle diverse sessualit\u00e0 ma la necessit\u00e0 di riconoscere tutti i diritti che agevolino la vita sociale dei cittadini a prescindere da tutto&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La lettera minatoria \u00e8 stata recapitata nella cassetta della posta della redazione de L&#8217;Avvenire di Calabria<\/p>\n","protected":false},"author":43,"featured_media":113913,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-113912","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/113912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=113912"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/113912\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/113913"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=113912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=113912"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=113912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}