{"id":113936,"date":"2019-08-03T09:53:53","date_gmt":"2019-08-03T07:53:53","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/ndrangheta-e-politica-il-consigliere-del-pd-romeo-nega-le-accuse-di-corruzione\/"},"modified":"2023-01-16T18:32:04","modified_gmt":"2023-01-16T17:32:04","slug":"306441-ndrangheta-e-politica-il-consigliere-del-pd-romeo-nega-le-accuse-di-corruzione","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/306441-ndrangheta-e-politica-il-consigliere-del-pd-romeo-nega-le-accuse-di-corruzione\/","title":{"rendered":"&#8216;Ndrangheta e politica: il consigliere del PD nega le accuse di corruzione"},"content":{"rendered":"<h4>Sebi Romeo, ad ora ristretto agli arresti domiciliari, ha risposto alle domande del gip<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>REGGIO CALABRIA &#8211; Il consigliere del Pd Sebi Romeo, ai domiciliari con l&#8217;accusa di tentata corruzione nell&#8217;ambito dell&#8217;operazione &#8220;Libro Nero&#8221;, ha <strong>risposto alle domande del gip del Tribunale di Reggio Calabria Domenico Armaleo negando le accuse che gli sono state rivolte.<\/strong> Romeo, in particolare, ha escluso di avere promesso alcunch\u00e9 al maresciallo della Guardia di finanza Francesco. Il capogruppo del Pd alla Regione Calabria, ora sospeso dal partito, secondo quanto emerso dall&#8217;indagine coordinata dalla Dda di Reggio Calabria avrebbe avvicinato ed incontrato di persona il maresciallo allo scopo di rivelargli notizie riservate su attivit\u00e0 di indagine che lo riguardavano, in cambio di favori personali. Il difensore di Romeo, l&#8217;avv. Natale Polimeni, ha presentato un&#8217;istanza di revoca della misura cautelare. Romeo, arrestato contestualmente nell&#8217;inchiesta contro la cosca Libri, come ha tenuto a specificare il procuratore Giovanni Bombardieri, non ha niente a che fare con i Libri.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sebi Romeo, ad ora ristretto agli arresti domiciliari, ha risposto alle domande del gip<\/p>\n","protected":false},"author":43,"featured_media":113937,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-113936","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/113936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=113936"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/113936\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/113937"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=113936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=113936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=113936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}