{"id":113990,"date":"2019-08-04T13:38:50","date_gmt":"2019-08-04T11:38:50","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/rapinescippi-e-furti-in-serie-arrestato-presunto-autore2\/"},"modified":"2023-01-16T18:32:08","modified_gmt":"2023-01-16T17:32:08","slug":"306560-rapinescippi-e-furti-in-serie-arrestato-presunto-autore2","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/306560-rapinescippi-e-furti-in-serie-arrestato-presunto-autore2\/","title":{"rendered":"Rapine,scippi e furti in serie, arrestato presunto autore"},"content":{"rendered":"<h4>Trentacinquenne reggino sarebbe responsabile di dodici episodi. Riconosciuto grazie alle immagini della videosorveglianza<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>REGGIO CALABRIA &#8211; E&#8217; accusato di avere commesso 12 tra rapine, scippi e furti. Un trentacinquenne, C.B., \u00e8 stato arrestato dalla Polizia di Stato, a Reggio Calabria, in esecuzione di un&#8217;ordinanza emessa dal gip del Tribunale su richiesta della Procura. Dalle indagini svolte dai poliziotti \u00e8 emerso che l&#8217;uomo si \u00e8 reso responsabile di diverse azioni criminose fulminee e talvolta violente realizzate nei confronti di donne per impossessarsi di borse ed effetti personali guadagnando poi la fuga a bordo di uno scooter con il quale percorreva le strade del centro cittadino a forte velocit\u00e0, anche contromano, mettendo in serio pericolo la sicurezza dei passanti.<\/p>\n<p>L&#8217;analisi delle caratteristiche fisionomiche descritte dalle vittime nelle loro denunce ha consentito agli esperti dell&#8217;Ufficio Volanti di individuare nelle immagini presenti nei sistemi di videosorveglianza pubblici e privati esistenti in citt\u00e0, la persona sospettata poi riconosciuta dalle vittime. Successivamente si \u00e8 provveduto a tentare di dare un nome al volto individuato grazie al confronto delle immagini con le fotografie di tutti i soggetti gi\u00e0 indagati per reati analoghi. Acquisita la somiglianza con una persona detenuta agli arresti domiciliari si \u00e8 proceduto al monitoraggio dei suoi spostamenti, effettuati con evasione dalla misura. In due circostanze, inoltre, \u00e8 risultato che l&#8217;uomo ha commesso le rapine approfittando di permessi di allontanarsi da casa per prelevare il figlio a scuola.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trentacinquenne reggino sarebbe responsabile di dodici episodi. Riconosciuto grazie alle immagini della videosorveglianza<\/p>\n","protected":false},"author":44,"featured_media":113991,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-113990","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/113990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=113990"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/113990\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/113991"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=113990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=113990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=113990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}