{"id":114050,"date":"2019-08-06T07:57:10","date_gmt":"2019-08-06T05:57:10","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/droga-cocaina-nascosta-nello-zaino-arrestato-presunto-pusher\/"},"modified":"2023-01-16T18:32:12","modified_gmt":"2023-01-16T17:32:12","slug":"306715-droga-cocaina-nascosta-nello-zaino-arrestato-presunto-pusher","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/306715-droga-cocaina-nascosta-nello-zaino-arrestato-presunto-pusher\/","title":{"rendered":"Droga, cocaina nascosta nello zaino: arrestato presunto pusher"},"content":{"rendered":"<h4>Era in procinto di prendere un bus diretto in Svizzera con 22,30 grammi di cocaina. Intercettato dalle unit\u00e0 cinofile<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>LAMEZIA TERME (CZ) &#8211; Un presunto pusher, Pasquale Gigliotti, di 38 anni, \u00e8 stato arrestato dai finanzieri del Nucleo mobile del Gruppo di Lamezia Terme con l&#8217;accusa di detenzione ai fini di spaccio di sostanze stupefacenti. A trovare la droga, nascosta nel bagaglio che l&#8217;uomo aveva con s\u00e9 \u00e8 stato il cane antidroga &#8220;Argus&#8221; che ha segnalato ai finanzieri qualcosa di sospetto all&#8217;interno di uno zaino. Assieme alla cocaina, che era stata gi\u00e0 suddivisa in dosi, \u00e8 stato trovato anche un bilancino elettronico. A carico del presunto pusher \u00e8 stata disposta la misura dell&#8217;obbligo di dimora nel comune di residenza e il divieto giornaliero di uscita dalla propria abitazione nella fascia oraria dalle 20.30 alle 6.30.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Era in procinto di prendere un bus diretto in Svizzera con 22,30 grammi di cocaina. Intercettato dalle unit\u00e0 cinofile<\/p>\n","protected":false},"author":37,"featured_media":114051,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-114050","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/114050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=114050"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/114050\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/114051"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=114050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=114050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=114050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}