{"id":114154,"date":"2019-08-08T09:05:56","date_gmt":"2019-08-08T07:05:56","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosenza-unioncamere-804-del-personale-genera-valore-per-le-imprese\/"},"modified":"2023-01-16T18:32:19","modified_gmt":"2023-01-16T17:32:19","slug":"306937-cosenza-unioncamere-804-del-personale-genera-valore-per-le-imprese","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/306937-cosenza-unioncamere-804-del-personale-genera-valore-per-le-imprese\/","title":{"rendered":"Cosenza, Unioncamere: 80,4 % del personale genera valore per le imprese"},"content":{"rendered":"<h4>Algieri: Qualit\u00e0 dei servizi erogati. La nostra governance punta sul capitale umano e costruisce il #modellocameracosenza<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; L\u201980,4 % del personale dipendente della Camera di Commercio di Cosenza svolge mansioni direttamente connesse a generare valore economico per le imprese, compresa l\u2019erogazione dei servizi. Mentre il 19,6 % \u00e8 impiegato nei processi di supporto. Il 39,5 % dei dipendenti si occupa di trasparenza, semplificazione e tutela. Un ambito dove il 22,6 % riguarda la gestione del registro imprese, albi ed elenchi. Lo sviluppo della competitivit\u00e0 impegna il 19,7 % del personale dove un dipendente su tre si occupa di servizi connessi all\u2019agenda digitale. E\u2019 quanto si legge in un report diramato da Unioncamere.<\/p>\n<p>\u00abPer noi si tratta dell\u2019ennesima conferma. Gi\u00e0 con la presentazione del mio bilancio di mandato erano emersi numeri virtuosi a fronte di una grande qualit\u00e0 dei servizi erogati e di un aumento importante del valore economico complessivo dell\u2019ente senza intaccare il patrimonio che, addirittura, \u00e8 aumentato. E, sottolineo, nonostante la contrazione delle entrate del diritto camerale\u00bb. E\u2019 quanto afferma il presidente della Camera di Commercio di Cosenza, Klaus Algieri. \u00abUsciamo fuori \u2013 sostiene Klaus Algieri &#8211; dalla rigidit\u00e0 dei numeri e proviamo a dare vita agli algoritmi. Ci accorgiamo che raccontano una filosofia ben precisa: quella del cammino\u00a0 di #OpenCameraCosenza e #ModelloCameraCosenza. Gli indicatori hanno un\u2019anima. La nostra governance costruisce il #ModelloCameraCosenza, valorizzando le competenze del capitale umano. Trasparenza, ottimizzazione dei costi e miglioramento dei servizi sono un nostro orizzonte di senso. Con le imprese sempre in cima alla nostra bussola\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Algieri: Qualit\u00e0 dei servizi erogati. La nostra governance punta sul capitale umano e costruisce il #modellocameracosenza<\/p>\n","protected":false},"author":44,"featured_media":114155,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-114154","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/114154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=114154"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/114154\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/114155"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=114154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=114154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=114154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}