{"id":114182,"date":"2019-08-08T18:33:05","date_gmt":"2019-08-08T16:33:05","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/occhiuto-in-tour-presenta-la-rigenerazione-della-citta-di-cosenza\/"},"modified":"2023-01-16T18:32:20","modified_gmt":"2023-01-16T17:32:20","slug":"307008-occhiuto-in-tour-presenta-la-rigenerazione-della-citta-di-cosenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/307008-occhiuto-in-tour-presenta-la-rigenerazione-della-citta-di-cosenza\/","title":{"rendered":"Occhiuto in tour presenta la &#8216;rigenerazione&#8217; della citt\u00e0 di Cosenza"},"content":{"rendered":"<h4>Sindaco candidato a governare la Regione Calabria<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>PAOLA (CS) &#8211;\u00a0Prosegue il tour di Mario Occhiuto nelle localit\u00e0 calabresi in qualit\u00e0 di candidato alla presidenza della Regione. <strong>Venerd\u00ec 9 agosto alle 21,30 \u00e8 in programma un incontro pubblico a Paola, in corso Roma. <\/strong>L\u2019aspirante governatore tratter\u00e0 proprio di come sia possibile, anche in Calabria, anche al Sud, rigenerare le citt\u00e0, realizzando appunto una Calabria e un Sud diversi. Nella circostanza, spunti interessanti saranno tratti dal volume di Rossana Galdini, \u201cPercorsi di rigenerazione urbana \u2013 Il caso Cosenza\u201d, edito da Pellegrini, incentrato sulla straordinaria trasformazione della citt\u00e0 di Cosenza avvenuta negli ultimi anni attraverso una ben precisa e complessiva visione progettuale che adesso si vuol proiettare sull\u2019intera Calabria. Un volume che testimonia l\u2019attenzione che il capoluogo bruzio ha stimolato riguardo a quanto prodotto in ambito di rigenerazione urbana. Il candidato alla presidenza regionale Mario Occhiuto ne discuter\u00e0 all\u2019aperto tra la gente, a Paola, proponendo le sue idee e i suoi progetti per una analoga positiva trasformazione da estendere alla Calabria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sindaco candidato a governare la Regione Calabria<\/p>\n","protected":false},"author":43,"featured_media":114183,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-114182","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/114182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=114182"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/114182\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/114183"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=114182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=114182"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=114182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}