{"id":114218,"date":"2019-08-09T14:53:17","date_gmt":"2019-08-09T12:53:17","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/regione-calabria-giunta-i-provvedimenti-approvati\/"},"modified":"2023-01-16T18:32:22","modified_gmt":"2023-01-16T17:32:22","slug":"307098-regione-calabria-giunta-i-provvedimenti-approvati","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/307098-regione-calabria-giunta-i-provvedimenti-approvati\/","title":{"rendered":"Regione Calabria: Giunta, i provvedimenti approvati"},"content":{"rendered":"<h4>Tra i provvedimenti stabiliti gli indirizzi per garantire il servizio di trattamento e di smaltimento dei rifiuti, la riscossione della tariffa per il conferimento rifiuti annualit\u00e0 2017\/2018<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>CATANZARO &#8211; Mario Oliverio ha presieduto la riunione della Giunta che, su proposta dello stesso presidente, ha deliberato le integrazioni e le precisazioni al d.g.r. n. 77 del 27 febbraio 2019 riguardanti la richiesta di dichiarazione di carattere eccezionale degli eventi meteorologici che hanno interessato il territorio della Calabria nei mesi di ottobre e novembre 2018. Contestuale la richiesta al Mipaaft di presa d&#8217;atto delle modifiche. Lo rende noto l&#8217;ufficio stampa della Giunta regionale.<\/p>\n<p>&#8220;Approvato poi &#8211; \u00e8 scritto in una nota &#8211; il Piano annuale 2019 dello sport, in riferimento alla legge regionale n. 28 del 22 novembre 2010, e lo schema dell&#8217;Accordo di Programma Quadro per l&#8217;area interna del Reventino-Savuto nell&#8217;ambito della strategia nazionale per le aree interne. Autorizzata anche la costituzione di parte civile della Regione Calabria in un procedimento penale al tribunale di Palmi per reati contro la pubblica amministrazione. Su proposta congiunta del presidente Oliverio e dell&#8217;assessore alle Infrastrutture Roberto Musmanno l&#8217;Esecutivo ha deliberato il finanziamento di 6,5 milioni di euro, tramite una delibera di variazione di bilancio proposta dall&#8217;assessore Mariateresa Fragomeni, dell&#8217;Intervento per opere accessorie propedeutiche alla realizzazione dello svincolo autostradale in localit\u00e0 Settimo di Rende, al km 250 dell&#8217;autostrada A2 del Mediterraneo e della stazione ferroviaria di settimo Montalto, all&#8217;interno del Piano di azione e coesione 2014-2020&#8221;.<\/p>\n<p>&#8220;La Giunta, su indicazione dell&#8217;assessore al lavoro Angela Robbe &#8211; \u00e8 scritto nella nota &#8211; ha anche approvato la delibera con cui destina, attraverso una variazione di bilancio di 28 milioni di euro deliberate su proposta dell&#8217;assessore Mariateresa Fragomeni, le risorse alla prosecuzione dei percorsi di politiche attive. Approvato poi il Piano di interventi previsti dal Fondo per le politiche della famiglia, annualit\u00e0 2019, in ottemperanza al decreto del Ministro per la famiglia e le disabilit\u00e0 del 30 aprile 2019. Gli obbiettivi del Piano: sostenere e promuovere la natalit\u00e0 anche attraverso il potenziamento dei servizi per la prima infanzia e per il supporto alle famiglie, sostenere e promuovere percorsi di formazione a sostegno della genitorialit\u00e0 e per promuove l&#8217;esercizio delle responsabilit\u00e0 genitoriali, la conciliazione dei tempi, la tutela della donne e dei minori anche con il potenziamento dei Consultori familiari esclusivamente per le attivit\u00e0 di carattere sociale.<\/p>\n<p>Su proposta dell&#8217;assessore all&#8217;ambiente Antonella Rizzo l&#8217;Esecutivo ha stabilito gli indirizzi per garantire il servizio di trattamento e di smaltimento dei rifiuti, la riscossione della tariffa per il conferimento rifiuti annualit\u00e0 2017\/2018. Con questo atto ancora una volta la Regione Calabria va incontro alle esigenze dei Comuni attuando un Piano di rateizzazione alle tariffe di conferimento dei rifiuti per due annualit\u00e0. Deciso anche, su sollecitazione dell&#8217;assessore alla cultura Maria Francesca Corigliano, il riconoscimento di interesse regionale del Museo dell&#8217;Arte del Bosco di Sorbo San Basile, del Museo all&#8217;aperto di Paterno Calabro, del Museo diocesano monsignor Aurelio Sorrentino di Reggio Calabria.<\/p>\n<p>Su proposta dell&#8217;assessore al bilancio Mariateresa Fragomeni \u00e8 stata deliberata la variazione al bilancio di previsione di 2,7 milioni di euro al fine di procedere alla stipula dell&#8217;Accordo di Programma Quadro &#8216;Area interna Reventino-Savuto&#8217;. Approvata anche una variazione di bilancio di circa 4 milioni di euro, a valere sul Pac 2014-2020 azione 7.3.3, per avviare una seconda fase di attuazione volta a perseguire in ulteriori aree urbane del territorio regionali un sistema di logistica urbana a zero emissioni di Co2, finalizzato alla realizzazione di progetti di City Logistics. Disposta inoltre la variazione di bilancio per 6,179 milioni di euro, finalizzata all&#8217;assegnazione di risorse da parte dello Stato per la fornitura gratuita e semigratuita dei libri di testo agli studenti meno abbienti delle scuole dell&#8217;obbligo e secondarie superiori.<\/p>\n<p>Deliberata poi la variazione al bilancio di 300 mila euro per il potenziamento di interventi per l&#8217;internazionalizzazione dei laboratori di ricerca del sistema universitario calabrese&#8221;. &#8220;In materia di sviluppo economico, su indicazione dell&#8217;assessore Fragomeni &#8211; conclude la nota &#8211; , la Giunta ha approvato i codici Ateco relativi alle attivit\u00e0 economiche nell&#8217;ambito della strategia di sviluppo urbano sostenibile per i principali poli urbani della Regione e delle aree urbane di dimensione inferiore. Infine la Giunta ha deliberato l&#8217;intesa Stato-Regione per il progetto denominato &#8220;variante metanodotto S.Eufemia-Crotone&#8221; in localit\u00e0 Marcellinara&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tra i provvedimenti stabiliti gli indirizzi per garantire il servizio di trattamento e di smaltimento dei rifiuti, la riscossione della tariffa per il conferimento rifiuti annualit\u00e0 2017\/2018<\/p>\n","protected":false},"author":44,"featured_media":114219,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-114218","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/114218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=114218"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/114218\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/114219"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=114218"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=114218"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=114218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}