{"id":114222,"date":"2019-08-09T16:19:18","date_gmt":"2019-08-09T14:19:18","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/regionali-oliverio-sulla-mia-ricandidatura-decidano-i-cittadini\/"},"modified":"2023-01-16T18:32:23","modified_gmt":"2023-01-16T17:32:23","slug":"307102-regionali-oliverio-sulla-mia-ricandidatura-decidano-i-cittadini","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/307102-regionali-oliverio-sulla-mia-ricandidatura-decidano-i-cittadini\/","title":{"rendered":"Regionali: Oliverio, sulla mia ricandidatura decidano i cittadini"},"content":{"rendered":"<h4>&#8220;Per quanto riguarda la mia ricandidatura, a dire se si \u00e8 interrotto o meno un rapporto con i calabresi devono essere gli stessi cittadini<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>CATANZARO &#8211; Dico questo non perch\u00e9 voglia fare prove muscolari o numeriche, ma perch\u00e9 sono convinto che i primi a doversi esprimere debbano essere i cittadini e i territori calabresi. Nessun soggetto pu\u00f2 sostituirsi a loro in questa valutazione che deve essere compiuta anche in rapporto alle persone che si mettono in campo&#8221;. A dirlo il presidente della Regione Calabria Mario Oliverio in merito alla sua ricandidatura alle prossime regionali di autunno dopo che ieri il segretario del Pd Nicola Zingaretti ha affermato che il partito gli chieder\u00e0 un passo indietro. &#8220;Allo stato &#8211; ha detto Oliverio ai giornalisti al termine della riunione del Pd calabrese conclusa nella serata di ieri &#8211; non mi pare che oltre al sottoscritto ci siano altri candidati. Se ci sono lo dicano e si facciano avanti. Poi si vada davanti ai calabresi e agli iscritti e si lasci a loro la facolt\u00e0 di decidere. Questa \u00e8 l&#8217;unica e la pi\u00f9 alta forma di democrazia che conosco&#8221;.<\/p>\n<p>&#8220;Ringrazio il responsabile per il Mezzogiorno del Pd Nicola Oddati &#8211; ha poi detto Oliverio &#8211; per avere finalmente evidenziato le cose positive che abbiamo realizzato. Finalmente qualcuno nel Pd, che in questi anni \u00e8 stato assolutamente assente, ha capito come abbiamo operato e cosa abbiamo realizzato. Ci\u00f2 che pi\u00f9 mi soddisfa della riunione \u00e8 il fatto che la stragrande maggioranza di quanti sono intervenuti abbia avanzato la richiesta di lasciare ai calabresi la volont\u00e0 di esprimere la loro indicazione sulle candidature, cos\u00ec come avviene in tutte le altre regioni. Non vedo perch\u00e9 ci\u00f2 non debba avvenire anche in Calabria. Lo strumento delle primarie mi sembra, in tal senso, una delle forme democratiche pi\u00f9 alte di partecipazione. Per quanto mi riguarda non mi sono mai sentito fuori corsa. Lo dico non per affermare e difendere una posizione personale, ma in rapporto al progetto che abbiamo messo in campo in questi anni per far uscire la Calabria dal pantano e per posizionarla sul binario della crescita e del futuro. La nostra storia e il nostro impegno sul versante del contrasto all&#8217;illegalit\u00e0 e alla criminalit\u00e0 sono noti a tutti e le stesse vicende giudiziarie che mi vedono coinvolto nulla hanno a che fare con rapporti o condizionamenti di organizzazioni criminali, mafiose o &#8216;ndranghetistiche n\u00e9 per quanto mi riguarda, n\u00e9 per quanto riguarda il capogruppo regionale del Pd Sebi Romeo che, come ha rilevato lo stesso procuratore di Reggio Calabria, \u00e8 fuori da rapporti con la cosca Libri, oggetto di un&#8217;operazione giudiziaria nella quale Romeo \u00e8 stato ingiustamente coinvolto&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Per quanto riguarda la mia ricandidatura, a dire se si \u00e8 interrotto o meno un rapporto con i calabresi devono essere gli stessi cittadini<\/p>\n","protected":false},"author":44,"featured_media":114223,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-114222","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/114222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=114222"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/114222\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/114223"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=114222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=114222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=114222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}