{"id":114252,"date":"2019-08-10T17:36:26","date_gmt":"2019-08-10T15:36:26","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/crotone-recuperato-cadavere-in-fondo-ad-un-pozzo\/"},"modified":"2023-01-16T18:32:25","modified_gmt":"2023-01-16T17:32:25","slug":"307152-crotone-recuperato-cadavere-in-fondo-ad-un-pozzo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/307152-crotone-recuperato-cadavere-in-fondo-ad-un-pozzo\/","title":{"rendered":"Crotone, recuperato cadavere in fondo ad un pozzo"},"content":{"rendered":"<h4>Il cadavere di un uomo e\u2019 stato recuperato questo pomeriggio in fondo a un pozzo in localita\u2019 Le Cannella del comune di Isola Capo Rizzuto, nel Crotonese<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>ISOLA CAPO RIZZUTO (KR) &#8211; Si tratta di un anziano uomo di 75 anni che potrebbe essere caduto accidentalmente nel pozzo, profondo circa sei metri. Sulla vicenda, comunque, stanno indagando i carabinieri della Tenenza di Isola Capo Rizzuto. Il cadavere e\u2019 stato recuperato dai Vigili del fuoco del comando provinciale di Crotone intervenuti sul posto con una squadra composta da sei uomini e con tre automezzi. I vigili intervenuti, con tecniche Speleo Alpine Fluviali (Saf ), si sono calati all&#8217;interno del pozzo,per meta\u2019 pieno d\u2019acqua, dove l&#8217;uomo galleggiava, il corpo e\u2019 stato imbracato e portato fuori.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il cadavere di un uomo e\u2019 stato recuperato questo pomeriggio in fondo a un pozzo in localita\u2019 Le Cannella del comune di Isola Capo Rizzuto, nel Crotonese<\/p>\n","protected":false},"author":44,"featured_media":114253,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-114252","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/114252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=114252"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/114252\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/114253"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=114252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=114252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=114252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}