{"id":114346,"date":"2019-08-13T06:00:14","date_gmt":"2019-08-13T04:00:14","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/nadia-toffa-sconfitta-dal-cancro-muore-a-40-anni-la-conduttrice-de-le-iene\/"},"modified":"2023-01-16T18:32:31","modified_gmt":"2023-01-16T17:32:31","slug":"307603-nadia-toffa-sconfitta-dal-cancro-muore-a-40-anni-la-conduttrice-de-le-iene","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/307603-nadia-toffa-sconfitta-dal-cancro-muore-a-40-anni-la-conduttrice-de-le-iene\/","title":{"rendered":"Nadia Toffa sconfitta dal cancro, muore a 40 anni la conduttrice de &#8220;Le Iene&#8221;"},"content":{"rendered":"<h4>E&#8217; un post commosso e doloroso quello diffuso dalla redazione de Le Iene di Italia Uno, per dire addio a Nadia Toffa, che aveva reso pubblica la sua battaglia contro il cancro.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>&#8220;E forse ora qualcuno potrebbe pensare che hai perso, ma chi ha vissuto come te, non perde mai. <strong>Hai combattuto a testa alta, col sorriso<\/strong>, con dignit\u00e0 e sfoderando tutta la tua forza, fino all\u2019ultimo, fino a oggi. D\u2019altronde nella vita hai lottato sempre. Hai lottato anche quando sei arrivata da noi, e forse \u00e8 per questo che ci hai conquistati da subito. \u00c8 stato un colpo di fulmine con te, Toffa. \u00c8 stato tanto facile piacersi, inevitabile innamorarsi, ed \u00e8 proprio per questo che \u00e8 cos\u00ec difficile lasciarsi&#8221;. <strong>E&#8217; questo il contenuto del post su Facebook della redazione della trasmissione televisiva di Italia 1, Le Iene, per salutare Nadia Toffa.<\/strong><\/p>\n<p>&#8220;Il destino, il karma, la sorte, la sfiga ha deciso di colpire proprio te, la nostra Toffa, la pi\u00f9 tosta di tutti, mentre qualcuno non credeva alla tua lotta, noi restavamo in silenzio e tu sorridevi. Sei riuscita a perdonare tutti, anche il fato, e forse anche il mostro contro cui hai combattuto senza sosta&#8230; il cancro, che fino a poco tempo fa tutti chiamavano timidamente <strong>\u201cIl male incurabile\u201d<\/strong> e che, anche grazie alla tua battaglia, adesso ha un nome proprio. \u201cNon bisogna vergognarsi di guardarlo in faccia e chiamarlo per nome il bastardo, &#8211; dicevi &#8211; che magari si spaventa un po\u2019 se lo guardi fisso negli occhi\u201d. E dato che sei stata in grado di perdonare l\u2019imperdonabile, cara Nadia, non ci resta che sperare con tutto il cuore che tu sia riuscita a perdonare anche noi, che non siamo stati in grado di aiutarti quanto avremmo voluto. Ed ecco le Iene che piangono la loro dolce guerriera, inermi davanti a tutto il dolore e alla consapevolezza che solo il tuo sorriso, Nadia, potrebbe consolarci, solo la tua energia e la tua forza potrebbero farci tornare ad essere quelli di sempre. Niente per noi sar\u00e0 pi\u00f9 come prima&#8221;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-307609 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/08\/nadia-toffa02.jpg\" alt=\"\" width=\"601\" height=\"373\" title=\"\"><\/p>\n<p>Nadia Toffa aveva scoperto di dover combattere quel male terribile nel dicembre 2017, a seguito di un grave malore, e da allora aveva iniziato ad affrontare quel calvario con il sorriso, cercando di incoraggiare chi soffre a <strong>non lasciarsi schiacciare dal dolore<\/strong>:<strong> \u201cNon siamo malati, siamo guerrieri\u201d, diceva<\/strong>. E con il sorriso aveva affrontato e si era sottoposta a cicli di radioterapia e chemioterapia, per poi aggiornare i suoi followers. Il suo ultimo post su Instagram risale al <strong>primo luglio<\/strong>, prima del peggioramento della malattia. Ad accompagnarlo, come sempre, uno scatto in cui sorride, accanto al suo cagnolino Tot\u00f2<em>: &#8220;Io e Tot\u00f2\u00a0 contro l\u2019afa! &#8211; scriveva &#8211; E dalle vostre parti come va? Vi bacio tutti tutti tutti&#8221;. <\/em>Da quel momento era sparita dai social e tutti avevano pensato ad una pausa, mentre invece le sue condizioni stavano peggiorando. Per diverso tempo Nadia Toffa aveva messo a nudo il suo coraggio e anche le sue fragilit\u00e0 nell&#8217;affrontare quella battaglia che oggi l&#8217;ha strappata alla vita.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>E&#8217; un post commosso e doloroso quello diffuso dalla redazione de Le Iene di Italia Uno, per dire addio a Nadia Toffa, che aveva reso pubblica la sua battaglia contro il cancro.<\/p>\n","protected":false},"author":42,"featured_media":114347,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-114346","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/114346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=114346"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/114346\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/114347"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=114346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=114346"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=114346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}