{"id":114354,"date":"2019-08-13T11:30:49","date_gmt":"2019-08-13T09:30:49","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/carlo-tansi-si-candida-resettare-la-regione-e-governare-con-persone-capaci\/"},"modified":"2023-01-16T18:32:32","modified_gmt":"2023-01-16T17:32:32","slug":"307628-carlo-tansi-si-candida-resettare-la-regione-e-governare-con-persone-capaci","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/307628-carlo-tansi-si-candida-resettare-la-regione-e-governare-con-persone-capaci\/","title":{"rendered":"Regionali, Carlo Tansi: &#8220;pronto a rivoltare la Calabria come un calzino&#8221; (AUDIO)"},"content":{"rendered":"<h4>Centinaia di calabresi avevano chiesto a gran voce il suo reintegro a capo della Protezione civile calabrese. Oggi in migliaia hanno firmato una petizione per la sua candidatura alla guida della Regione Calabria. Carlo Tansi accetta e annuncia &#8216;pulizia e trasparenza&#8217;<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; <strong>Carlo Tansi, geologo del Cnr, \u00e8 l&#8217;ex capo della Protezione civile calabrese<\/strong> alla quale ha dedicato anima e cuore rendendo il suo Dipartimento tra i migliori d&#8217;Italia. Il modello di protezione civile della Calabria \u00e8 stato adottato persino dalle Regioni Lazio e Sicilia. E&#8217; riuscito, non senza ostacoli e lunghe battaglie, a trasformare la Protezione Civile da &#8220;cenerentola&#8221; e ultima d&#8217;Italia a fiore all&#8217;occhiello in tutto lo stivale. Quel <strong>lavoro di &#8220;pulizia e trasparenza&#8221; <\/strong>Tansi \u00e8 pronto adesso ad attuarlo anche negli uffici della Regione, dove correr\u00e0 come prossimo governatore con una serie di liste che, annuncia, <strong>dovranno includere rigorosamente candidati garantiti da certificazione antimafia<\/strong>. \u00c8 partito dal basso, dai social e dalla gente comune che gli ha manifestato tutto il suo sostegno e quel desiderio enorme di cambiare una regione dalle infinit\u00e0 potenzialit\u00e0 ed eccellenze, ma troppo spesso<strong> vittima di malaffare e interessi<\/strong>. Ha iniziato ad incontrare i calabresi e continuer\u00e0 a farlo con tutti quelli che hanno a cuore il desiderio di cambiare la Calabria.<\/p>\n<h4><span style=\"color: #ff0000;\">ASCOLTA l&#8217;intervista\u00a0<\/span><\/h4>\n<p><iframe loading=\"lazy\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/665110862&amp;color=%23ff5500&amp;auto_play=false&amp;hide_related=false&amp;show_comments=true&amp;show_user=true&amp;show_reposts=false&amp;show_teaser=true\" width=\"100%\" height=\"166\" frameborder=\"no\" scrolling=\"no\"><\/iframe><\/p>\n<h4><strong>&#8220;Cacciato&#8221; per aver dato fastidio ad un &#8220;manipolo di burocrati&#8221;<\/strong><\/h4>\n<p>\u00abNel mio mandato da responsabile della protezione civile regionale, ho tolto privilegi ad autisti che guadagnavano 6.000 euro al mese di straordinario netti. Ho tagliato dappertutto, sugli affitti, le assicurazioni, ed abbiamo risparmiato milioni di euro all&#8217;anno. Inoltre <strong>abbiamo professionalizzato la protezione civile<\/strong>, abbiamo fatto denunce a varie Procure che hanno anche prodotto degli arresti&#8230; abbiamo bonificato un ambiente malsano. Alla fine del mandato per\u00f2, <strong>sono stato &#8220;cacciato&#8221; perch\u00e8 ho dato fastidio<\/strong>, ho <strong>toccato interessi di casta impressionanti<\/strong>, decine di milioni di euro che andavano a societ\u00e0 che andavano avanti a proroghe, bandi pilotati&#8230; Dopo aver fatto tutto questo, <strong>quel &#8220;manipolo di burocrati&#8221; della Regione Calabria mi ha dato il benservito.<\/strong> In un primo momento ci sono rimasto male; poi per\u00f2 \u00e8 nato un &#8216;<strong>movimento social&#8217;<\/strong>, dal basso, che all&#8217;inizio mi ha incoraggiato chiedendo al Presidente Oliverio di prendere provvedimenti sulla mia posizione e che oggi chiede a gran voce la mia candidatura alle Regionali\u00bb.<\/p>\n<h4>Al primo posto la &#8220;meritocrazia&#8221;<\/h4>\n<p>\u00abPer questo motivo voglio mettere a disposizione dei calabresi, la mia energia e capacit\u00e0 per fare la stessa cosa che ho fatto alla protezione civile. <strong>Come ho rivoltato con un calzino la Protezione civile, vorrei fare altrettanto con tutta la regione Calabria<\/strong>, senza guardare in faccia a nessuno, senza favoritismi, mettendo in campo la <strong>meritocrazia<\/strong>, cacciando quei quattro cialtroni che governano l&#8217;amministrazione e dando in mano le cabine di comando a quei bravissimi giovani calabresi, laureati. Anzich\u00e8 farli lavorare nei call center o nei ristoranti come camerieri quando va bene, altrimenti vanno via dalla Calabria, consegneremo loro le &#8216;cabine di comando&#8217; per una Calabria migliore\u00bb.<\/p>\n<h4>\u00a0&#8216;Corteggiato&#8217; dai Cinquestelle. Sono il candidato di tutti<\/h4>\n<p>\u00abIo <strong>sono il candidato di tutti<\/strong> e il mio intento \u00e8 di mettere insieme le forze positive, <strong>abbandonando ideologie e &#8220;partiti presi&#8221;,<\/strong> per canalizzare il flusso di energie positive di quelle\u00a0 persone che non ne possono pi\u00f9, verso un unico obiettivo: cambiare la Regione nei punti cardine. Per esempio la <strong>burocrazia<\/strong> \u00e8 uno dei fattori che hanno determinato il blocco dello sviluppo di questa regione. Se si presenta un progetto si deve aspettare, se va bene, un anno. La tecnologia oggi, offre gli strumenti per informatizzare tutti i documenti, per consentire la tracciabilit\u00e0 di ogni documento, per garantire la trasparenza\u00bb.<\/p>\n<h4>Tagliare i dipartimenti e toglierli a &#8216;cialtroni incapaci&#8217;<\/h4>\n<p>\u00abCi sono <strong>23 dipartimenti<\/strong>, unit\u00e0 che sono ai vertici della Regione; in Lombardia sono meno della met\u00e0 e l\u00ec sono quasi 8 milioni di persone mentre qui, siamo poco meno di 2 milioni. E&#8217; necessario tagliare drasticamente il numero dei dipartimenti regionali che sono solo ricettacoli di potere per mettere in mano questi uffici a persone competenti e non a cialtroni incapaci\u00bb.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-307645 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/08\/carlo-tansi-.jpg\" alt=\"\" width=\"519\" height=\"271\" title=\"\"><\/p>\n<h4>Inversione di tendenza: la prima azione di Tansi? il tasto &#8220;reset&#8221;<\/h4>\n<p>\u00abCosa farei per prima cosa in Regione? Avete presente il tasto &#8220;Reset&#8221; del computer? Io resetterei la Regione, azzererei tutti gli uffici e inizierei a costruire pochi dipartimenti. E quelle persone incapaci che non hanno mai fatto un concorso e che governano quegli uffici li manderei in altri settori dove non fanno danni. Prenderei giovani capaci e meritevoli, con tanto di visione dei loro curriculum, per metterli nelle postazioni di comando. E&#8217; chiaro che i vertici di quei macro dipartimenti che si occupano dei grandi problemi della Calabria (<em>mare, agricoltura, turismo, ambiente&#8230;<\/em>) dovranno essere affidati persone d&#8217;esperienza e non ad &#8220;amici degli amici&#8221; che fanno avere incarichi alle ditte amiche e che creano il solito indotto. Dobbiamo capire tutti che <strong>le nostre risorse devono essere messe a sistema e devono essere il nostro vanto<\/strong>. Ci sono tanti modi per risollevare la Calabria basta mettere a sistema le ricchezze e farlo con <strong>persone capaci<\/strong>\u00bb.<\/p>\n<p>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Centinaia di calabresi avevano chiesto a gran voce il suo reintegro a capo della Protezione civile calabrese. Oggi in migliaia hanno firmato una petizione per la sua candidatura alla guida della Regione Calabria. Carlo Tansi accetta e annuncia &#8216;pulizia e trasparenza&#8217;<\/p>\n","protected":false},"author":19,"featured_media":114355,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-114354","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/114354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=114354"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/114354\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/114355"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=114354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=114354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=114354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}