{"id":114626,"date":"2019-08-19T17:05:49","date_gmt":"2019-08-19T15:05:49","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/ristoratore-calabrese-ucciso-a-colpi-di-pistola-in-canada\/"},"modified":"2023-01-16T18:32:49","modified_gmt":"2023-01-16T17:32:49","slug":"308406-ristoratore-calabrese-ucciso-a-colpi-di-pistola-in-canada","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/308406-ristoratore-calabrese-ucciso-a-colpi-di-pistola-in-canada\/","title":{"rendered":"Ristoratore calabrese ucciso a colpi di pistola in Canada"},"content":{"rendered":"<h4>Fratelli ritenuti vicini al narcotraffico<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>TORONTO &#8211; Un calabrese \u00e8 stato assassinato in Canada. Si tratta del proprietario di un ristorante di Toronto. Originario del vibonese \u00e8 morto sotto una raffica di colpi di arma da fuoco. Proiettili sparati in pieno centro citt\u00e0, su Roncesvalles Road, da killer a bordo di un Suv che hanno fatto perdere le proprie tracce.<strong> Il 64enne Paolo Caputo, ritrovato in una pozza di sangue a pochi metri dal ristorante, \u00e8 fratello di Martino Caputo<\/strong> 43enne tutt&#8217;ora in carcere per l&#8217;omicidio di Jhonny Raposo. Un assassinio avvenuto vicino ad un bar della Little Italy di Toronto nel 2012. Delitto maturato, secondo gli inquirenti, nella lotta per il predominio del narcotraffico di cocaina. Nato a Capistrano, Paolo Caputo risultava essere un incensurato pur essendo stato arrestato due volte (nel 2004 per aver fatto il bookmaker e per il gioco d&#8217;azzardo nel 2007) non aveva mai riportato condanne. Per 11 anni aveva gestito un altro locale canadese e viveva in Ontario.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-308412 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/08\/caputo64.jpg\" alt=\"\" width=\"497\" height=\"483\" title=\"\"><\/p>\n<p>Il suo corpo \u00e8 stato ufficialmente identificato dalle autorit\u00e0 competenti sabato, mentre sono in corso gli accertamenti della polizia scientifica sulla pistola usata dai sicari venerd\u00ec alle 16:00 durante il sanguinario agguato. Lanciata dal finestrino del suv bianco sul quale a gran corsa sono corsi via gli assassini, \u00e8 stata recuperata dagli investigatori. Il ristorante di Caputo \u00e8 il popolare Domani, rinomato per l&#8217;ottima cucina italiana e l&#8217;alta qualit\u00e0 del servizio. Descritto dai conoscenti come un onesto lavoratore, non \u00e8 da escludere sia rimasto coinvolto in una serie di vendette per gli affari dei<strong> suoi fratelli minori ritenuti vicini al defunto boss di Montreal Vito Rizzuto.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>https:\/\/quicosenza.it\/news\/calabria\/307030-ndrangheta-business-ed-accordi-decisi-oltreoceano-28-arresti<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fratelli ritenuti vicini al narcotraffico<\/p>\n","protected":false},"author":43,"featured_media":114627,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[22,571],"tags":[],"class_list":["post-114626","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dal-mondo","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/114626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=114626"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/114626\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/114627"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=114626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=114626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=114626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}