{"id":114656,"date":"2019-08-20T11:36:13","date_gmt":"2019-08-20T09:36:13","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/raganello-mai-piu-un-anno-fa-la-tragedia-che-uccise-10-persone\/"},"modified":"2023-01-16T18:32:51","modified_gmt":"2023-01-16T17:32:51","slug":"308493-raganello-mai-piu-un-anno-fa-la-tragedia-che-uccise-10-persone","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/308493-raganello-mai-piu-un-anno-fa-la-tragedia-che-uccise-10-persone\/","title":{"rendered":"Raganello, mai pi\u00f9. Un anno fa la tragedia che uccise 10 persone"},"content":{"rendered":"<h4>Il 20 agosto 2018 la tragedia che cancell\u00f2 per sempre la vita di 10 persone, 9 turisti e una guida. Travolti delle acque del Raganello diventate una furia a causa delle piogge. Tragedie del genere non si ripetano pi\u00f9<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CIVITA (CS) &#8211; Improvvisa,<strong>\u00a0la valanga d&#8217;acqua e fango si rivers\u00f2 furiosa nel torrente che attraversa le strette gole all&#8217;interno del Parco Nazionale del Pollino<\/strong> nel comune di Civita, <strong>meta ogni anno di migliaia di appassionati e turisti del rafting e delle escursioni <\/strong>in uno dei canyon pi\u00f9 belli al mondo, incastonato in un contesto naturalistico unico. Quarantaquattro furono gli escursionisti sorpresi dal maltempo. Per 10 di loro, <strong>9 turisti e una guida,<\/strong> no ci fu speranza. Morti dopo essere stati trascinati via per centinaia di metri dalla<strong> furia delle acque del Raganello<\/strong>, ingrossate dalla pioggia in una calda giornata di fine agosto, arrivate a superare i due metri di altezza. Alcuni corpi furono ritrovati anche a quasi 3 chilometri a valle.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/7866\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-308497\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/08\/Ragganello2-698x400.jpg\" alt=\"\" width=\"551\" height=\"316\" title=\"\"><\/a><\/p>\n<p>Le vittime furono <strong>Antonio De Rasis, 32 anni di Cerchiara di Calabria<\/strong> in provincia di Cosenza, la guida esperta e <strong>volontario della Protezione Civile<\/strong>. <strong>Maria Immacolata Marrazzo, 43 anni, avvocato di Torre del Greco,<\/strong>\u00a0<strong>Carlo Maurici, 35 anni, e Valentina Venditti, 34 anni di Roma,<\/strong>\u00a0<strong>Myriam Mezzolla, 27 anni, e Claudia Giampietro di 31, pugliesi<\/strong>, investiti dalla piena del torrente mentre erano in canoa a fare rafting. <strong>Gianfranco Fumarola 44 anni<\/strong>, anche lui pugliese agente di polizia penitenziaria. <strong>Carmen Tammaro 41 anni e Antonio Santopaolo, 44 marito e moglie<\/strong> di Di Qualiano nel Napoletano, erano. Le loro figlie di 10 e 12 anni si sono salvate. L&#8217;ultima vittima fu <strong>Paola Romagnoli, ricercatrice di 55 anni di Bergamo<\/strong>.<\/p>\n<p><strong>Chiara, la bimba di 9 anni, salvata dagli uomini del Soccorso Alpino <\/strong>e trovata accanto un cadavere, \u00e8 diventando il simbolo di quella terribile giornata.<\/p>\n<p>&nbsp;<\/p>\n<p><center><script>window.fbAsyncInit = function() {   FB.init({   xfbml : true,   version : 'v2.3'   });   }; (function(d, s, id){   var js, fjs = d.getElementsByTagName(s)[0];   if (d.getElementById(id)) {return;}   js = d.createElement(s); js.id = id;   js.src = \"\/\/connect.facebook.net\/en_US\/sdk.js\";   fjs.parentNode.insertBefore(js, fjs);   }(document, 'script', 'facebook-jssdk'));<\/script><\/center><\/p>\n<div class=\"fb-video\" data-href=\" https:\/\/www.facebook.com\/soccorsoalpinocalabria\/videos\/373659519988166\/\" data-width=\"600\" data-allowfullscreen=\"true\"><\/div>\n<p>&nbsp;<\/p>\n<p>Ad un anno dalla tragedia, nel primo anniversario da pi\u00f9 parti si \u00e8 rafforzata la consapevolezza che tutto poteva essere evitato. C&#8217;era un <strong>bollettino di allerta meteo diffuso dalla Protezione Civile<\/strong> emanato il giorno prima. Su questo aspetto si concentra l\u2019indagine della Procura di Castrovillari che pochi giorni fa \u00e8 stato notificato l&#8217;avviso di conclusione indagini. Secondo la ricostruzione emersa, oltre alla sottovalutazione meteo, un ruolo fondamentale lo avrebbero avuto anche l<strong>&#8216;assenza di regolamenti per l&#8217;accesso alle gole<\/strong>, la mancanza di aggiornamenti dei piani di emergenza e infine l&#8217;imprudenza.<\/p>\n<p>Ma oggi <strong>\u00e8 il giorno del ricordo, il giorno della preghiera e della memoria<\/strong> per quelle 10 persone che in un giorno che doveva essere di festa e divertimento hanno trovato la morte. La commemorazione delle 10 vittime avver\u00e0 nella <strong>chiesa di Santa Maria Assunta alle 18:00<\/strong> dove si terr\u00e0 una messa in suffragio a cui parteciperanno le autorit\u00e0 civili, religiose e militari del comprensorio, i componenti del &#8220;Comitato Familiari Vittime del Raganello&#8221;, i familiari delle vittime e i rappresentanti istituzionali delle comunit\u00e0 di alcune delle vittime. Alle 20:00, organizzata dallo stesso comitato, un<em>a fiaccolata che arriver\u00e0 fino al Belvedere.\u00a0 &#8220;Ad un anno da quel terribile luned\u00ec vogliamo ricordare chi non c\u2019\u00e8 pi\u00f9. Lo vogliamo fare sommessamente e in modo molto sobrio ha detto il <strong>sindaco di Civita, Alessandro Tocci &#8211;<\/strong>\u00a0. Vogliamo testimoniare, ancora una volta, la nostra vicinanza ai familiari delle dieci vittim<\/em>e. U<em>n evento che ha stravolto la vita di una piccola comunit\u00e0<\/em>. <em>Un triste ricordo indelebile ma che ci deve spronare ad andare avanti. Quanto successo il 20 agosto dell\u2019anno scorso non potr\u00e0 e non sar\u00e0 cancellato dalla memoria della comunit\u00e0 civitese, sottolineando, per\u00f2, che la comunit\u00e0 che mi onoro di rappresentare ha vissuto quest\u2019anno con grande dignit\u00e0 e con grande senso di umanit\u00e0<\/em>&#8220;.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/7867\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-308496\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/08\/Raganello3-600x400.jpg\" alt=\"\" width=\"528\" height=\"352\" title=\"\"><\/a><\/p>\n<h4>Protezione Civile &#8220;\u00e8 mancata la prevenzione, su questo si deve lavorare&#8221;<\/h4>\n<p>A tutto il sistema di protezione civile l&#8217;obbligo di fare tutto il possibile per evitare che simili tragedie si ripetano. Se, infatti, un anno fa <strong>il sistema ha funzionato bene nella fase del soccorso<\/strong> (l&#8217;<span class=\"text_exposed_show\">intervento tempestivo del Soccorso Alpino, dei Vigili del Fuoco e delle altre componenti operative ha impedito che il bilancio fosse molto pi\u00f9 pesante) <strong>\u00e8 invece mancato nella fase della prevenzione<\/strong>. Bisogna <strong>lavorare per migliorare la comunicazione dei rischi e delle allerte ai cittadini<\/strong>. Purtroppo manca nella nostra regione una cultura della Protezione civile. Leggi, regole e divieti sono fondamentali ma pi\u00f9 importante \u00e8 che tutti i cittadini, i sindaci e gli operatori conoscano i pericoli a cui sono esposti e le azioni che si possono mettere in campo per mitigare i rischi conseguenti. La sicurezza non pu\u00f2 essere semplicemente delegata!<strong> La sicurezza \u00e8 qualcosa che si costruisce giorno dopo giorno con scelte consapevoli,<\/strong> ad esempio quando si costruisce una casa scegliendo un\u2019area sicura e rispettando le norme o quando si attraversano aree a rischio di inondazione o allagamento (es. sottopassi) in caso di allerta meteo. Infine il piano di protezione civile dovrebbe essere uno strumento semplice e conosciuto da tutti. <strong>La conoscenza \u00e8 fondamentale per evitare che simili tragedie accadano di nuovo<\/strong>.<\/span><\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/7868\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-308498\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/08\/Raganello4-665x400.jpg\" alt=\"\" width=\"545\" height=\"328\" title=\"\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il 20 agosto 2018 la tragedia che cancell\u00f2 per sempre la vita di 10 persone, 9 turisti e una guida. Travolti delle acque del Raganello diventate una furia a causa delle piogge. Tragedie del genere non si ripetano pi\u00f9<\/p>\n","protected":false},"author":46,"featured_media":114657,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-114656","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/114656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=114656"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/114656\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/114657"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=114656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=114656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=114656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}