{"id":114792,"date":"2019-08-23T08:54:34","date_gmt":"2019-08-23T06:54:34","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/legati-davanti-al-canile-con-un-cappio-di-plastica-una-casa-vera-per-zorro-e-zara\/"},"modified":"2023-01-16T18:33:01","modified_gmt":"2023-01-16T17:33:01","slug":"308925-legati-davanti-al-canile-con-un-cappio-di-plastica-una-casa-vera-per-zorro-e-zara","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/308925-legati-davanti-al-canile-con-un-cappio-di-plastica-una-casa-vera-per-zorro-e-zara\/","title":{"rendered":"Legati davanti al canile con un cappio di plastica, una casa &#8216;vera&#8217; per Zorro e Zara"},"content":{"rendered":"<h4>Dopo la pausa estiva torna la rubrica Qui la Zampa. Questa settimana l&#8217;ennesima storia triste che, si spera, possa avere presto un lieto fine. Questa coppia di pelosi \u00e8 stata trovata legata davanti al canile di Donnici ma ora si spera in una &#8216;vera&#8217; famiglia<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<h3>Zorro e Zara<\/h3>\n<p>Sono lontani entrambi dal sapere cosa sia realmente una famiglia perch\u00e8 evidentemente chi li ha tenuti fino ad oggi, non li riteneva parte della famiglia altrimenti non li avrebbe mai abbandonati. Invece Zorro e Zara sono stati\u00a0 lasciati l\u00ec, con un cappio di plastica al collo, legati davanti al canile. Chi li ha abbandonati gli ha voltato le spalle ed \u00e8 andato via, lasciandoli denutriti, tristi, e Zara&#8230; anche in dolce attesa, ma i suoi cuccioli non ce l&#8217;hanno fatta.<\/p>\n<p>Per fortuna in meno di un mese, i loro occhi hanno ricominciato a sorridere e grazie ai veterinari e ai volontari si sono rimessi in sesto, nel corpo e nell&#8217;anima. Ora Zorro e Zara sono pronti a vivere in una vera casa, magari in coppia, insieme. Eh s\u00ec perch\u00e8 al momento dell&#8217;abbandono si sono dati forza reciprocamente e ora sono inseparabili. Un dolore li ha uniti e speriamo che una gioia li tenga insieme.<\/p>\n<p style=\"text-align: center;\"><strong>Zorro<\/strong> (in basso)\u00a0\u00e8 un maschietto ed \u00e8 un incrocio Boxer\/Pitbull di circa due anni.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-308945 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/08\/Zorro-maschio.jpg\" alt=\"\" width=\"463\" height=\"429\" title=\"\"><\/p>\n<p style=\"text-align: center;\"><strong> Zara<\/strong><em> (in basso),<\/em> \u00e8 tutta nera, femmina di Pitbull e ha circa 3 anni.<\/p>\n<p style=\"text-align: center;\">Sono entrambi di taglia media, socializzati e affettuosi.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-308944 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/08\/Zara-femminia.jpg\" alt=\"\" width=\"460\" height=\"404\" title=\"\"><\/p>\n<h3><span style=\"color: #ff0000;\">ASCOLTA la rubrica di questa settimana<\/span><\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/669872231&amp;color=%23ff5500&amp;auto_play=false&amp;hide_related=false&amp;show_comments=true&amp;show_user=true&amp;show_reposts=false&amp;show_teaser=true\" width=\"100%\" height=\"166\" frameborder=\"no\" scrolling=\"no\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">Se vuoi scriverci per chiedere informazioni sui cani da adottare: <strong>redazione@quicosenza.it<\/strong> (nell\u2019oggetto indicare \u201c<strong>Qui la Zampa<\/strong>\u201c); Se invece vuoi adottare i cani, il giorno delle adozioni in canile a <strong>Donnici<\/strong> \u00e8 il<span style=\"color: #ff0000;\"><strong>\u00a0GIOVEDI&#8217;<\/strong><\/span>. Le adozioni al canile sanitario in contrada Acquafredda di <strong>Mendicino<\/strong> (Cs) invece, si possono effettuare di <span style=\"color: #ff0000;\"><strong>LUNED\u00cc<\/strong> <\/span>dalle 9:30 alle 12:30<\/p>\n<h3 style=\"text-align: center;\">Numeri utili per informazioni e\/o adozioni<\/h3>\n<p style=\"text-align: center;\">Letizia 327 636 2179<br \/>\nMaria Giulia 334 354 2780<br \/>\nTeresa 348 134 3975<br \/>\nNadia 389 051 7756<br \/>\nMaria Francesca 3917348381<\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/5314\" target=\"_blank\" rel=\"noopener noreferrer\">\u00a0LEGGI TUTTI GLI ARTICOLI della rubrica &#8220;Qui la Zampa&#8221;<\/a><\/span><\/h4>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo la pausa estiva torna la rubrica Qui la Zampa. Questa settimana l&#8217;ennesima storia triste che, si spera, possa avere presto un lieto fine. Questa coppia di pelosi \u00e8 stata trovata legata davanti al canile di Donnici ma ora si spera in una &#8216;vera&#8217; famiglia<\/p>\n","protected":false},"author":42,"featured_media":114793,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[47],"tags":[],"class_list":["post-114792","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-qui-la-zampa"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/114792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=114792"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/114792\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/114793"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=114792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=114792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=114792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}