{"id":114844,"date":"2019-08-24T09:30:43","date_gmt":"2019-08-24T07:30:43","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/la-truffa-del-cd-rom-agli-anziani-arrestato-45enne-mentre-e-in-vacanza-a-scalea\/"},"modified":"2023-01-16T18:33:04","modified_gmt":"2023-01-16T17:33:04","slug":"309090-la-truffa-del-cd-rom-agli-anziani-arrestato-45enne-mentre-e-in-vacanza-a-scalea","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/309090-la-truffa-del-cd-rom-agli-anziani-arrestato-45enne-mentre-e-in-vacanza-a-scalea\/","title":{"rendered":"La truffa del cd-rom agli anziani, arrestato 45enne mentre \u00e8 in vacanza a Scalea"},"content":{"rendered":"<h4>Sarebbero almeno 7 i colpi compiuti dal truffatore. Le vittime erano anziani, ai quali l&#8217;uomo consegnava dei cd-rom vuoti, millantando accordi con i figli dei truffati, in cambio di denaro. Ma prima osservava e studiava le loro abitudini e i legami familiari<\/h4>\n<h4><!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>SCALEA (CS) &#8211; E&#8217; stato rintracciato mentre era in vacanza nella <strong>localit\u00e0 del tirreno cosentino<\/strong> grazie alle immagini della videosorveglianza e ad altri accertamenti tecnici, incrociati con le testimonianze dei truffati. Il sostituto procuratore Amara ha chiesto e ottenuto dal Gip l\u2019ordinanza di custodia cautelare in carcere per il truffatore seriale che \u00e8 stato, dopo vari spostamenti in tutta Italia, identificato e arrestato mentre era in vacanza a Scalea e condotto in carcere.<\/p>\n<p><strong>L&#8217;uomo, di origine napoletana, pluripregiudicato e con precedenti legati a reati di truffa<\/strong> compiute in tutta Italia aveva messo in atto ben sette colpi\u00a0a Modena, in Emilia Romagna. Le <strong>vittime erano anziani benestanti e con figli. Persone over 70<\/strong> delle quali studiava i legami familiari e le abitudini, lo stile di vita e i luoghi frequentati. Poi le raggiungeva per strada, mentre erano a piedi, e dopo averli affiancati con l&#8217;auto li chiamava per nome. Per questo motivo le vittime rispondevano.<\/p>\n<p>Millantando di essere un amico dei figli metteva in atto il suo piano mostrando alle vittime un <strong>cd-rom vuoto<\/strong> (che costa pochi centesimi di euro) ma agli anziani diceva che aveva un accordo con il figlio per la consegna di questo dischetto, chiedendo in cambio una <strong>cifra compresa tra i 200 e i 300<\/strong> euro. Alla Questura di Modena in 5 mesi, da febbraio a giugno, sarebbero arrivate diverse segnalazioni che hanno portato all&#8217;apertura delle indagini fino all&#8217;arresto del truffatore che se ne stava tranquillamente in vacanza in Calabria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sarebbero almeno 7 i colpi compiuti dal truffatore. Le vittime erano anziani, ai quali l&#8217;uomo consegnava dei cd-rom vuoti, millantando accordi con i figli dei truffati, in cambio di denaro. Ma prima osservava e studiava le loro abitudini e i legami familiari<\/p>\n","protected":false},"author":42,"featured_media":114845,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28,576],"tags":[],"class_list":["post-114844","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","category-tirreno"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/114844","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=114844"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/114844\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/114845"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=114844"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=114844"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=114844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}