{"id":114908,"date":"2019-08-26T11:30:02","date_gmt":"2019-08-26T09:30:02","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/mendicino-boom-di-presenze-a-monte-cocuzzo-il-29-i-sud-sound-system\/"},"modified":"2023-01-16T18:33:08","modified_gmt":"2023-01-16T17:33:08","slug":"309302-mendicino-boom-di-presenze-a-monte-cocuzzo-il-29-i-sud-sound-system","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/309302-mendicino-boom-di-presenze-a-monte-cocuzzo-il-29-i-sud-sound-system\/","title":{"rendered":"Mendicino, boom di presenze a Monte Cocuzzo. Il 29 i Sud Sound System"},"content":{"rendered":"<h4>Tantissimi cittadini, visitatori, viaggiatori e turisti quest&#8217;estate hanno scelto il fresco della montagna mendicinese<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>MENDICINO (CS) &#8211; In tantissimi hanno trascorso le loro giornate <strong>su una delle vette pi\u00f9 belle di tutta la Calabria<\/strong>, Monte Cocuzzo, a met\u00e0 via tra l\u2019aria urbana, le Serre Cosentine e la costa tirrenica. Un luogo dall&#8217;incantevole e dalla natura incontaminata, invaso da un vero e proprio boom di visitatori che hanno cos\u00ec potuto godere della <strong>bellezza di un luogo incantevole<\/strong> e dei servizi anche di ristorazione efficiente e accoglienti presenti nell&#8217;area picnic. In tanti si sono spinti fino alla vetta del Monte per poter osservare il tramonto del sole sul mar Tirreno e, nelle belle giornate di quest&#8217;estate, <strong>finanche ammirare sullo sfondo le isole Eolie<\/strong>.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/7915\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-309303\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/08\/vetta-monte-cocuzzo-657x400.jpg\" alt=\"\" width=\"526\" height=\"320\" title=\"\"><\/a><\/p>\n<p>Soddisfazione ha espresso il sindaco <strong>Antonio Palermo<\/strong> che ha parlato di <em>\u00ablavoro intenso di promozione del territorio svolto in questi anni, sta producendo ormai frutti visibili. Oggi Mendicino, il suo centro storico e la nostra Monte Cocuzzo \u2013<\/em> ha aggiunto Palermo &#8211;<em> grazie anche all&#8217;intuizione di Radicamenti sono diventate mete tra le pi\u00f9 note in Calabria. Invitiamo tutti i calabresi a Radicamenti 2019 che partir\u00e0 gioved\u00ec 29 agosto e soprattutto a venire la mattina del 1\u00ba settembre fino al tramonto a Monte Cocuzzo per il pi\u00f9 bel concerto che si tiene ormai ogni anno in tutta la Calabria. Sar\u00e0 il coronamento di un\u2019estate fantastica per la nostra Citt\u00e0\u00bb.<\/em><\/p>\n<p><strong>Prossimi appuntamenti:<\/strong><\/p>\n<p>29 Agosto &#8211; Sud Sound System<br \/>\n30 Agosto &#8211; Baba Sissoko, Mediterranean Blues, Tonino Carotone<br \/>\n31 Agosto &#8211; Morgan &amp; Megahertz, Calabria Orchestra<br \/>\n1 Settembre &#8211; Puro Desiderio, Teresa De Sio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tantissimi cittadini, visitatori, viaggiatori e turisti quest&#8217;estate hanno scelto il fresco della montagna mendicinese<\/p>\n","protected":false},"author":42,"featured_media":114909,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40,13],"tags":[],"class_list":["post-114908","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo","category-qui-green"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/114908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=114908"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/114908\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/114909"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=114908"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=114908"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=114908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}