{"id":114946,"date":"2019-08-28T07:00:31","date_gmt":"2019-08-28T05:00:31","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/tra-storia-e-street-art-a-potame-il-museo-case-narranti\/"},"modified":"2024-11-05T11:37:29","modified_gmt":"2024-11-05T10:37:29","slug":"309411-tra-storia-e-street-art-a-potame-il-museo-case-narranti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/309411-tra-storia-e-street-art-a-potame-il-museo-case-narranti\/","title":{"rendered":"Street Art, a Potame il Museo Case Narranti: visita guidata e realizzazione di un murales"},"content":{"rendered":"<h4>Dalla sinergia di due Associazioni Culturali, Parco Tommaso Campanella nella persona del suo presidente William Gatto, e Associazione sottosuolo con Mario Verta, nasce nel 2015 l\u2019idea progettuale di far rivivere con una semplice ma originale proposta il Villaggio Potame <!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>DOMANICO (CS) &#8211; Una formula di turismo culturale per scolaresche, cittadini residenti, turisti italiani e stranieri. Il Museo in itinere \u00e8 nato spontaneamente da un incrocio di realt\u00e0 artistiche presenti sul territorio ed \u00e8 realizzato da professionisti del settore della <strong>Street Art,<\/strong> con al momento <strong>25 opere pittoriche e due sculture<\/strong> realizzate dagli artisti, <strong>Mario Verta<\/strong>, Ferdinando Gatto, Daniele Armieri, Antonio Oliva e Caterina Fiorino. La professionalit\u00e0 degli autori nel settore del turismo culturale e dell\u2019arte di strada ha permesso la sua realizzazione.<\/p>\n<p>E\u2019 difficile dare una definizione teorica a questa forma d\u2019arte contemporanea perch\u00e8 la Street Art predilige il contesto pubblico ed urbano e lo eleva ad ambito esclusivo d\u2019intervento. La Street Art nasce \u2018in strada\u2019 e si manifesta nei luoghi pubblici spesso in disuso. La creazione artistica prende probabilmente le mosse da un forte desiderio di riappropriarsi del proprio ambito territoriale.<\/p>\n<p><strong>Il dott. Mario Verta,<\/strong> della Street Art School di Cosenza, anticipa l&#8217;iniziativa ai microfoni di <strong>Rlb<\/strong><\/p>\n<h4><span style=\"color: #ff0000;\">ASCOLTA\u00a0<\/span><\/h4>\n<p><iframe loading=\"lazy\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/672642122&amp;color=%23ff5500&amp;auto_play=false&amp;hide_related=false&amp;show_comments=true&amp;show_user=true&amp;show_reposts=false&amp;show_teaser=true\" width=\"100%\" height=\"166\" frameborder=\"no\" scrolling=\"no\"><\/iframe><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-309414 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/08\/Museo-delle-case-narranti-potame-02.jpg\" alt=\"\" width=\"566\" height=\"401\" title=\"\"><\/p>\n<p>Ma in tal caso non si tratta della realt\u00e0 urbana, ma del Villaggio Potame. Cos\u00ec <strong>sulle mura di una casa ambiente in cui prevale la tonalit\u00e0 cromatica del grigio, disabitata si andranno a realizzare le opere d\u2019arte.<\/strong> Ci\u00f2 nasce in virt\u00f9 di una risposta ad una serie di stimoli che sono negativi. Qualsiasi forma artistica che si inserisca in uno spazio, \u00e8 detta arte di strada. Il Museo <strong>tende a migliorare l\u2019aspetto delle case abbandonate<\/strong> sul territorio rendendole delle opere uniche, facenti parti di un museo integrato in modo che sia usufruibile con visite guidate prenotabili o da soli attraverso una <strong>sentieristica totemica in corso di realizzazione<\/strong>. Sar\u00e0 implementato pertanto negli anni successivi.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-309416 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/08\/Museo-delle-case-narranti-potame-04.jpg\" alt=\"\" width=\"570\" height=\"383\" title=\"\"><\/p>\n<p>Il tutto \u00e8 partito con la realizzazione iniziale di alcune opere aventi a riferimento altrettanti momenti significativi per il passaggio delle popolazioni straniere, in un territorio che ha subito diverse dominazioni rendendo omaggio alla flora e fauna presente sul territorio, e coinvolgendo personaggi illustri che siano collegati ai paesi confinanti con Domanico (Carolei, Mendicino, Lago, Paterno Calabro, Grimaldi, Amantea). <strong>Un viaggio nei periodi storici che sono trattati nei vari soggetti sui 35 murales.<\/strong><\/p>\n<p>La prossima data del viaggio emozionale nel Museo delle Case Narranti Potame, \u00e8 previsto per<strong> gioved\u00ec 29 agosto 2019 alle ore 16:00<\/strong>. L&#8217;itinerario culturale con partenza dal murales di Ciccio presso il Bar Tre Monti a Potame, in compagnia del cantastorie William Gatto per le 35 opere pittoriche e scultoree. Il percorso avr\u00e0 una durata di <strong>tre ore e 30 minuti circa per una percorrenza di 3,5 km.<\/strong> Nel corso della giornata <strong>l&#8217;artista Antonio Oliva<\/strong>, realizzer\u00e0 in estemporanea una nuova opera. Le persone che parteciperanno potranno ammirare dal vivo l&#8217;esecuzione di un murales.<\/p>\n<div id=\"js_4v0\" class=\"_5pbx userContent _3576\" data-testid=\"post_message\" data-ft=\"{&quot;tn&quot;:&quot;K&quot;}\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-309415 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/08\/Museo-delle-case-narranti-potame-03.jpg\" alt=\"\" width=\"575\" height=\"511\" title=\"\"><\/p>\n<\/div>\n<div class=\"_3x-2\" data-ft=\"{&quot;tn&quot;:&quot;H&quot;}\">\n<div data-ft=\"{&quot;tn&quot;:&quot;H&quot;}\">\n<div class=\"mtm\">\n<div>\n<div class=\"_1ktf\" data-ft=\"{&quot;tn&quot;:&quot;E&quot;}\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dalla sinergia di due Associazioni Culturali, Parco Tommaso Campanella nella persona del suo presidente William Gatto, e Associazione sottosuolo con Mario Verta, nasce nel 2015 l\u2019idea progettuale di far rivivere con una semplice ma originale proposta il Villaggio Potame<\/p>\n","protected":false},"author":49,"featured_media":114947,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40],"tags":[],"class_list":["post-114946","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/114946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=114946"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/114946\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/114947"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=114946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=114946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=114946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}