{"id":115038,"date":"2019-08-29T07:13:30","date_gmt":"2019-08-29T05:13:30","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/la-fusione-dei-comuni-della-presila-nessun-vantaggio-la-lettera-al-presidente-oliverio\/"},"modified":"2023-01-16T18:33:17","modified_gmt":"2023-01-16T17:33:17","slug":"309721-la-fusione-dei-comuni-della-presila-nessun-vantaggio-la-lettera-al-presidente-oliverio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/309721-la-fusione-dei-comuni-della-presila-nessun-vantaggio-la-lettera-al-presidente-oliverio\/","title":{"rendered":"La fusione dei comuni della presila? Nessun vantaggio. La lettera al presidente Oliverio"},"content":{"rendered":"<h4>A scrivere sono i &#8220;Liberi cittadini di Spezzano Piccolo&#8221;, e la missiva \u00e8 indirizzata al Presidente della Giunta Regionale e a tutti i capigruppo del Consiglio Regionale.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>SPEZZANO PICCOLO (CS) &#8211; La legge sulla fusione dei cinque comuni della presila (Casole Bruzio, Pedace, Serra Pedace, Spezzano Piccolo e Trenta), a distanza di due anni dalla sua approvazione, oltre ad aver dimostrato tutti i suoi limiti ha confermato tutti i dubbi che avevamo espresso, \u00e8 ormai cosa acclarata&#8221;.<\/p>\n<p>&#8220;Se poi, per pochi istanti, riavvolgiamo il nastro, e ripensiamo a come si \u00e8 arrivati a deliberare una norma simile non possiamo non ricordare come lo stravolgimento delle pi\u00f9 elementari norme della democrazia e il ripiegamento delle istituzioni agli interessi di parte, o meglio di partito, l\u2019abbiano fatta da padrone. Ad oggi non possiamo che registrare come i vantaggi per la popolazione, con la fusione, siano a zero. Anzi, si \u00e8 registrato un peggioramento su tutti i fronti: con la chiusura di tre sedi municipali si sono diminuiti i servizi sul territorio a danno soprattutto delle fasce pi\u00f9 deboli: anziani in primis&#8221;.<\/p>\n<p>&#8220;<strong>Oggi i cittadini di Spezzano Piccolo &#8211;<\/strong> scrivono &#8211; ma dicasi la stessa cosa per i <strong>cittadini di Pedace e Serra Pedace<\/strong>, <strong>per richiedere un qualsiasi atto o documento debbono recarsi alle ex sedi comunali di Casole Bruzio o Trenta presso cui sono dislocati gli uffici<\/strong>. Abbassamento della pressione fiscale: nemmeno a parlarne, anzi anche qui rincari. Ripercussioni negative anche a livello locale con la riduzione, per ora, delle stazioni dei Carabinieri sul territorio, con la chiusura della storica stazione di Spezzano Sila, ed in futuro stessa sorte per altri uffici pubblici. Anche il prezzo della svendita della nostra autonomia, il tanto decantato trasferimento decennale aggiuntivo, ha subito, quest\u2019anno, una drastica riduzione anche se, a dire il vero, le ricadute sul territorio, con le risorse assegnate per il 2018 sono state impalpabili. E potremmo ancora continuare&#8221;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-309722 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/08\/spezzano-piccolo.jpg\" alt=\"\" width=\"736\" height=\"319\" title=\"\"><\/p>\n<p>&#8220;Come certamente Lei sapr\u00e0 &#8211; rivolgendosi al presidente Oliverio &#8211; per fortuna, la s<strong>tessa esistenza dell\u2019Ente nato dalla fusione \u00e8 ancora sub-judice, infatti, \u00e8 ancora pendente, presso il Tar Calabria,<\/strong> il nostro ricorso contro l\u2019annessione forzosa di Spezzano Piccolo. E nella giustizia, anche se lenta, riponiamo tutta la nostra fiducia. Ma a Lei, che anche con il suo voto favorevole, ha contribuito a creare questo obbrobrio istituzionale, vogliamo chiedere, comunque, prima della chiusura della legislatura, un atto di coraggio politico. La seconda commissione del consiglio regionale ha deliberato alla unanimit\u00e0, il 6 maggio u.s, la proposta di legge che riforma il settore \u201c Disposizioni in materia di riordino territoriale delle circoscrizioni comunali \u2013 Modifiche e integrazioni alla legge regionale 5 aprile 1983, n. 13. Una proposta che finalmente mette al bando l\u2019improvvisazione e la convenienza di parte e cerca di affrontare in maniera seria la materia del riordino degli enti territoriali&#8221;.<\/p>\n<p>&#8220;Nella relazione illustrativa si evidenziano chiaramente, tra l\u2019altro, tutti i limiti e la disorganicit\u00e0 che la confusa legislazione vigente ha generato e \u201crischia di generare contenziosi giudiziari, dal verosimile esito sfavorevole per la Regione\u201d. Preso atto di quanto votato alla unanimit\u00e0, a questo punto chiediamo a Lei che intanto solleciti la discussione in aula della proposta di legge di riforma. Non solo, ma Le chiediamo che si faccia promotore di un <strong>emendamento che sani l\u2019ingiustizia commessa ai danni della comunit\u00e0 di Spezzano Piccolo<\/strong> che, ricordiamo, ha votato contro la fusione. Presenti un emendamento che preveda, per Spezzano Piccolo, che un numero di cittadini, pari a quelli che hanno chiesto al consiglio comunale l\u2019adesione alla proposta di fusione, possano richiedere, entro un tempo stabilito dall\u2019emendamento stesso, l\u2019indizione di un referendum confermativo. Specificando che qualora l\u2019esito fosse negativo il comune di Spezzano Piccolo riavr\u00e0 la sua autonomia. Sarebbe sicuramente una bella pagina che cancellerebbe una deprecabile scelta e che eviterebbe alla giustizia di sanare, ancora una volta, i guasti commessi dalla politica&#8221;.<\/p>\n<p style=\"text-align: right;\"><strong>Liberi cittadini di Spezzano Piccolo<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A scrivere sono i &#8220;Liberi cittadini di Spezzano Piccolo&#8221;, e la missiva \u00e8 indirizzata al Presidente della Giunta Regionale e a tutti i capigruppo del Consiglio Regionale.<\/p>\n","protected":false},"author":21,"featured_media":115039,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-115038","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/115038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=115038"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/115038\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/115039"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=115038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=115038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=115038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}