{"id":115102,"date":"2019-08-30T10:19:18","date_gmt":"2019-08-30T08:19:18","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/ritrovato-anziano-disperso-in-provincia-di-cosenza\/"},"modified":"2023-01-16T18:33:21","modified_gmt":"2023-01-16T17:33:21","slug":"309923-ritrovato-anziano-disperso-in-provincia-di-cosenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/309923-ritrovato-anziano-disperso-in-provincia-di-cosenza\/","title":{"rendered":"Ritrovato anziano disperso in provincia di Cosenza"},"content":{"rendered":"<h4>Rintracciato dai Vigili del Fuoco<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>FIRMO (CS) &#8211; I Vigili del Fuoco del Comando provinciale di Cosenza sono intervenuti ieri sera nel territorio di Firmo per effettuare le ricerche di una persona dispersa, un pensionato del luogo. Stamattina, dopo diverse ore trascorse nel rastrellare le zone rurali del Comune, insieme alle forze dell&#8217;ordine, durate anche per tutta la notte, i vigili del fuoco lo hanno ritrovato, in<strong> buono stato di salute.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rintracciato dai Vigili del Fuoco<\/p>\n","protected":false},"author":43,"featured_media":115103,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-115102","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/115102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=115102"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/115102\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/115103"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=115102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=115102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=115102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}